{"id":26111,"date":"2021-12-14T19:14:48","date_gmt":"2021-12-14T18:14:48","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/"},"modified":"2025-12-15T11:37:58","modified_gmt":"2025-12-15T10:37:58","slug":"camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/","title":{"rendered":"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames"},"content":{"rendered":"<p>Les batteries perdent de la puissance par temps froid, par exemple avec un t\u00e9l\u00e9phone portable. Pour \u00e9viter ce sort, Volvo Trucks a test\u00e9 ses camions \u00e9lectriques par temps extr\u00eamement froid pr\u00e8s du cercle polaire. Le r\u00e9sultat ? Une fonction qui maintient la puissance de la batterie, m\u00eame \u00e0 des temp\u00e9ratures bien en dessous de z\u00e9ro.<\/p>\n<p>(Ismaning) \u00ab Nous avons des clients dans le monde entier et nos camions doivent fonctionner partout. C&rsquo;est pourquoi les tests dans des conditions climatiques difficiles sont essentiels, cela vaut \u00e9galement pour nos v\u00e9hicules \u00e9lectriques \u00bb, d\u00e9clare Jessica Sandstr\u00f6m, SVP Product Management chez Volvo Trucks.<\/p>\n<p>Que se passe-t-il avec un camion \u00e0 batterie lorsque le thermom\u00e8tre affiche -25\u00b0 C et qu&rsquo;un vent fort se l\u00e8ve ? Pour le d\u00e9couvrir, Volvo Trucks a r\u00e9alis\u00e9 des tests d&rsquo;hiver dans le nord extr\u00eame de la Su\u00e8de.<\/p>\n<p>\u00ab Lors de l&rsquo;essai pratique de nos camions en Su\u00e8de du Nord pr\u00e8s du cercle polaire, nous exposons les v\u00e9hicules \u00e0 toutes les adversit\u00e9s de la nature \u00bb, poursuit Jessica Sandstr\u00f6m. \u00ab Le vent fait geler le v\u00e9hicule de l&rsquo;ext\u00e9rieur, ce qui nous permet de v\u00e9rifier que tout fonctionne correctement m\u00eame dans des conditions extr\u00eames. Nos tests ont montr\u00e9 que nos camions \u00e9lectriques sont tout \u00e0 fait adapt\u00e9s \u00e0 une utilisation par temps tr\u00e8s froid.\u00a0\u00bb<\/p>\n<h5><strong>Pr\u00e9chauffer ou pr\u00e9-refroidir la cabine<\/strong><\/h5>\n<p>Un r\u00e9sultat tangible des tests d&rsquo;hiver est la nouvelle fonction \u00ab Ready to Run \u00bb, ce qui signifie \u00ab pr\u00eat \u00e0 rouler \u00bb. Selon les besoins, cette fonction pr\u00e9pare le v\u00e9hicule pour la journ\u00e9e de travail en pr\u00e9chauffant les batteries et la cabine ou en refroidissant par temps tr\u00e8s chaud. La temp\u00e9rature optimale pour les batteries est d&rsquo;environ +25 \u00b0 et le conducteur peut d\u00e9marrer le pr\u00e9chauffage ou le pr\u00e9-refroidissement facilement via une application \u00e0 distance.Les camions \u00e9lectriques contribuent de mani\u00e8re significative \u00e0 la r\u00e9duction des \u00e9missions de CO<sub>2<\/sub>, mais jusqu&rsquo;\u00e0 pr\u00e9sent, seule une petite partie du march\u00e9 total des camions est constitu\u00e9e de tels v\u00e9hicules. Cette ann\u00e9e, seulement quelques centaines de camions lourds enti\u00e8rement \u00e9lectriques ont \u00e9t\u00e9 livr\u00e9s \u00e0 des entreprises de transport europ\u00e9ennes.<\/p>\n<p>\u00ab Nous faisons avancer le changement et occupons une position de leader sur le march\u00e9 europ\u00e9en des camions \u00e9lectriques. Nous produisons d\u00e9j\u00e0 des camions \u00e9lectriques en s\u00e9rie et livrons des clients dans toute l&rsquo;Europe et en Am\u00e9rique du Nord. Notre objectif est que d&rsquo;ici 2030, environ 50 % de nos camions vendus soient \u00e9lectriques \u00bb, conclut Jessica Sandstr\u00f6m.<\/p>\n<p>La fonction \u00ab Ready-to-Run \u00bb sera disponible pour les mod\u00e8les Volvo FH, FM et FMX Electric, qui sont utilis\u00e9s pour le transport de marchandises r\u00e9gional et les travaux de construction l\u00e9gers.<\/p>\n<h5><strong>Faits sur les camions \u00e9lectriques de Volvo Trucks :<\/strong><\/h5>\n<ul>\n<li>Volvo Trucks propose six camions enti\u00e8rement \u00e9lectriques, con\u00e7us pour une vari\u00e9t\u00e9 de t\u00e2ches de transport.<\/li>\n<li>Les mod\u00e8les Volvo FH, FM et FMX Electric sont des camions lourds avec un poids total autoris\u00e9 de 44 tonnes. Les ventes en Europe ont d\u00e9j\u00e0 commenc\u00e9 et la production d\u00e9butera en 2022 dans la seconde moiti\u00e9 de l&rsquo;ann\u00e9e.<\/li>\n<li>La production en s\u00e9rie des mod\u00e8les Volvo FL et FE Electric pour la distribution urbaine et la gestion des d\u00e9chets a commenc\u00e9 en Europe en 2019.<\/li>\n<li>La fabrication du Volvo VNR Electric pour l&rsquo;Am\u00e9rique du Nord a commenc\u00e9 en 2020.<\/li>\n<\/ul>\n<p>Vid\u00e9o\/Photo : \u00a9 Volvo Trucks<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les batteries perdent de la puissance par temps froid, par exemple avec un t\u00e9l\u00e9phone portable. Pour \u00e9viter ce sort, Volvo Trucks a test\u00e9 ses camions \u00e9lectriques<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-26111","post","type-post","status-publish","format-standard","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Les batteries perdent de la puissance par temps froid, par exemple avec un t\u00e9l\u00e9phone portable. Pour \u00e9viter ce sort, Volvo Trucks a test\u00e9 ses camions \u00e9lectriques [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-14T18:14:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T10:37:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames\",\"datePublished\":\"2021-12-14T18:14:48+00:00\",\"dateModified\":\"2025-12-15T10:37:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/\"},\"wordCount\":601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/\",\"name\":\"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-12-14T18:14:48+00:00\",\"dateModified\":\"2025-12-15T10:37:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/12\\\/14\\\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/","og_locale":"fr_FR","og_type":"article","og_title":"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames - Loginfo24.","og_description":"Les batteries perdent de la puissance par temps froid, par exemple avec un t\u00e9l\u00e9phone portable. Pour \u00e9viter ce sort, Volvo Trucks a test\u00e9 ses camions \u00e9lectriques [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-12-14T18:14:48+00:00","article_modified_time":"2025-12-15T10:37:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/"},"author":{"name":"","@id":""},"headline":"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames","datePublished":"2021-12-14T18:14:48+00:00","dateModified":"2025-12-15T10:37:58+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/"},"wordCount":601,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/","url":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/","name":"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-12-14T18:14:48+00:00","dateModified":"2025-12-15T10:37:58+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/12\/14\/camions-electriques-de-volvo-testes-dans-des-conditions-hivernales-extremes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Camions \u00e9lectriques de Volvo test\u00e9s dans des conditions hivernales extr\u00eames"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=26111"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26111\/revisions"}],"predecessor-version":[{"id":28464,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/26111\/revisions\/28464"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=26111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=26111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=26111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}