{"id":25806,"date":"2021-05-31T16:27:40","date_gmt":"2021-05-31T14:27:40","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/"},"modified":"2025-12-15T13:04:12","modified_gmt":"2025-12-15T12:04:12","slug":"le-commerce-de-detail-revient-le-commerce-en-ligne-reste","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/","title":{"rendered":"Le commerce de d\u00e9tail revient - le commerce en ligne reste"},"content":{"rendered":"<p>GfK a de nouveau \u00e9tudi\u00e9 en Suisse comment la pand\u00e9mie a modifi\u00e9 les habitudes de consommation de la population. Les nouveaux besoins qui ont \u00e9merg\u00e9 avec la pand\u00e9mie continuent d&rsquo;influencer les habitudes de consommation, mais certains ph\u00e9nom\u00e8nes ralentissent d\u00e9j\u00e0. La population suisse souhaite \u00e0 nouveau plus d&rsquo;exp\u00e9riences, mais ne veut pas renoncer \u00e0 certains aspects simplificateurs et apaisants du confinement, tels que la livraison \u00e0 domicile et le shopping en ligne, m\u00eame \u00e0 l&rsquo;avenir.<\/p>\n<p>(Rotkreuz) Depuis avril 2020, GfK Switzerland interroge continuellement les consommateurs, \u00e2g\u00e9s de 16 \u00e0 74 ans, sur leurs plus grandes pr\u00e9occupations, comme c&rsquo;est le cas maintenant dans la 7e vague, en mai. Actuellement, GfK observe un retour de th\u00e8mes qui avaient d\u00e9j\u00e0 une grande pertinence avant la pand\u00e9mie - le changement climatique et la pollution de l&rsquo;environnement sont \u00e0 nouveau plus centraux que la pand\u00e9mie. <\/p>\n<p>Surtout parmi la population de plus de 60 ans, le th\u00e8me de la pand\u00e9mie reste cependant en t\u00eate de liste des plus grandes pr\u00e9occupations. <\/p>\n<h5><strong>Cons\u00e9quences \u00e9conomiques de la pand\u00e9mie<\/strong><\/h5>\n<p>La grande majorit\u00e9 des Suisses de plus de 30 ans est d\u00e9sormais un peu plus rassur\u00e9e quant aux cons\u00e9quences \u00e9conomiques de la pand\u00e9mie de coronavirus. Ils voient leur situation professionnelle de mani\u00e8re plus optimiste qu&rsquo;au cours des derniers mois, mais environ un cinqui\u00e8me s&rsquo;inqui\u00e8te encore d&rsquo;une d\u00e9t\u00e9rioration de sa situation professionnelle (par exemple, sous la forme d&rsquo;un licenciement). Surtout les jeunes de moins de 29 ans s&rsquo;inqui\u00e8tent encore de leur avenir financier. <\/p>\n<h5><strong>La commodit\u00e9 reste, l&rsquo;exp\u00e9rience physique redevient plus importante<\/strong><\/h5>\n<p>Par rapport au premier confinement, la vie des consommateurs n&rsquo;a plus beaucoup chang\u00e9, tandis que par rapport \u00e0 la p\u00e9riode pr\u00e9c\u00e9dant la pand\u00e9mie, elle a chang\u00e9. Des th\u00e8mes comme \u00ab\u00a0simplification\u00a0\u00bb restent durablement importants. Cependant, chez les consommateurs, le d\u00e9sir d&rsquo;exp\u00e9riences revient lentement - cela entra\u00eene des dynamiques dans les deux sens. Dans le domaine de la simplification ou de la commodit\u00e9, on constate qu&rsquo;environ deux tiers des consommateurs interrog\u00e9s d\u00e9clarent avoir fait des achats en ligne au cours de la derni\u00e8re semaine. Un tiers de tous les r\u00e9pondants souhaite utiliser la livraison \u00e0 domicile de mani\u00e8re encore plus intensive \u00e0 l&rsquo;avenir, ici des dynamiques durables semblent se manifester, qui continueront \u00e0 mettre \u00e0 l&rsquo;\u00e9preuve le commerce et la logistique. <\/p>\n<p>Les fournisseurs de m\u00e9dias num\u00e9riques \u00e0 la demande comme Netflix, Spotify, etc. ont \u00e9galement pu tirer de grands b\u00e9n\u00e9fices de la pand\u00e9mie et renforcer leur position. Ici aussi, un besoin d&rsquo;individualit\u00e9 et d&rsquo;exp\u00e9riences sur mesure se manifeste, qui a \u00e9t\u00e9 encore acc\u00e9l\u00e9r\u00e9 par la pand\u00e9mie. <\/p>\n<p>Michel Rahm, expert en intelligence des consommateurs, observe : \u00ab\u00a0Il est \u00e9galement int\u00e9ressant de noter l&rsquo;autre c\u00f4t\u00e9, l&rsquo;exp\u00e9rience physique redevient \u00e9galement plus importante : nous constatons que les consommateurs disent de moins en moins vouloir aller moins souvent dans le commerce de d\u00e9tail. Alors que cette proportion \u00e9tait r\u00e9cemment d&rsquo;environ un tiers, elle n&rsquo;est d\u00e9sormais plus que d&rsquo;environ un consommateur sur quatre - les r\u00e9pondants veulent \u00e0 nouveau sortir, veulent \u00e0 nouveau participer \u00e0 la vie.\u00a0\u00bb <\/p>\n<h5><strong>Signes positifs pour l&rsquo;\u00e9t\u00e9 \u00e0 venir<\/strong><\/h5>\n<p>Les consommateurs sont g\u00e9n\u00e9ralement relativement confiants - ou aspirent \u00e0 un changement de d\u00e9cor et planifient d\u00e9j\u00e0 leurs vacances pour l&rsquo;\u00e9t\u00e9. <\/p>\n<p>Seulement un cinqui\u00e8me exclut actuellement cat\u00e9goriquement des vacances, environ 80 % ont d\u00e9j\u00e0 quelque chose de pr\u00e9vu ou envisagent encore cela. Il est frappant de constater que la distance de la destination de vacances devrait \u00e0 nouveau s&rsquo;agrandir. <\/p>\n<p>36 % des r\u00e9pondants restent en Suisse, mais environ autant pr\u00e9voient des vacances \u00e0 l&rsquo;\u00e9tranger. Il est frappant de constater que plus de la moiti\u00e9 des voyageurs \u00e0 l&rsquo;\u00e9tranger pr\u00e9voient de partir en vacances en voiture ou en train. Seul un r\u00e9pondant sur dix souhaite prendre l&rsquo;avion pour des vacances intra-europ\u00e9ennes, et seulement un r\u00e9pondant sur vingt peut se r\u00e9jouir de vacances outre-mer. <\/p>\n<h5><strong>Pr\u00e9paration \u00e0 la vaccination des r\u00e9pondants<\/strong><\/h5>\n<p>Les conditions pour des vacances \u00e0 l&rsquo;\u00e9tranger seraient des assouplissements, qui pourraient \u00eatre atteints, par exemple, gr\u00e2ce \u00e0 la vaccination - GfK a interrog\u00e9 pour la premi\u00e8re fois la population suisse sur sa volont\u00e9 de se faire vacciner lors de la vague de mai. <\/p>\n<p>Plus de 70 % souhaitent se faire vacciner contre le coronavirus. Seuls environ 16 % des r\u00e9pondants d\u00e9clarent explicitement qu&rsquo;ils ne se feront pas vacciner. <\/p>\n<p>Plus d&rsquo;un quart des r\u00e9pondants a d\u00e9j\u00e0 re\u00e7u une ou deux injections, un tiers a d\u00e9j\u00e0 des rendez-vous ou s&rsquo;est au moins d\u00e9j\u00e0 inscrit. <\/p>\n<h4><a href=\"https:\/\/www.gfk.com\/de-ch\/am-markt-und-konsumentenpuls\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Vers l&rsquo;\u00e9tude<\/strong><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>GfK a de nouveau \u00e9tudi\u00e9 en Suisse comment la pand\u00e9mie a modifi\u00e9 les habitudes de consommation de la population. Les nouveaux besoins qui ont \u00e9merg\u00e9 avec<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-25806","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le commerce de d\u00e9tail revient - le commerce en ligne reste - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le commerce de d\u00e9tail revient - le commerce en ligne reste - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"GfK a de nouveau \u00e9tudi\u00e9 en Suisse comment la pand\u00e9mie a modifi\u00e9 les habitudes de consommation de la population. Les nouveaux besoins qui ont \u00e9merg\u00e9 avec [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-31T14:27:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:04:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le commerce de d\u00e9tail revient - le commerce en ligne reste\",\"datePublished\":\"2021-05-31T14:27:40+00:00\",\"dateModified\":\"2025-12-15T12:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/\"},\"wordCount\":809,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/\",\"name\":\"Le commerce de d\u00e9tail revient - le commerce en ligne reste - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-05-31T14:27:40+00:00\",\"dateModified\":\"2025-12-15T12:04:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/31\\\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le commerce de d\u00e9tail revient &#8211; le commerce en ligne reste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le commerce de d\u00e9tail revient - le commerce en ligne reste - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/","og_locale":"fr_FR","og_type":"article","og_title":"Le commerce de d\u00e9tail revient - le commerce en ligne reste - Loginfo24.","og_description":"GfK a de nouveau \u00e9tudi\u00e9 en Suisse comment la pand\u00e9mie a modifi\u00e9 les habitudes de consommation de la population. Les nouveaux besoins qui ont \u00e9merg\u00e9 avec [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-31T14:27:40+00:00","article_modified_time":"2025-12-15T12:04:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/"},"author":{"name":"","@id":""},"headline":"Le commerce de d\u00e9tail revient - le commerce en ligne reste","datePublished":"2021-05-31T14:27:40+00:00","dateModified":"2025-12-15T12:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/"},"wordCount":809,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/","url":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/","name":"Le commerce de d\u00e9tail revient - le commerce en ligne reste - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-05-31T14:27:40+00:00","dateModified":"2025-12-15T12:04:12+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/31\/le-commerce-de-detail-revient-le-commerce-en-ligne-reste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le commerce de d\u00e9tail revient &#8211; le commerce en ligne reste"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=25806"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25806\/revisions"}],"predecessor-version":[{"id":47306,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25806\/revisions\/47306"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=25806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=25806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=25806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}