{"id":25688,"date":"2021-05-25T17:42:18","date_gmt":"2021-05-25T15:42:18","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/"},"modified":"2025-12-15T13:03:37","modified_gmt":"2025-12-15T12:03:37","slug":"dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/","title":{"rendered":"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en"},"content":{"rendered":"<p>DHL Express annonce ses plans pour la future structure de son r\u00e9seau de fret a\u00e9rien europ\u00e9en. Les nouveaut\u00e9s repr\u00e9sentent une nouvelle \u00e9tape de la strat\u00e9gie 2025. Une nouvelle compagnie a\u00e9rienne bas\u00e9e en Autriche effectuera principalement des vols de fret europ\u00e9ens. La compagnie a\u00e9rienne actuelle DHL Air UK sera d\u00e9velopp\u00e9e pour les vols intercontinentaux.<\/p>\n<p>(Bonn) DHL Express a annonc\u00e9 aujourd&rsquo;hui ses plans pour la future structure de son r\u00e9seau de fret a\u00e9rien europ\u00e9en. Les nouveaut\u00e9s repr\u00e9sentent une nouvelle \u00e9tape de la strat\u00e9gie 2025 de l&rsquo;entreprise et r\u00e9pondent \u00e0 la demande croissante pour les services internationaux de DHL Express. Dans un premier temps, DHL Express souhaite \u00e9tablir une nouvelle compagnie a\u00e9rienne de fret en Autriche. Actuellement, DHL soumet les demandes correspondantes aux autorit\u00e9s autrichiennes. Sous r\u00e9serve de l&rsquo;approbation de ces demandes, la nouvelle compagnie a\u00e9rienne devrait \u00eatre fond\u00e9e cette ann\u00e9e et commencer ses op\u00e9rations. Avec une flotte d&rsquo;avions de fret de type B757, transf\u00e9r\u00e9s par DHL Air UK, la nouvelle soci\u00e9t\u00e9 prendra en charge les vols intra-europ\u00e9ens. En contrepartie, DHL Air UK sera d\u00e9velopp\u00e9e en une compagnie a\u00e9rienne intercontinentale et la flotte actuelle d&rsquo;avions B767 sera compl\u00e9t\u00e9e par de nouveaux avions de type B777F. Avec ces \u00e9tapes, DHL Express renforce son r\u00e9seau de transport a\u00e9rien, assure des capacit\u00e9s de fret a\u00e9rien flexibles et stables, et soutient ainsi la demande toujours croissante pour les envois express internationaux de ses clients.<\/p>\n<h5><strong>Pr\u00e9paration \u00e0 une croissance suppl\u00e9mentaire<\/strong><\/h5>\n<p> \u00ab\u00a0Avec la nouvelle compagnie a\u00e9rienne, nous adaptons notre r\u00e9seau europ\u00e9en non seulement aux r\u00e9glementations changeantes, mais nous le pr\u00e9parons \u00e9galement \u00e0 une croissance suppl\u00e9mentaire\u00a0\u00bb, explique Roy Hughes, responsable du r\u00e9seau de fret a\u00e9rien europ\u00e9en chez DHL Express. \u00ab\u00a0Avec cette \u00e9tape, nous r\u00e9pondons \u00e0 la demande toujours \u00e9lev\u00e9e de nos clients pour des livraisons express transfrontali\u00e8res et pouvons leur fournir des capacit\u00e9s express suffisantes. Avec la nouvelle structure, nous pouvons rendre notre r\u00e9seau de transport a\u00e9rien en Europe plus flexible et plus stable tout en assurant une meilleure int\u00e9gration dans notre r\u00e9seau mondial gr\u00e2ce \u00e0 un plus grand nombre de vols intercontinentaux.\u00a0\u00bb DHL Express a r\u00e9cemment r\u00e9alis\u00e9 le meilleur trimestre de ses plus de 50 ans d&rsquo;histoire. Gr\u00e2ce \u00e0 l&rsquo;essor du commerce \u00e9lectronique mondial, l&rsquo;entreprise a pu augmenter le volume de ses envois internationaux \u00ab\u00a0Time Definite\u00a0\u00bb (TDI) de plus de 25 % par rapport au premier trimestre 2020. Pour l&rsquo;avenir, une nouvelle croissance du commerce \u00e9lectronique est attendue, car la num\u00e9risation du secteur B2B progresse \u00e9galement, ce qui augmentera consid\u00e9rablement le nombre d&rsquo;achats sur les plateformes en ligne, favorisant ainsi la demande pour les envois express internationaux.<\/p>\n<h5><strong>A\u00e9ronefs suppl\u00e9mentaires \u00e0 l&rsquo;a\u00e9roport d&rsquo;East Midlands<\/strong><\/h5>\n<p><div id=\"attachment_11586\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11586\" class=\"wp-image-11586 size-large\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg\" alt=\"\" width=\"1024\" height=\"439\" \/><p id=\"caption-attachment-11586\" class=\"wp-caption-text\">Boeing B757 de DHL \u00e0 l&rsquo;a\u00e9roport d&rsquo;East Midlands\/GB<\/p><\/div> En r\u00e9ponse \u00e0 cette croissance et pour continuer \u00e0 offrir \u00e0 ses clients les d\u00e9lais les plus rapides pour leurs livraisons transfrontali\u00e8res, DHL Express restructure sa compagnie a\u00e9rienne DHL Air UK bas\u00e9e dans les East Midlands. DHL Air UK se concentrera \u00e0 l&rsquo;avenir sur les vols intercontinentaux et augmentera le nombre de vols entre le Royaume-Uni, l&rsquo;Am\u00e9rique du Nord et du Sud, et l&rsquo;Asie. La flotte sera compl\u00e9t\u00e9e par des avions B767 suppl\u00e9mentaires et de nouveaux avions de type B777F. DHL Air UK pr\u00e9voit d&rsquo;introduire les avions B777 d\u00e9but 2022. \u00ab\u00a0Le Royaume-Uni a toujours \u00e9t\u00e9 une porte d&rsquo;entr\u00e9e importante vers le monde. Compte tenu de la demande croissante pour des livraisons internationales \u00e0 temps, cela est plus vrai que jamais aujourd&rsquo;hui\u00a0\u00bb, explique Tom Mackle, directeur g\u00e9n\u00e9ral de DHL Air UK. \u00ab\u00a0L&rsquo;extension de notre flotte express intercontinentale au Royaume-Uni avec de nouveaux B777 - les avions de fret les plus modernes et les plus efficaces - souligne notre engagement et notre volont\u00e9 de r\u00e9pondre aux besoins changeants des clients, de fournir continuellement des services excellents et d&rsquo;am\u00e9liorer \u00e9galement notre bilan carbone.\u00a0\u00bb Photo : \u00a9 DHL Express \/ <strong><em>L\u00e9gende de l&rsquo;image en couverture :<\/em><\/strong> <em>Avions DHL \u00e0 l&rsquo;a\u00e9roport de Linz<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DHL Express annonce ses plans pour la future structure de son r\u00e9seau de fret a\u00e9rien europ\u00e9en. Les nouveaut\u00e9s repr\u00e9sentent une nouvelle \u00e9tape de la strat\u00e9gie 2025.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1561],"tags":[],"class_list":["post-25688","post","type-post","status-publish","format-standard","hentry","category-air-freight","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"DHL Express annonce ses plans pour la future structure de son r\u00e9seau de fret a\u00e9rien europ\u00e9en. Les nouveaut\u00e9s repr\u00e9sentent une nouvelle \u00e9tape de la strat\u00e9gie 2025. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-25T15:42:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:03:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en\",\"datePublished\":\"2021-05-25T15:42:18+00:00\",\"dateModified\":\"2025-12-15T12:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/\"},\"wordCount\":740,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_25.5.21_2.jpg\",\"articleSection\":[\"Air Freight\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/\",\"name\":\"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_25.5.21_2.jpg\",\"datePublished\":\"2021-05-25T15:42:18+00:00\",\"dateModified\":\"2025-12-15T12:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_25.5.21_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_25.5.21_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/25\\\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/","og_locale":"fr_FR","og_type":"article","og_title":"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en - Loginfo24.","og_description":"DHL Express annonce ses plans pour la future structure de son r\u00e9seau de fret a\u00e9rien europ\u00e9en. Les nouveaut\u00e9s repr\u00e9sentent une nouvelle \u00e9tape de la strat\u00e9gie 2025. [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-25T15:42:18+00:00","article_modified_time":"2025-12-15T12:03:37+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/"},"author":{"name":"","@id":""},"headline":"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en","datePublished":"2021-05-25T15:42:18+00:00","dateModified":"2025-12-15T12:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/"},"wordCount":740,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg","articleSection":["Air Freight","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/","url":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/","name":"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg","datePublished":"2021-05-25T15:42:18+00:00","dateModified":"2025-12-15T12:03:37+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_25.5.21_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/25\/dhl-express-cree-une-nouvelle-compagnie-aerienne-pour-le-marche-europeen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"DHL Express cr\u00e9e une nouvelle compagnie a\u00e9rienne pour le march\u00e9 europ\u00e9en"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=25688"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25688\/revisions"}],"predecessor-version":[{"id":47078,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25688\/revisions\/47078"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=25688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=25688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=25688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}