{"id":25232,"date":"2021-05-05T16:51:28","date_gmt":"2021-05-05T14:51:28","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/"},"modified":"2025-12-15T13:01:23","modified_gmt":"2025-12-15T12:01:23","slug":"les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/","title":{"rendered":"Les prestataires logistiques sont ouverts \u00e0 l&rsquo;intelligence artificielle"},"content":{"rendered":"<p>Une analyse de march\u00e9 command\u00e9e par Weber Data Service \u00e0 l&rsquo;Universit\u00e9 de W\u00fcrzburg-Schweinfurt FHWS atteste du grand potentiel de l&rsquo;intelligence artificielle (IA) dans la logistique de transport. L&rsquo;\u00e9tude montre une volont\u00e9 majoritairement \u00e9lev\u00e9e d&rsquo;impl\u00e9menter l&rsquo;IA dans leur propre entreprise. Les processus simples tels que la saisie, l&rsquo;interpr\u00e9tation et l&rsquo;archivage des documents sont consid\u00e9r\u00e9s comme particuli\u00e8rement prometteurs.<\/p>\n<p><strong><span style=\"font-family: 'Cambria',serif;font-weight: normal\">(Bielefeld) Dans de nombreuses entreprises, les flux de travail r\u00e9currents sont encore trait\u00e9s \u00ab\u00a0avec des moyens d\u00e9pass\u00e9s\u00a0\u00bb. Cela inclut la facturation ou le remplissage de listes de colisage et de documents d&rsquo;accompagnement. De nombreuses donn\u00e9es doivent y \u00eatre saisies, v\u00e9rifi\u00e9es, pr\u00e9par\u00e9es et archiv\u00e9es manuellement. Ce sont pr\u00e9cis\u00e9ment des processus o\u00f9 l&rsquo;IA peut consid\u00e9rablement simplifier le travail.<\/span><\/strong><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">L&rsquo;analyse de march\u00e9 pr\u00e9sent\u00e9e en f\u00e9vrier par la FHWS s&rsquo;intitule \u00ab\u00a0Potentiels de l&rsquo;intelligence artificielle dans la logistique de transport\u00a0\u00bb. L&rsquo;\u00e9tude, r\u00e9alis\u00e9e par six \u00e9tudiants sous la direction du Prof. Dr. Andreas R\u00fckgauer, s&rsquo;est concentr\u00e9e sur le transport terrestre europ\u00e9en. Elle a examin\u00e9 si les solutions bas\u00e9es sur l&rsquo;IA dans des logiciels logistiques sp\u00e9cifiques offrent une valeur ajout\u00e9e. De plus, il a \u00e9t\u00e9 question de savoir s&rsquo;il existe d\u00e9j\u00e0 des tendances et des besoins dans le secteur pour l&rsquo;impl\u00e9mentation de logiciels bas\u00e9s sur l&rsquo;IA.<\/span><\/p>\n<h5><b><span style=\"font-family: 'Cambria',serif\">Des attentes \u00e9lev\u00e9es partiellement d\u00e9\u00e7ues<\/span><\/b><\/h5>\n<p><span style=\"font-family: 'Cambria',serif\">\u00ab\u00a0Les attentes tr\u00e8s \u00e9lev\u00e9es concernant l&rsquo;intelligence artificielle ou l&rsquo;apprentissage automatique au d\u00e9but de l&rsquo;engouement ont \u00e9t\u00e9 partiellement d\u00e9\u00e7ues\u00a0\u00bb, constate R\u00fckgauer. Cependant, on est maintenant dans une phase o\u00f9 l&rsquo;on peut \u00ab\u00a0utiliser les potentiels de l&rsquo;IA pour les affaires quotidiennes avec des objectifs r\u00e9alistes et des projets concrets\u00a0\u00bb. Cette perspective correspond au Hype Cycle d\u00e9velopp\u00e9 par le cabinet de conseil Gartner, qui divise le d\u00e9veloppement des innovations technologiques en diff\u00e9rentes phases. Celles-ci sont caract\u00e9ris\u00e9es par un engouement initial, la d\u00e9ception qui suit et la r\u00e9cup\u00e9ration des attentes.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">L&rsquo;\u00e9tude a \u00e9galement mis en \u00e9vidence des obstacles pour la suite des op\u00e9rations. Cela inclut, par exemple, les craintes des employ\u00e9s concernant la pr\u00e9servation de leurs emplois, le scepticisme et la r\u00e9ticence de la g\u00e9n\u00e9ration plus \u00e2g\u00e9e, ainsi qu&rsquo;une infrastructure informatique encore peu d\u00e9velopp\u00e9e. De plus, de nombreux logisticiens sont encore \u00ab\u00a0trop peu impliqu\u00e9s dans les th\u00e8mes de la num\u00e9risation et de l&rsquo;IA\u00a0\u00bb. Par cons\u00e9quent, des incertitudes subsistent quant \u00e0 la rentabilit\u00e9 des investissements correspondants.<\/span><\/p>\n<h5><b><span style=\"font-family: 'Cambria',serif\">Enqu\u00eate aupr\u00e8s des prestataires logistiques<\/span><\/b><\/h5>\n<div id=\"attachment_11121\" style=\"width: 242px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11121\" class=\" wp-image-11121\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg\" alt=\"\" width=\"232\" height=\"348\" \/><p id=\"caption-attachment-11121\" class=\"wp-caption-text\">Astrid Drexhage<\/p><\/div>\n<p><span style=\"font-family: 'Cambria',serif\">Une partie essentielle de l&rsquo;enqu\u00eate repose sur des entretiens avec des prestataires logistiques. Parmi les entreprises interrog\u00e9es figurent des soci\u00e9t\u00e9s telles que <strong><span style=\"font-family: 'Cambria',serif;font-weight: normal\">Dachser, <\/span><\/strong>Seifert Logistics GmbH et Meyer &amp; Meyer ainsi que les coop\u00e9rations de fret Cargo Line, VTL et la logistique syst\u00e8me en ligne. Mais aussi des prestataires logistiques de taille moyenne comme Sievers Logistik et l&rsquo;<em><span style=\"font-family: 'Cambria',serif;font-style: normal\">entreprise FreightTech<\/span><\/em><em> Timocom ont particip\u00e9 \u00e0 l&rsquo;\u00e9tude. Des contributions importantes ont \u00e9galement \u00e9t\u00e9 fournies par des entreprises de conseil telles qu&rsquo;Apari ou <strong><span style=\"font-family: 'Cambria',serif;font-weight: normal\">Camelot<\/span><\/strong>.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">\u00ab\u00a0L&rsquo;\u00e9tude de la FHWS nous a confirm\u00e9 que nous allons compl\u00e9ter notre syst\u00e8me de gestion des transports et de gestion d&rsquo;entrep\u00f4t DISPONENTplus avec des fonctions d&rsquo;IA pratiques\u00a0\u00bb, explique Astrid Drexhage, associ\u00e9e g\u00e9rante de Weber Data Service. Dans un prochain pas, on souhaite maintenant d\u00e9velopper une strat\u00e9gie IA. \u00c0 cette occasion, on identifiera et \u00e9valuera ensemble avec la FH Bielefeld des cas d&rsquo;utilisation appropri\u00e9s. De plus, des sc\u00e9narios de solutions bas\u00e9es sur l&rsquo;IA doivent \u00eatre con\u00e7us et leur faisabilit\u00e9 examin\u00e9e.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Photo : \u00a9 Weber Data<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une analyse de march\u00e9 command\u00e9e par Weber Data Service \u00e0 l&rsquo;Universit\u00e9 de W\u00fcrzburg-Schweinfurt FHWS atteste du grand potentiel de l&rsquo;intelligence artificielle (IA) dans la logistique de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-25232","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les prestataires logistiques sont ouverts \u00e0 l&#039;intelligence artificielle - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les prestataires logistiques sont ouverts \u00e0 l&#039;intelligence artificielle - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Une analyse de march\u00e9 command\u00e9e par Weber Data Service \u00e0 l&rsquo;Universit\u00e9 de W\u00fcrzburg-Schweinfurt FHWS atteste du grand potentiel de l&rsquo;intelligence artificielle (IA) dans la logistique de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-05T14:51:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:01:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Les prestataires logistiques sont ouverts \u00e0 l&rsquo;intelligence artificielle\",\"datePublished\":\"2021-05-05T14:51:28+00:00\",\"dateModified\":\"2025-12-15T12:01:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/\"},\"wordCount\":660,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/WeberData_4.5.21_2.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/\",\"name\":\"Les prestataires logistiques sont ouverts \u00e0 l'intelligence artificielle - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/WeberData_4.5.21_2.jpg\",\"datePublished\":\"2021-05-05T14:51:28+00:00\",\"dateModified\":\"2025-12-15T12:01:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/WeberData_4.5.21_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/WeberData_4.5.21_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/05\\\/05\\\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les prestataires logistiques sont ouverts \u00e0 l&rsquo;intelligence artificielle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les prestataires logistiques sont ouverts \u00e0 l'intelligence artificielle - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/","og_locale":"fr_FR","og_type":"article","og_title":"Les prestataires logistiques sont ouverts \u00e0 l'intelligence artificielle - Loginfo24.","og_description":"Une analyse de march\u00e9 command\u00e9e par Weber Data Service \u00e0 l&rsquo;Universit\u00e9 de W\u00fcrzburg-Schweinfurt FHWS atteste du grand potentiel de l&rsquo;intelligence artificielle (IA) dans la logistique de [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-05T14:51:28+00:00","article_modified_time":"2025-12-15T12:01:23+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/"},"author":{"name":"","@id":""},"headline":"Les prestataires logistiques sont ouverts \u00e0 l&rsquo;intelligence artificielle","datePublished":"2021-05-05T14:51:28+00:00","dateModified":"2025-12-15T12:01:23+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/"},"wordCount":660,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/","url":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/","name":"Les prestataires logistiques sont ouverts \u00e0 l'intelligence artificielle - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg","datePublished":"2021-05-05T14:51:28+00:00","dateModified":"2025-12-15T12:01:23+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/WeberData_4.5.21_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/05\/05\/les-prestataires-logistiques-sont-ouverts-a-lintelligence-artificielle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les prestataires logistiques sont ouverts \u00e0 l&rsquo;intelligence artificielle"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=25232"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25232\/revisions"}],"predecessor-version":[{"id":46170,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/25232\/revisions\/46170"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=25232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=25232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=25232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}