{"id":24861,"date":"2021-04-21T18:17:50","date_gmt":"2021-04-21T16:17:50","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/"},"modified":"2025-12-15T12:59:38","modified_gmt":"2025-12-15T11:59:38","slug":"le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/","title":{"rendered":"Le conseil d&rsquo;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2"},"content":{"rendered":"<p>Les clients de DB Cargo peuvent d\u00e9j\u00e0 aujourd&rsquo;hui circuler avec 100 % d&rsquo;\u00e9lectricit\u00e9 verte dans le transport de marchandises. La logistique ferroviaire durable contribue \u00e0 la cr\u00e9ation de valeur des produits verts. Avec une action symbolique de conteneurs dans les grandes villes allemandes et le long des autoroutes, DB Cargo fait la promotion des nouveaux objectifs climatiques, \u00e0 temps pour le<\/p>\n<p>(Mayence) Le conseil d&rsquo;administration du plus grand chemin de fer de marchandises d&rsquo;Europe met r\u00e9solument les signaux au vert. \u00ab\u00a0Nous voulons offrir une logistique ferroviaire sans CO2 \u00e0 tous nos clients\u00a0\u00bb, a d\u00e9clar\u00e9 le conseil d&rsquo;administration de DB Cargo AG lors de sa r\u00e9union \u00e0 Mayence. \u00ab\u00a0Un seul train de marchandises remplace en moyenne 52 camions. Le rail permet d\u00e9j\u00e0 d&rsquo;\u00e9conomiser entre 80 et 100 % de CO2 par rapport au transport routier\u00a0\u00bb, explique la pr\u00e9sidente du conseil d&rsquo;administration de DB Cargo, Dr. Sigrid Nikutta, \u00e0 l&rsquo;occasion de l'\u00a0\u00bbEarth Day\u00a0\u00bb, qui a lieu le jeudi 22 avril.<\/p>\n<p>Avec une action symbolique de conteneurs dans les grandes villes allemandes et le long des autoroutes, DB Cargo fait la promotion des nouveaux objectifs climatiques. \u00ab\u00a0Main sur le c\u0153ur : nous pouvons d\u00e9j\u00e0 aujourd&rsquo;hui offrir \u00e0 chaque client une cha\u00eene d&rsquo;approvisionnement compl\u00e8tement sans CO2 pour toutes les marchandises\u00a0\u00bb, promet DB Cargo. \u00ab\u00a0Nous pouvons le faire parce que nous misons sur le plus grand r\u00e9seau environnemental du transport terrestre europ\u00e9en \u2013 le r\u00e9seau ferroviaire\u00a0\u00bb, d\u00e9clare Dr. Nikutta. \u00ab\u00a0Il s&rsquo;agit maintenant de sensibiliser non seulement les niveaux de direction de nos clients Cargok, mais aussi les consommateurs aux cha\u00eenes d&rsquo;approvisionnement vertes.\u00a0\u00bb<\/p>\n<h5><strong>DB Cargo veut \u00eatre climatiquement neutre d&rsquo;ici 2050<\/strong><\/h5>\n<p>D\u00e9j\u00e0 aujourd&rsquo;hui, les locomotives \u00e9lectriques fournissent 95 % de la puissance de traction de DB Cargo. L&rsquo;\u00e9nergie n\u00e9cessaire peut \u00eatre fournie \u00e0 100 % sous forme d&rsquo;\u00e9lectricit\u00e9 verte, si les clients le souhaitent. De plus, DB Cargo peut \u00e9galement proposer des transports climatiquement neutres pour les marchandises \u00ab\u00a0sur le dernier kilom\u00e8tre jusqu&rsquo;au client\u00a0\u00bb \u2013 et compenser concr\u00e8tement via des certificats climatiques. \u00ab\u00a0Non seulement le bilan \u00e9cologique du transport ferroviaire de marchandises \u2013 notre ADN en tant que Deutsche Bahn est \u00e9galement vert\u00a0\u00bb, d\u00e9clare Dr. Nikutta en regardant les objectifs climatiques de la Deutsche Bahn. D&rsquo;ici 2050, le plus grand groupe ferroviaire europ\u00e9en souhaite \u00eatre climatiquement neutre. \u00ab\u00a0Nous n&rsquo;avons pas de mal \u00e0 nous passer du diesel : nous avons pris les d\u00e9cisions cl\u00e9s au sein du conseil d&rsquo;administration pour que nous puissions \u00e0 moyen terme convertir l&rsquo;ensemble de notre flotte de locomotives vers des concepts de propulsion \u00e9lectrique et alternatifs.<\/p>\n<h5><strong>Rendre encore plus efficace gr\u00e2ce \u00e0 la num\u00e9risation<\/strong><\/h5>\n<p>De plus, la num\u00e9risation nous aide \u00e0 devenir encore plus efficaces \u2013 et donc plus respectueux de l&rsquo;environnement pour nos clients, d\u00e9clare Dr. Nikutta dans une d\u00e9claration \u00e0 l&rsquo;occasion de l&rsquo;Earth Day. \u00ab\u00a0La crise du coronavirus n&rsquo;a pas frein\u00e9 le r\u00e9chauffement climatique, bien au contraire. 2020 a \u00e9t\u00e9, selon l&rsquo;Organisation m\u00e9t\u00e9orologique mondiale (OMM), la deuxi\u00e8me ann\u00e9e la plus chaude depuis le d\u00e9but des enregistrements.\u00a0\u00bb La concentration de gaz \u00e0 effet de serre nocifs pour le climat comme le CO2 dans l&rsquo;atmosph\u00e8re a \u00e9galement atteint un nouveau record, selon le rapport annuel de l&rsquo;OMM du lundi 19 avril 2021.<\/p>\n<p>L&rsquo;Earth Day est c\u00e9l\u00e9br\u00e9 chaque ann\u00e9e le 22 avril dans plus de 175 pays. Il vise \u00e0 sensibiliser aux questions environnementales et appelle au changement.<\/p>\n<p>Photo : \u00a9 DB Cargo :<em> <strong>L\u00e9gende de l&rsquo;image :<\/strong> Conseil d&rsquo;administration de DB Cargo devant un conteneur vert, si\u00e8ge de DB Cargo \u00e0 Mayence, de g. \u00e0 d. Pierre Timmermans, Dr. Ursula Biernert, Ralf G\u00fcnter Klo\u00df, Dr. Sigrid Nikutta, Thorsten Dieter, Dr. Martina Niemann<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les clients de DB Cargo peuvent d\u00e9j\u00e0 aujourd&rsquo;hui circuler avec 100 % d&rsquo;\u00e9lectricit\u00e9 verte dans le transport de marchandises. La logistique ferroviaire durable contribue \u00e0 la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-24861","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le conseil d&#039;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2 - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le conseil d&#039;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2 - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Les clients de DB Cargo peuvent d\u00e9j\u00e0 aujourd&rsquo;hui circuler avec 100 % d&rsquo;\u00e9lectricit\u00e9 verte dans le transport de marchandises. La logistique ferroviaire durable contribue \u00e0 la [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T16:17:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:59:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le conseil d&rsquo;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2\",\"datePublished\":\"2021-04-21T16:17:50+00:00\",\"dateModified\":\"2025-12-15T11:59:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/\"},\"wordCount\":639,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/\",\"name\":\"Le conseil d'administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2 - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-04-21T16:17:50+00:00\",\"dateModified\":\"2025-12-15T11:59:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/21\\\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le conseil d&rsquo;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le conseil d'administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2 - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/","og_locale":"fr_FR","og_type":"article","og_title":"Le conseil d'administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2 - Loginfo24.","og_description":"Les clients de DB Cargo peuvent d\u00e9j\u00e0 aujourd&rsquo;hui circuler avec 100 % d&rsquo;\u00e9lectricit\u00e9 verte dans le transport de marchandises. La logistique ferroviaire durable contribue \u00e0 la [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-21T16:17:50+00:00","article_modified_time":"2025-12-15T11:59:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/"},"author":{"name":"","@id":""},"headline":"Le conseil d&rsquo;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2","datePublished":"2021-04-21T16:17:50+00:00","dateModified":"2025-12-15T11:59:38+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/"},"wordCount":639,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/","url":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/","name":"Le conseil d'administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2 - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-04-21T16:17:50+00:00","dateModified":"2025-12-15T11:59:38+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/21\/le-conseil-dadministration-de-db-cargo-met-les-signaux-au-vert-pour-une-logistique-ferroviaire-sans-co2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le conseil d&rsquo;administration de DB Cargo met les signaux au vert pour une logistique ferroviaire sans CO2"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=24861"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24861\/revisions"}],"predecessor-version":[{"id":45434,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24861\/revisions\/45434"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=24861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=24861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=24861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}