{"id":24512,"date":"2021-04-07T17:36:20","date_gmt":"2021-04-07T15:36:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/"},"modified":"2025-12-15T12:58:00","modified_gmt":"2025-12-15T11:58:00","slug":"unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/","title":{"rendered":"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek"},"content":{"rendered":"<p>La logistique pharmaceutique de Unitax distribue dans le Brandebourg les vaccins COVID-19 sensibles \u00e0 la temp\u00e9rature de Biontech \/ Pfizer et Moderna aux h\u00f4pitaux, centres de vaccination, maisons de retraite et \u00e9quipes de vaccination mobiles. Les solutions informatiques de Dr. Malek Software garantissent des processus fluides et un \u00e9change rapide de donn\u00e9es.<\/p>\n<p>(Berlin\/Dresden) La logistique n&rsquo;a rarement \u00e9t\u00e9 autant sous les projecteurs que lors de la distribution du vaccin COVID-19. Cela est particuli\u00e8rement vrai pour le s\u00e9rum d\u00e9velopp\u00e9 par Biontech \/ Pfizer, qui doit \u00eatre stock\u00e9 et transport\u00e9 \u00e0 une temp\u00e9rature de -75 degr\u00e9s. Pour la logistique pharmaceutique de Unitax, il s&rsquo;agissait donc d&rsquo;un honneur particulier d&rsquo;\u00eatre mandat\u00e9 le 10 d\u00e9cembre pour la distribution du vaccin dans le Land de Brandebourg.<\/p>\n<h5><strong>Connu depuis de nombreuses ann\u00e9es<\/strong><\/h5>\n<p> \u00ab\u00a0Gr\u00e2ce \u00e0 notre certification GDP et notre autorisation de fabrication, nous sommes connus dans le Land de Brandebourg depuis de nombreuses ann\u00e9es. C&rsquo;est pourquoi nous avons \u00e9t\u00e9 invit\u00e9s \u00e0 participer \u00e0 l&rsquo;appel d&rsquo;offres\u00a0\u00bb, se souvient Ren\u00e9 Gutke, responsable des domaines transport et planification chez Unitax. L&rsquo;entreprise stocke et transporte pour l&rsquo;industrie pharmaceutique des principes actifs et des m\u00e9dicaments finis en chargements partiels et complets. \u00c0 partir des sites de Sch\u00f6nefeld, Gro\u00dfbeeren et Nuremberg, Unitax prend \u00e9galement en charge la distribution fine et livre quotidiennement des pharmacies, des cliniques et des \u00e9tablissements de soins.<br \/>De plus, Unitax est un des membres fondateurs de GDP network solutions. Ce r\u00e9seau de fret national avec un hub \u00e0 Kassel a \u00e9t\u00e9 cr\u00e9\u00e9 en juillet 2020 par 10 prestataires logistiques de taille moyenne, sp\u00e9cifiquement pour les m\u00e9dicaments et les dispositifs m\u00e9dicaux.<\/p>\n<h5><strong>Logiciel logistique compl\u00e9t\u00e9<\/strong><\/h5>\n<p> \u00ab\u00a0Pour notre entr\u00e9e dans la livraison de fret au sein d&rsquo;un r\u00e9seau national, nous avons investi dans les technologies de l&rsquo;information\u00a0\u00bb, explique Gutke. Le syst\u00e8me de gestion des transports M3 Logisticware de Dr. Malek Software, utilis\u00e9 chez Unitax depuis 2014, a \u00e9t\u00e9 compl\u00e9t\u00e9 par d&rsquo;autres modules pour le transport de fret, y compris le transbordement. D&rsquo;autres modules, tels que la communication avec les conducteurs et les services Web M3, qui permettent par exemple le suivi des envois, ont \u00e9t\u00e9 adapt\u00e9s \u00e0 cet effet. Les services Web M3 sont une offre de services de donn\u00e9es de Dr. Malek Software GmbH sur des serveurs Web sp\u00e9cialement exploit\u00e9s \u00e0 cet effet.<br \/>Une autre adaptation concernait l&rsquo;application M3, qui peut \u00eatre install\u00e9e sur tous les smartphones Android courants, tablettes et de nombreux scanners mobiles. L&rsquo;application re\u00e7oit les donn\u00e9es de commande et guide les 35 conducteurs de Unitax \u00e9tape par \u00e9tape tout au long du processus de livraison \u2013 y compris la navigation et le re\u00e7u de livraison sur l&rsquo;\u00e9cran. Le scanner est utilis\u00e9 \u00e0 chaque point de transfert de la marchandise entre le chargeur, le hub et le destinataire. Le transbordement est \u00e9galement document\u00e9 chez Unitax \u00e0 l&rsquo;aide de l&rsquo;application M3 et des scanners mobiles.<\/p>\n<h5><strong>Pr\u00e9sentation adapt\u00e9e<\/strong><\/h5>\n<p> Pour r\u00e9pondre aux exigences \u00e9lev\u00e9es de num\u00e9risation du r\u00e9seau GDP, Unitax a compl\u00e9t\u00e9 l&rsquo;application avec Dr. Malek de nouvelles fonctionnalit\u00e9s. \u00ab\u00a0Une nouveaut\u00e9 est par exemple l&rsquo;\u00e9change d&#8217;emballages, qui a maintenant \u00e9t\u00e9 int\u00e9gr\u00e9 dans l&rsquo;application M3\u00a0\u00bb, d\u00e9clare Gutke. Mais la pr\u00e9sentation de certaines donn\u00e9es a \u00e9galement \u00e9t\u00e9 adapt\u00e9e aux souhaits de Unitax.<br \/>Dans ce contexte, Unitax \u00e9tait bien pr\u00e9par\u00e9 pour la distribution de vaccins \u00e0 l&rsquo;\u00e9chelle nationale. Il ne manquait plus que l&rsquo;interface de transfert de donn\u00e9es entre le syst\u00e8me ERP du centre de distribution et M3, qui a \u00e9t\u00e9 programm\u00e9e par Dr. Malek Software. Cela permet \u00e0 Unitax de recevoir les donn\u00e9es de commande pour les 25 \u00e0 45 arr\u00eats du lendemain. Sur cette base, M3 calcule les itin\u00e9raires optimaux, qui sont ensuite renvoy\u00e9s par transfert de donn\u00e9es au centre de distribution pour la pr\u00e9paration des commandes. Apr\u00e8s quelques heures, les envois sont pr\u00eats \u00e0 \u00eatre r\u00e9cup\u00e9r\u00e9s \u00e0 l&rsquo;adresse d&rsquo;exp\u00e9dition \u2013 tenue secr\u00e8te pour le public. Apr\u00e8s le chargement, les conducteurs commencent la livraison \u00e0 6h00.<\/p>\n<h5><strong>5 000 doses de vaccin par carton<\/strong><\/h5>\n<p> \u00ab\u00a0Lors de la planification des tourn\u00e9es, il s&rsquo;agit des chemins les plus courts possibles, de sorte que les conducteurs empruntent sans cesse de nouveaux itin\u00e9raires, tout en \u00e9tant fournis par l&rsquo;application M3 avec des indications pr\u00e9cises sur les particularit\u00e9s respectives\u00a0\u00bb, rapporte Gutke. Le cercle des destinataires comprend 75 h\u00f4pitaux, 17 centres de vaccination, des maisons de retraite et des \u00e9quipes de vaccination mobiles. En raison du faible volume des envois, six fourgonnettes de classe Sprinter avec des am\u00e9nagements de refroidissement sp\u00e9ciaux, capables de maintenir la temp\u00e9rature de la cargaison \u00e0 -25 degr\u00e9s Celsius, suffisent. Dans de petites bo\u00eetes avec une surface de base de seulement 25&#215;25 centim\u00e8tres, 1 000 flacons \u2013 c&rsquo;est-\u00e0-dire des vials \u2013 sont contenus, ce qui correspond \u00e0 une quantit\u00e9 de 5 000 \u00e0 10 000 doses de vaccin selon le vaccin. \u00c0 titre de comparaison : chaque h\u00f4pital re\u00e7oit environ 400 doses de vaccin par livraison, qui sont administr\u00e9es en quelques heures. Des accessoires de vaccination tels que des gants, des masques, des d\u00e9sinfectants, des seringues jetables et des solutions salines sont \u00e9galement fournis.<br \/>Pendant le transport, les cartons sont prot\u00e9g\u00e9s de mani\u00e8re optimale contre les variations de temp\u00e9rature par des bo\u00eetes r\u00e9frig\u00e9r\u00e9es avec des accumulateurs de froid. Les bo\u00eetes sont \u00e9quip\u00e9es d&rsquo;un enregistreur de donn\u00e9es qui documente la courbe de temp\u00e9rature pendant tout le transport. De plus, le froid \u00e0 l&rsquo;int\u00e9rieur de la bo\u00eete est mesur\u00e9 lors de la r\u00e9ception de la marchandise. \u00c0 la fin de la tourn\u00e9e, les donn\u00e9es enregistr\u00e9es sont li\u00e9es aux commandes ex\u00e9cut\u00e9es dans M3 et mises \u00e0 la disposition du centre de distribution.<br \/>Photos : \u00a9 Unitax<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La logistique pharmaceutique de Unitax distribue dans le Brandebourg les vaccins COVID-19 sensibles \u00e0 la temp\u00e9rature de Biontech \/ Pfizer et Moderna aux h\u00f4pitaux, centres de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-24512","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La logistique pharmaceutique de Unitax distribue dans le Brandebourg les vaccins COVID-19 sensibles \u00e0 la temp\u00e9rature de Biontech \/ Pfizer et Moderna aux h\u00f4pitaux, centres de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-07T15:36:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:58:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek\",\"datePublished\":\"2021-04-07T15:36:20+00:00\",\"dateModified\":\"2025-12-15T11:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/\"},\"wordCount\":1004,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/\",\"name\":\"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-04-07T15:36:20+00:00\",\"dateModified\":\"2025-12-15T11:58:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/07\\\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/","og_locale":"fr_FR","og_type":"article","og_title":"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek - Loginfo24.","og_description":"La logistique pharmaceutique de Unitax distribue dans le Brandebourg les vaccins COVID-19 sensibles \u00e0 la temp\u00e9rature de Biontech \/ Pfizer et Moderna aux h\u00f4pitaux, centres de [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-07T15:36:20+00:00","article_modified_time":"2025-12-15T11:58:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/"},"author":{"name":"","@id":""},"headline":"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek","datePublished":"2021-04-07T15:36:20+00:00","dateModified":"2025-12-15T11:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/"},"wordCount":1004,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/","url":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/","name":"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-04-07T15:36:20+00:00","dateModified":"2025-12-15T11:58:00+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/07\/unitax-gere-la-distribution-de-vaccins-avec-des-solutions-informatiques-de-dr-malek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Unitax g\u00e8re la distribution de vaccins avec des solutions informatiques de Dr. Malek"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=24512"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24512\/revisions"}],"predecessor-version":[{"id":44742,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24512\/revisions\/44742"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=24512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=24512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=24512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}