{"id":24470,"date":"2021-04-06T16:52:03","date_gmt":"2021-04-06T14:52:03","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/"},"modified":"2025-12-15T12:57:48","modified_gmt":"2025-12-15T11:57:48","slug":"le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/","title":{"rendered":"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise"},"content":{"rendered":"<p>Le groupe Seifert Logistics (SLG) a r\u00e9alis\u00e9 un chiffre d&rsquo;affaires de 200 millions d&rsquo;euros en 2020, une ann\u00e9e de crise. C&rsquo;est la deuxi\u00e8me meilleure valeur de chiffre d&rsquo;affaires de l&rsquo;histoire de l&rsquo;entreprise. Les secteurs d&rsquo;activit\u00e9 restent stables malgr\u00e9 la crise du Corona et le groupe regarde l&rsquo;avenir avec optimisme. Avec le plus grand investissement de son histoire, la planification d&rsquo;un nouveau centre logistique multi-utilisateurs \u00e0 Ulm Nord a \u00e9t\u00e9 lanc\u00e9e.<\/p>\n<p>(Ulm) Le groupe Seifert Logistics (SLG) a cl\u00f4tur\u00e9 l&rsquo;ann\u00e9e commerciale 2020 avec un chiffre d&rsquo;affaires de 200 millions d&rsquo;euros. Les attentes pour l&rsquo;ann\u00e9e 2020 \u00e9taient positives et rien ne s&rsquo;opposait \u00e0 la poursuite de la croissance du groupe. Cependant, l&rsquo;\u00e9clatement de la pand\u00e9mie de Corona a partiellement paralys\u00e9 le monde et donc l&rsquo;\u00e9conomie. Malgr\u00e9 cette ann\u00e9e de crise, le groupe a atteint le deuxi\u00e8me chiffre d&rsquo;affaires le plus \u00e9lev\u00e9 de son histoire et a pu cl\u00f4turer l&rsquo;ann\u00e9e en p\u00e9riode de Corona avec un r\u00e9sultat solide et positif. Ce r\u00e9sultat est principalement d\u00fb aux d\u00e9cisions efficaces et strat\u00e9giques de la direction. \u00ab\u00a0Nous avons agi rapidement et efficacement au d\u00e9but de l&rsquo;ann\u00e9e derni\u00e8re et avons retourn\u00e9 chaque pierre pour prot\u00e9ger nos employ\u00e9s et le groupe\u00a0\u00bb, d\u00e9clare Axel Frey, directeur des op\u00e9rations (COO) de la SLG.<\/p>\n<h5><strong>Les secteurs d&rsquo;activit\u00e9 restent stables malgr\u00e9 la crise du Corona<\/strong><\/h5>\n<p>Les deux grands secteurs d&rsquo;activit\u00e9, le transport et la logistique contractuelle, ont continu\u00e9 \u00e0 contribuer au r\u00e9sultat positif du groupe, malgr\u00e9 des pertes de chiffre d&rsquo;affaires parfois significatives. Bien que le secteur automobile ait \u00e9t\u00e9 fortement touch\u00e9 en 2020 et que les effets de la crise aient compliqu\u00e9 le secteur du transport en raison de l&rsquo;utilisation volatile de l&rsquo;espace de chargement et des fermetures de fronti\u00e8res, la large gamme de secteurs d&rsquo;activit\u00e9 du groupe a permis de minimiser les pertes. La nouvelle certification IFS pour le commerce ainsi que pour le secteur alimentaire et pharmaceutique repr\u00e9sente \u00e9galement une opportunit\u00e9 d&rsquo;utiliser les capacit\u00e9s de mani\u00e8re flexible et ainsi de contribuer \u00e0 la s\u00e9curit\u00e9 d&rsquo;approvisionnement. Dans le domaine de la logistique contractuelle, un grand projet automobile dans la r\u00e9gion de Rastatt, pr\u00e8s de Karlsruhe, a \u00e9t\u00e9 prolong\u00e9 de cinq ans suppl\u00e9mentaires. La SLG est d\u00e9j\u00e0 pr\u00e9sente dans cette r\u00e9gion depuis 2008 et emploie actuellement environ 650 personnes. De plus, la deuxi\u00e8me phase de construction du centre logistique de Seifert Automotive Logistics France \u00e0 Hambach\/Lorraine a \u00e9t\u00e9 achev\u00e9e sans retard. Avec plus de 40 000 m\u00e8tres carr\u00e9s et un acc\u00e8s direct \u00e0 l&rsquo;autoroute A4 \u00e0 proximit\u00e9 de la fronti\u00e8re allemande, le centre logistique offre de nombreuses possibilit\u00e9s d&rsquo;utilisation. Des capacit\u00e9s de stockage pour diff\u00e9rents secteurs sont encore disponibles sur le site.<\/p>\n<h5><strong>SLG mise sur la fabrication additive<\/strong><\/h5>\n<p>La SLG renforce le domaine de la fabrication additive. Des coop\u00e9rations existent d\u00e9j\u00e0 avec des entreprises et des \u00e9tablissements de recherche pour d\u00e9velopper davantage le savoir-faire dans le domaine de l&rsquo;impression 3D et se pr\u00e9parer proactivement pour l&rsquo;avenir. Maintenant, le logisticien contractuel va encore plus loin et investit dans ses propres capacit\u00e9s de production dans le domaine de la fabrication additive (AM). L&rsquo;objectif est de d\u00e9velopper progressivement l&rsquo;AM en tant que secteur d&rsquo;activit\u00e9 autonome pour faire face aux changements des mod\u00e8les commerciaux, \u00e0 l&rsquo;augmentation des flux de marchandises et \u00e0 la hausse des stocks. Julian Seifert, responsable de la num\u00e9risation de la SLG, voit un int\u00e9r\u00eat particulier dans l&rsquo;application pour la logistique des pi\u00e8ces de rechange ou la technologie m\u00e9dicale.<\/p>\n<h5><strong>Perspectives positives et investissements pour 2021<\/strong><\/h5>\n<p>Les pr\u00e9visions du groupe pour l&rsquo;exercice en cours sont positives. \u00ab\u00a0Nous pr\u00e9voyons, contrairement \u00e0 la crise \u00e9conomique mondiale de 2009, une reprise \u00e9conomique plus rapide. Apr\u00e8s la ma\u00eetrise de la pand\u00e9mie, une nouvelle dynamique va revenir dans l&rsquo;\u00e9conomie\u00a0\u00bb, d\u00e9clare Frey. Les actions du groupe logistique parlent d&rsquo;elles-m\u00eames. Ainsi, la SLG r\u00e9alise malgr\u00e9 la pand\u00e9mie le plus grand investissement unique de l&rsquo;entreprise familiale et construit un nouveau centre logistique multi-utilisateurs, y compris un b\u00e2timent administratif principal. D&rsquo;ici 2022, 60 000 emplacements de palettes seront cr\u00e9\u00e9s dans le nord d&rsquo;Ulm, avec une sortie d&rsquo;autoroute propre sur l&rsquo;A8 et \u00e0 proximit\u00e9 de la gare de conteneurs. \u00ab\u00a0Gr\u00e2ce \u00e0 l&#8217;emplacement strat\u00e9giquement avantageux, nous sommes bien pr\u00e9par\u00e9s pour le d\u00e9veloppement futur des affaires ainsi que pour la croissance future de notre groupe\u00a0\u00bb, d\u00e9clare Harald Seifert, pr\u00e9sident du conseil consultatif de la SLG. <br \/>Photo : \u00a9 Seifert \/ <strong><em>L\u00e9gende de l&rsquo;image :<\/em><\/strong><em> Simulation du nouveau centre logistique multi-utilisateurs de Seifert dans le nord d&rsquo;Ulm<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le groupe Seifert Logistics (SLG) a r\u00e9alis\u00e9 un chiffre d&rsquo;affaires de 200 millions d&rsquo;euros en 2020, une ann\u00e9e de crise. C&rsquo;est la deuxi\u00e8me meilleure valeur de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-24470","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le groupe Seifert Logistics (SLG) a r\u00e9alis\u00e9 un chiffre d&rsquo;affaires de 200 millions d&rsquo;euros en 2020, une ann\u00e9e de crise. C&rsquo;est la deuxi\u00e8me meilleure valeur de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-06T14:52:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:57:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise\",\"datePublished\":\"2021-04-06T14:52:03+00:00\",\"dateModified\":\"2025-12-15T11:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/\"},\"wordCount\":828,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/\",\"name\":\"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-04-06T14:52:03+00:00\",\"dateModified\":\"2025-12-15T11:57:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/04\\\/06\\\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/","og_locale":"fr_FR","og_type":"article","og_title":"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise - Loginfo24.","og_description":"Le groupe Seifert Logistics (SLG) a r\u00e9alis\u00e9 un chiffre d&rsquo;affaires de 200 millions d&rsquo;euros en 2020, une ann\u00e9e de crise. C&rsquo;est la deuxi\u00e8me meilleure valeur de [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-06T14:52:03+00:00","article_modified_time":"2025-12-15T11:57:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/"},"author":{"name":"","@id":""},"headline":"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise","datePublished":"2021-04-06T14:52:03+00:00","dateModified":"2025-12-15T11:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/"},"wordCount":828,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/","url":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/","name":"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-04-06T14:52:03+00:00","dateModified":"2025-12-15T11:57:48+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/04\/06\/le-groupe-seifert-logistics-avec-un-resultat-solide-en-annee-de-crise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le groupe Seifert Logistics avec un r\u00e9sultat solide en ann\u00e9e de crise"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=24470"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24470\/revisions"}],"predecessor-version":[{"id":44658,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24470\/revisions\/44658"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=24470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=24470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=24470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}