{"id":24314,"date":"2021-03-29T18:33:13","date_gmt":"2021-03-29T16:33:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/"},"modified":"2025-12-15T12:57:04","modified_gmt":"2025-12-15T11:57:04","slug":"hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/","title":{"rendered":"Hermes mise sur Swobbee comme solution d&rsquo;infrastructure de recharge \u00e0 Berlin"},"content":{"rendered":"<p>Le prestataire de services de colis Hermes mise sur Swobbee \u00e0 Berlin pour garantir un approvisionnement \u00e9nerg\u00e9tique sans faille de sa flotte de v\u00e9los cargo \u00e9lectriques. L&rsquo;une des stations de changement de batterie innovantes de Swobbee a \u00e9t\u00e9 mise en service au d\u00e9p\u00f4t Hermes \u00e0 Berlin-Tempelhof. L\u00e0, Swobbee veille \u00e0 ce qu&rsquo;un fonctionnement fluide des nouveaux v\u00e9los lourds ONO soit possible sans limitations d&rsquo;autonomie ni interruptions de charge.<\/p>\n<p>(Berlin) Hermes et Swobbee entretiennent une collaboration fructueuse de longue date. Le logisticien de colis avait d\u00e9j\u00e0 particip\u00e9 en 2018 au premier grand essai sur le terrain de la start-up berlinoise, afin d&rsquo;exp\u00e9rimenter pour la premi\u00e8re fois les avantages de cette infrastructure \u00e9nerg\u00e9tique novatrice, durable et efficace pour les applications de transport en milieu urbain, en collaboration avec d&rsquo;autres partenaires de projet.<\/p>\n<p>Le logisticien de colis Hermes augmente actuellement consid\u00e9rablement sa flotte de v\u00e9los cargo \u00e9lectriques \u00e0 Berlin pour livrer des envois dans la ville de Berlin de mani\u00e8re sans \u00e9missions. Le d\u00e9p\u00f4t Hermes \u00e0 Berlin-Tempelhof remplit \u00e0 cet \u00e9gard la fonction d&rsquo;un micro-d\u00e9p\u00f4t, consid\u00e9r\u00e9 comme une alternative d&rsquo;avenir aux syst\u00e8mes de livraison conventionnels dans la logistique urbaine. Cette approche respectueuse de la ville r\u00e9duit la pression du trafic tout en augmentant l&rsquo;efficacit\u00e9 sur le dernier kilom\u00e8tre.<\/p>\n<h5><strong>Solution de recharge id\u00e9ale pour le dernier kilom\u00e8tre<\/strong><\/h5>\n<p>La livraison par v\u00e9lo cargo est particuli\u00e8rement adapt\u00e9e aux zones de livraison dens\u00e9ment peupl\u00e9es avec un volume \u00e9lev\u00e9 d&rsquo;envois, comme c&rsquo;est le cas dans les quartiers de Mitte, Kreuzberg et Sch\u00f6neberg. Hermes utilise l\u00e0 des v\u00e9los lourds \u00e9lectriques du fabricant berlinois ONO. Les batteries GreenPack des transporteurs ONO peuvent \u00eatre \u00e9chang\u00e9es en quelques gestes \u00e0 la station Swobbee et sont donc toujours pr\u00eates \u00e0 l&#8217;emploi. Le nouveau fonctionnement quotidien a d\u00e9j\u00e0 d\u00e9marr\u00e9 avec succ\u00e8s, comme l&rsquo;explique Martin Mandos, responsable du dernier kilom\u00e8tre chez Hermes dans la r\u00e9gion de Berlin : \u00ab Les stations de recharge et de changement de Swobbee ne sont pas seulement un grand soutien pour nous, mais surtout une condition pr\u00e9alable \u00e0 l&rsquo;utilisation de nos v\u00e9los cargo \u00e9lectriques. \u00c0 notre d\u00e9p\u00f4t de Berlin-Tempelhof, nous avons le &lsquo;luxueux&rsquo; avantage que la colonne est directement plac\u00e9e sur notre site. C&rsquo;est particuli\u00e8rement pratique ! Le service de Swobbee est impeccable : tout est surveill\u00e9 \u00e0 distance, les batteries d\u00e9fectueuses sont remplac\u00e9es et nos livreurs peuvent toujours compter sur des batteries &lsquo;fra\u00eeches&rsquo; en d\u00e9placement. \u00bb<\/p>\n<p>Tobias Breyer, COO de Swobbee, voit \u00e9galement un grand potentiel dans l&rsquo;int\u00e9gration des solutions d&rsquo;infrastructure de recharge intelligentes et des solutions de transport pour la logistique urbaine : \u00ab Nous sommes tr\u00e8s heureux qu&rsquo;Hermes, en tant que l&rsquo;un des principaux prestataires de services de colis en Allemagne, confirme l&rsquo;efficacit\u00e9 et l&rsquo;efficience de notre syst\u00e8me de changement de batteries avec l&rsquo;utilisation d&rsquo;un autre Swobbee. Ce n&rsquo;est que le d\u00e9but. Au cours des prochaines ann\u00e9es, le transport de livraison \u00e0 v\u00e9lo dans les centres urbains va recevoir un v\u00e9ritable coup de pouce \u00e9nerg\u00e9tique. \u00bb<\/p>\n<p>Photo : \u00a9 Hermes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le prestataire de services de colis Hermes mise sur Swobbee \u00e0 Berlin pour garantir un approvisionnement \u00e9nerg\u00e9tique sans faille de sa flotte de v\u00e9los cargo \u00e9lectriques.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-24314","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hermes mise sur Swobbee comme solution d&#039;infrastructure de recharge \u00e0 Berlin - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hermes mise sur Swobbee comme solution d&#039;infrastructure de recharge \u00e0 Berlin - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le prestataire de services de colis Hermes mise sur Swobbee \u00e0 Berlin pour garantir un approvisionnement \u00e9nerg\u00e9tique sans faille de sa flotte de v\u00e9los cargo \u00e9lectriques. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T16:33:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:57:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hermes mise sur Swobbee comme solution d&rsquo;infrastructure de recharge \u00e0 Berlin\",\"datePublished\":\"2021-03-29T16:33:13+00:00\",\"dateModified\":\"2025-12-15T11:57:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/\",\"name\":\"Hermes mise sur Swobbee comme solution d'infrastructure de recharge \u00e0 Berlin - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-03-29T16:33:13+00:00\",\"dateModified\":\"2025-12-15T11:57:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/29\\\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hermes mise sur Swobbee comme solution d&rsquo;infrastructure de recharge \u00e0 Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hermes mise sur Swobbee comme solution d'infrastructure de recharge \u00e0 Berlin - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/","og_locale":"fr_FR","og_type":"article","og_title":"Hermes mise sur Swobbee comme solution d'infrastructure de recharge \u00e0 Berlin - Loginfo24.","og_description":"Le prestataire de services de colis Hermes mise sur Swobbee \u00e0 Berlin pour garantir un approvisionnement \u00e9nerg\u00e9tique sans faille de sa flotte de v\u00e9los cargo \u00e9lectriques. [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-03-29T16:33:13+00:00","article_modified_time":"2025-12-15T11:57:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/"},"author":{"name":"","@id":""},"headline":"Hermes mise sur Swobbee comme solution d&rsquo;infrastructure de recharge \u00e0 Berlin","datePublished":"2021-03-29T16:33:13+00:00","dateModified":"2025-12-15T11:57:04+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/","url":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/","name":"Hermes mise sur Swobbee comme solution d'infrastructure de recharge \u00e0 Berlin - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-03-29T16:33:13+00:00","dateModified":"2025-12-15T11:57:04+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/29\/hermes-mise-sur-swobbee-comme-solution-dinfrastructure-de-recharge-a-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Hermes mise sur Swobbee comme solution d&rsquo;infrastructure de recharge \u00e0 Berlin"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=24314"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24314\/revisions"}],"predecessor-version":[{"id":44350,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/24314\/revisions\/44350"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=24314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=24314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=24314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}