{"id":23934,"date":"2021-03-15T18:31:04","date_gmt":"2021-03-15T17:31:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/"},"modified":"2025-12-15T12:55:15","modified_gmt":"2025-12-15T11:55:15","slug":"le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/","title":{"rendered":"Le programme de formation de la KION Group entre dans une nouvelle phase"},"content":{"rendered":"<p>La KION Group offre \u00e9galement cette ann\u00e9e un d\u00e9but de carri\u00e8re attrayant pour les dipl\u00f4m\u00e9s universitaires avec un dipl\u00f4me de master. Au total, cinq postes dans le programme de formation en management sont \u00e0 pourvoir dans diverses entreprises du groupe. Le programme est marqu\u00e9 par une forte orientation internationale avec diff\u00e9rents axes professionnels.<\/p>\n<p>(Francfort\/Main) La KION GROUP AG, le leader mondial des \u00e9quipements (intra-)logistiques, poursuit son programme de formation en management de haute qualit\u00e9 pour les dipl\u00f4m\u00e9s universitaires avec un dipl\u00f4me de master. La prochaine promotion du programme de formation sur mesure dans diff\u00e9rentes disciplines commence le 1er octobre 2021. Les stages dans les domaines de l&rsquo;Intralogistics Aftersales, de la gestion de projet, de la recherche et d\u00e9veloppement, de la gestion des ressources humaines ainsi que de l&rsquo;automatisation mobile comprennent un programme vari\u00e9 de 18 mois avec une forte orientation internationale au sein du groupe KION op\u00e9rant \u00e0 l&rsquo;\u00e9chelle mondiale. Les participants doivent non seulement rapidement assumer des responsabilit\u00e9s dans leur propre domaine d&rsquo;expertise, mais aussi d\u00e9couvrir les diff\u00e9rentes facettes et les principales interfaces du groupe multi-marques.<\/p>\n<h5><strong>\u00c0 diff\u00e9rents endroits<\/strong><\/h5>\n<p>Le poste de stagiaire pour le domaine de l&rsquo;Intralogistics Aftersales est situ\u00e9 chez la filiale KION Linde Material Handling \u00e0 Aschaffenburg, en Bavi\u00e8re. Le stage en gestion de projet, en revanche, est \u00e9tabli chez la filiale Dematic, un sp\u00e9cialiste mondial du flux de mat\u00e9riaux avec des solutions logicielles intelligentes, de cha\u00eene d&rsquo;approvisionnement et d&rsquo;automatisation \u00e0 Heusenstamm, pr\u00e8s de Francfort\/Main. Un autre poste pour la recherche et d\u00e9veloppement est situ\u00e9 au sein de la fonction interne du directeur technique de KION, l&rsquo;organisation CTO, \u00e0 Hambourg. De plus, il y a un poste dans le domaine de la gestion des ressources humaines chez KION GROUP AG au si\u00e8ge du groupe \u00e0 Francfort. Le poste de stagiaire dans le domaine global de l&rsquo;automatisation mobile, c&rsquo;est-\u00e0-dire des syst\u00e8mes de transport sans conducteur, est \u00e9galement h\u00e9berg\u00e9 par KION GROUP AG, avec un site \u00e0 Aschaffenburg. Les stages sont divis\u00e9s en quatre blocs de quatre \u00e0 cinq mois, dont le troisi\u00e8me bloc comprend un s\u00e9jour de cinq mois dans un site \u00e0 l&rsquo;\u00e9tranger - si la situation pand\u00e9mique le permet. De cette mani\u00e8re, les dipl\u00f4m\u00e9s ont t\u00f4t l&rsquo;occasion de d\u00e9couvrir d&rsquo;autres sites internationaux et d&rsquo;\u00e9largir leurs horizons. Au d\u00e9but et \u00e0 mi-parcours du programme, des ateliers communs de cinq jours sont organis\u00e9s, o\u00f9 les connaissances de base sur le groupe KION, la formation m\u00e9thodologique et le r\u00e9seautage sont au centre des pr\u00e9occupations.<\/p>\n<h5><strong>D\u00e9velopper son potentiel et r\u00e9aliser ses id\u00e9es<\/strong><\/h5>\n<p>\u00ab\u00a0Avec notre programme de formation, nous offrons aux jeunes leaders motiv\u00e9s et orient\u00e9s internationalement un d\u00e9but de carri\u00e8re attrayant\u00a0\u00bb, d\u00e9clare Anke Groth, CFO et directrice des ressources humaines de KION Group. \u00ab\u00a0Ils ont chez nous les meilleures possibilit\u00e9s de d\u00e9velopper leur potentiel et de r\u00e9aliser leurs propres id\u00e9es - et nous gagnons en m\u00eame temps de jeunes talents avec lesquels nous souhaitons poursuivre notre histoire de succ\u00e8s et fa\u00e7onner l&rsquo;avenir de l&rsquo;intralogistique.\u00a0\u00bb En plus d&rsquo;opportunit\u00e9s de carri\u00e8re exceptionnelles et de t\u00e2ches vari\u00e9es dans un secteur d&rsquo;avenir dynamique, les stagiaires peuvent \u00e9galement s&rsquo;attendre \u00e0 des \u00e9quipes coll\u00e9giales ainsi qu&rsquo;\u00e0 une r\u00e9mun\u00e9ration attrayante. Le processus de candidature comprend quatre \u00e9tapes - de la soumission des documents de candidature \u00e0 un entretien t\u00e9l\u00e9phonique et un test en ligne, jusqu&rsquo;\u00e0 un centre d&rsquo;\u00e9valuation - et se d\u00e9roule enti\u00e8rement en anglais. Pour plus d&rsquo;informations sur le programme de formation et sur la candidature, veuillez consulter le site Web de KION Group :<br \/>Photo : \u00a9 KION Group<br \/><a href=\"https:\/\/www.kiongroup.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.kiongroup.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La KION Group offre \u00e9galement cette ann\u00e9e un d\u00e9but de carri\u00e8re attrayant pour les dipl\u00f4m\u00e9s universitaires avec un dipl\u00f4me de master. Au total, cinq postes dans<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-23934","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le programme de formation de la KION Group entre dans une nouvelle phase - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le programme de formation de la KION Group entre dans une nouvelle phase - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La KION Group offre \u00e9galement cette ann\u00e9e un d\u00e9but de carri\u00e8re attrayant pour les dipl\u00f4m\u00e9s universitaires avec un dipl\u00f4me de master. Au total, cinq postes dans [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T17:31:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:55:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le programme de formation de la KION Group entre dans une nouvelle phase\",\"datePublished\":\"2021-03-15T17:31:04+00:00\",\"dateModified\":\"2025-12-15T11:55:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/\",\"name\":\"Le programme de formation de la KION Group entre dans une nouvelle phase - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-03-15T17:31:04+00:00\",\"dateModified\":\"2025-12-15T11:55:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/03\\\/15\\\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le programme de formation de la KION Group entre dans une nouvelle phase\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le programme de formation de la KION Group entre dans une nouvelle phase - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/","og_locale":"fr_FR","og_type":"article","og_title":"Le programme de formation de la KION Group entre dans une nouvelle phase - Loginfo24.","og_description":"La KION Group offre \u00e9galement cette ann\u00e9e un d\u00e9but de carri\u00e8re attrayant pour les dipl\u00f4m\u00e9s universitaires avec un dipl\u00f4me de master. Au total, cinq postes dans [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-03-15T17:31:04+00:00","article_modified_time":"2025-12-15T11:55:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/"},"author":{"name":"","@id":""},"headline":"Le programme de formation de la KION Group entre dans une nouvelle phase","datePublished":"2021-03-15T17:31:04+00:00","dateModified":"2025-12-15T11:55:15+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/","url":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/","name":"Le programme de formation de la KION Group entre dans une nouvelle phase - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-03-15T17:31:04+00:00","dateModified":"2025-12-15T11:55:15+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/03\/15\/le-programme-de-formation-de-la-kion-group-entre-dans-une-nouvelle-phase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le programme de formation de la KION Group entre dans une nouvelle phase"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/23934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=23934"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/23934\/revisions"}],"predecessor-version":[{"id":43592,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/23934\/revisions\/43592"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=23934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=23934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=23934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}