{"id":23068,"date":"2021-02-04T18:41:29","date_gmt":"2021-02-04T17:41:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/"},"modified":"2025-12-15T12:51:24","modified_gmt":"2025-12-15T11:51:24","slug":"scannell-properties-developpe-pour-amazon-en-saxe-anhalt","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/","title":{"rendered":"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt"},"content":{"rendered":"<p>Scannell Properties, une soci\u00e9t\u00e9 am\u00e9ricaine de d\u00e9veloppement immobilier, d\u00e9veloppe pour Amazon \u00e0 Teuschenthal pr\u00e8s de Halle an der Saale (Saxe-Anhalt) un bien immobilier logistique. Le projet sert \u00e0 la logistique de dernier kilom\u00e8tre du d\u00e9taillant en ligne. Le bien couvre environ 6 400 m2. Les travaux de terrassement ont d\u00e9j\u00e0 commenc\u00e9 d\u00e9but janvier 2021 et l&rsquo;ach\u00e8vement est pr\u00e9vu pour l&rsquo;automne 2021.<\/p>\n<p>(Teuschenthal) Scannell Properties, la soci\u00e9t\u00e9 am\u00e9ricaine de d\u00e9veloppement immobilier et d&rsquo;investissement avec des succursales en Europe, sp\u00e9cialis\u00e9e dans les projets industriels et logistiques \u00e0 grande \u00e9chelle, d\u00e9veloppe pour le d\u00e9taillant en ligne Amazon un bien immobilier logistique en Saxe-Anhalt.<\/p>\n<p>Le centre logistique pour la livraison de colis sur le dernier kilom\u00e8tre est en cours de construction \u00e0 Teutschenthal pr\u00e8s de Halle (Saale). Il s&rsquo;agit d&rsquo;un d\u00e9veloppement sur mesure avec environ 4 600 m\u00b2 d&rsquo;espace d&rsquo;entrep\u00f4t et 1 900 m\u00b2 d&rsquo;espace de bureau et de services. Le terrain est situ\u00e9 dans le parc d&rsquo;activit\u00e9s de la commune de Teutschenthal, \u00e0 environ 15 minutes en voiture de la grande ville de Halle (Saale).<\/p>\n<h5><strong>Les travaux commencent \u00e0 la mi-f\u00e9vrier<\/strong><\/h5>\n<p>Les travaux de terrassement ont d\u00e9j\u00e0 commenc\u00e9 d\u00e9but janvier 2021, de sorte que les travaux de construction peuvent commencer sans interruption \u00e0 partir de la mi-f\u00e9vrier. L&rsquo;ach\u00e8vement et la mise en service sont pr\u00e9vus pour l&rsquo;automne 2021.<\/p>\n<p>Le d\u00e9veloppeur immobilier attache une grande importance \u00e0 une installation flexible lors de l&rsquo;ex\u00e9cution. De plus, le projet de construction comprend des mesures \u00e9tendues pour un fonctionnement aussi respectueux de l&rsquo;environnement et \u00e0 faibles \u00e9missions que possible. Scannell Properties vise le certificat or de la Deutsche Gesellschaft f\u00fcr Nachhaltiges Bauen (DGNB), et le toit de l&rsquo;installation sera \u00e9galement \u00e9quip\u00e9 d&rsquo;un syst\u00e8me photovolta\u00efque.<\/p>\n<p>Robert Viegers, vice-pr\u00e9sident d&rsquo;Amazon Logistics en Allemagne, commente le d\u00e9veloppement ainsi : \u00ab Nous sommes tr\u00e8s heureux d&rsquo;ouvrir un centre de distribution \u00e0 Teutschenthal, o\u00f9 plus de 20 ans de comp\u00e9tence logistique, de progr\u00e8s technologique et d&rsquo;investissements dans l&rsquo;infrastructure de transport sont r\u00e9unis. Ainsi, les clients d&rsquo;Amazon b\u00e9n\u00e9ficient d&rsquo;options de livraison plus rapides et plus flexibles \u00bb.<\/p>\n<h5><strong>La politique se r\u00e9jouit \u00e9galement<\/strong><\/h5>\n<p>Le maire, Tilo Eigendorf, se montre particuli\u00e8rement heureux de l&rsquo;implantation du d\u00e9taillant en ligne : \u00ab C&rsquo;est un signal important pour notre site et la r\u00e9gion qu&rsquo;une entreprise comme Amazon s&rsquo;implante ici. La cr\u00e9ation de l&rsquo;unit\u00e9 logistique repr\u00e9sente une \u00e9tape importante dans le d\u00e9veloppement commercial de notre commune. \u00bb<\/p>\n<p>Heiko Richter, directeur g\u00e9n\u00e9ral de Scannell Properties en Allemagne, souligne la collaboration r\u00e9ussie entre toutes les parties : \u00ab En tant que d\u00e9veloppeur de projets international pour des biens immobiliers commerciaux et logistiques, notre objectif est de fournir \u00e0 nos clients internationaux en Europe les espaces n\u00e9cessaires \u00e0 leur expansion.<\/p>\n<p>Cela profite \u00e0 l&rsquo;\u00e9conomie locale ainsi qu&rsquo;au march\u00e9 du travail. R\u00e9unir les exigences de toutes les parties de mani\u00e8re consensuelle a \u00e9galement \u00e9t\u00e9 un succ\u00e8s remarquable dans ce projet. Je tiens \u00e0 remercier en particulier les autorit\u00e9s et tous les partenaires en ces temps difficiles. \u00bb<\/p>\n<p>Photo : \u00a9 Scannell \/ <strong><em>L\u00e9gende de l&rsquo;image :<\/em><\/strong><em> Visualisation a\u00e9rienne du projet \u00e0 Teutschenthal. <\/em><\/p>\n<p><a href=\"https:\/\/www.scannellproperties.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.scannellproperties.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scannell Properties, une soci\u00e9t\u00e9 am\u00e9ricaine de d\u00e9veloppement immobilier, d\u00e9veloppe pour Amazon \u00e0 Teuschenthal pr\u00e8s de Halle an der Saale (Saxe-Anhalt) un bien immobilier logistique. Le projet<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1560,1561],"tags":[],"class_list":["post-23068","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Scannell Properties, une soci\u00e9t\u00e9 am\u00e9ricaine de d\u00e9veloppement immobilier, d\u00e9veloppe pour Amazon \u00e0 Teuschenthal pr\u00e8s de Halle an der Saale (Saxe-Anhalt) un bien immobilier logistique. Le projet [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T17:41:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:51:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt\",\"datePublished\":\"2021-02-04T17:41:29+00:00\",\"dateModified\":\"2025-12-15T11:51:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/\"},\"wordCount\":559,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/\",\"name\":\"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-02-04T17:41:29+00:00\",\"dateModified\":\"2025-12-15T11:51:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/04\\\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/","og_locale":"fr_FR","og_type":"article","og_title":"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt - Loginfo24.","og_description":"Scannell Properties, une soci\u00e9t\u00e9 am\u00e9ricaine de d\u00e9veloppement immobilier, d\u00e9veloppe pour Amazon \u00e0 Teuschenthal pr\u00e8s de Halle an der Saale (Saxe-Anhalt) un bien immobilier logistique. Le projet [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-02-04T17:41:29+00:00","article_modified_time":"2025-12-15T11:51:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/"},"author":{"name":"","@id":""},"headline":"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt","datePublished":"2021-02-04T17:41:29+00:00","dateModified":"2025-12-15T11:51:24+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/"},"wordCount":559,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/","url":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/","name":"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-02-04T17:41:29+00:00","dateModified":"2025-12-15T11:51:24+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/04\/scannell-properties-developpe-pour-amazon-en-saxe-anhalt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Scannell Properties d\u00e9veloppe pour Amazon en Saxe-Anhalt"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/23068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=23068"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/23068\/revisions"}],"predecessor-version":[{"id":41862,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/23068\/revisions\/41862"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=23068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=23068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=23068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}