{"id":22993,"date":"2021-02-01T17:56:21","date_gmt":"2021-02-01T16:56:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/"},"modified":"2025-12-15T12:50:59","modified_gmt":"2025-12-15T11:50:59","slug":"lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/","title":{"rendered":"L&rsquo;ASTAG constate qu&rsquo;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro"},"content":{"rendered":"<p>L&rsquo;association suisse des v\u00e9hicules utilitaires ASTAG souligne que depuis exactement 20 ans, le secteur du transport routier contribue efficacement \u00e0 la politique de transfert avec des paiements de LSVA totalisant plus de 25 milliards de francs. En lien avec la r\u00e9forme annonc\u00e9e du syst\u00e8me tarifaire, l&rsquo;ASTAG est pr\u00eate \u00e0 discuter, mais exige une s\u00e9curit\u00e9 de planification et d&rsquo;investissement pour le transport routier. Les objectifs environnementaux de la LSVA sont atteints. Les r\u00e8gles du jeu ne doivent pas \u00eatre modifi\u00e9es maintenant.<\/p>\n<p>(Berne) La redevance sur le transport lourd d\u00e9pendant de la performance (LSVA) est de loin le plus grand facteur de charge financi\u00e8re de l&rsquo;\u00c9tat dans le secteur du transport routier suisse. Il y a exactement 20 ans, le 31 janvier 2001, \u00e9tait la date de d\u00e9but de la premi\u00e8re p\u00e9riode de facturation. Depuis lors, environ 1 franc est d\u00fb pour chaque kilom\u00e8tre parcouru par un camion de 40 tonnes. Cela repr\u00e9sente, selon le kilom\u00e9trage et la cat\u00e9gorie d&rsquo;\u00e9mission*, jusqu&rsquo;\u00e0 100&rsquo;000 francs par an et par v\u00e9hicule utilitaire \u2013 au profit de la caisse f\u00e9d\u00e9rale, avant m\u00eame que les entreprises de transport ne gagnent un centime. Dans aucun autre pays, le p\u00e9age n&rsquo;est aussi \u00e9lev\u00e9. Actuellement, 1,5 milliard de francs s&rsquo;accumulent chaque ann\u00e9e, et depuis 2001, cela repr\u00e9sente plus de 25 milliards de francs au total. Deux tiers sont directement utilis\u00e9s pour financer l&rsquo;infrastructure ferroviaire, ce qui permet au transport routier de contribuer activement et efficacement \u00e0 la politique de transfert.<\/p>\n<h5><strong>Sujet \u00e9motionnel \u2013 destruction massive de valeur<\/strong><\/h5>\n<p> Pourtant, l&rsquo;association suisse des v\u00e9hicules utilitaires ASTAG pr\u00e9f\u00e8re regarder vers l&rsquo;avenir plut\u00f4t que de revenir sur une histoire de LSVA extr\u00eamement mouvement\u00e9e et \u00e9motionnelle. Trop souvent, les pr\u00e9occupations et arguments l\u00e9gitimes du secteur du transport routier n&rsquo;ont pas \u00e9t\u00e9 pris en compte par la politique dans le pass\u00e9 \u2013 en particulier jusqu&rsquo;en 2010. Les cons\u00e9quences n\u00e9gatives ont \u00e9t\u00e9 des augmentations massives des tarifs de la LSVA ainsi que des modifications anticip\u00e9es et arbitraires (\u00ab r\u00e9trogradations \u00bb) des cat\u00e9gories de redevance. La valeur d&rsquo;acquisition des v\u00e9hicules a ainsi \u00e9t\u00e9 r\u00e9duite de mani\u00e8re dramatique, voire compl\u00e8tement d\u00e9truite, plus d&rsquo;une fois. \u00ab Je comprends tr\u00e8s bien l&rsquo;amertume et les \u00e9motions que beaucoup de nos membres ressentent concernant la LSVA \u00bb, d\u00e9clare le conseiller aux \u00c9tats et pr\u00e9sident central de l&rsquo;ASTAG, Thierry Burkart : \u00ab Non seulement \u00e0 cause de la LSVA, plusieurs petites et moyennes entreprises ont disparu du march\u00e9 ! \u00bb<br \/> D&rsquo;autant plus importants sont l&rsquo;\u00e9quit\u00e9, la proportionnalit\u00e9 et \u00ab l&rsquo;effet sur l&rsquo;objectif \u00bb dans le cadre de l&rsquo;\u00e9volution annonc\u00e9e de la LSVA. L&rsquo;ASTAG se r\u00e9jouit de constater que le Conseil f\u00e9d\u00e9ral semble \u2013 en s&rsquo;\u00e9loignant de la pratique ant\u00e9rieure \u2013 vouloir agir non pas avec le \u00ab marteau \u00bb, mais en dialogue avec le secteur. Avec l&rsquo;augmentation des moteurs alternatifs (\u00e9lectriques, CNG\/LNG, hydrog\u00e8ne), des discussions sur la syst\u00e9matique et les tarifs sont sans aucun doute n\u00e9cessaires. Il est cependant crucial que la s\u00e9curit\u00e9 des investissements et la planification anticip\u00e9e soient en tout cas pr\u00e9serv\u00e9es.<\/p>\n<h5><strong>Aucune r\u00e9trogradation anticip\u00e9e de la norme EURO VI<\/strong><\/h5>\n<p> Avec la r\u00e9duction des \u00e9missions de polluants (monoxyde de carbone, oxydes d&rsquo;azote, etc.) \u00e0 presque z\u00e9ro, atteinte gr\u00e2ce \u00e0 une modernisation rapide de la flotte, les objectifs environnementaux de la LSVA sont atteints depuis longtemps. Ce serait fatal, voire un coup inacceptable pour le secteur, de changer fondamentalement les r\u00e8gles du jeu maintenant et de rendre la LSVA, par exemple, principalement d\u00e9pendante des \u00e9missions de CO2. Une r\u00e9trogradation des v\u00e9hicules de la norme Euro VI, jusqu&rsquo;\u00e0 pr\u00e9sent la plus moderne, ne doit donc avoir lieu que si une \u00e9ventuelle nouvelle norme EURO VII est disponible en s\u00e9rie pour chaque domaine d&rsquo;application \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne. \u00ab L&rsquo;ASTAG est cependant pr\u00eate \u00e0 participer de mani\u00e8re constructive aux discussions \u00e0 venir \u00bb, souligne Thierry Burkart.<br \/>*Le kilom\u00e9trage moyen d&rsquo;un camion en Suisse se situe entre 70&rsquo;000 et 90&rsquo;000 kilom\u00e8tres. Des informations d\u00e9taill\u00e9es sur le calcul de la LSVA se trouvent sur le calculateur LSVA de l&rsquo;ASTAG (<a href=\"https:\/\/www.astag.ch\/wissen\/betriebswirtschaft\/lsva-rechner\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.astag.ch\/wissen\/betriebswirtschaft\/lsva-rechner<\/a> ou <a href=\"https:\/\/www.lsva.ch)\" target=\"_blank\" rel=\"noopener noreferrer\">www.lsva.ch)<\/a>.<\/p>\n<p>Photo : \u00a9 Adobe Stock<br \/><a href=\"https:\/\/www.post.ch\" target=\"_blank\" rel=\"noopener noreferrer\">www.astag.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;association suisse des v\u00e9hicules utilitaires ASTAG souligne que depuis exactement 20 ans, le secteur du transport routier contribue efficacement \u00e0 la politique de transfert avec des<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-22993","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ASTAG constate qu&#039;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ASTAG constate qu&#039;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;association suisse des v\u00e9hicules utilitaires ASTAG souligne que depuis exactement 20 ans, le secteur du transport routier contribue efficacement \u00e0 la politique de transfert avec des [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T16:56:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:50:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L&rsquo;ASTAG constate qu&rsquo;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro\",\"datePublished\":\"2021-02-01T16:56:21+00:00\",\"dateModified\":\"2025-12-15T11:50:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/\"},\"wordCount\":748,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/\",\"name\":\"L'ASTAG constate qu'apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-02-01T16:56:21+00:00\",\"dateModified\":\"2025-12-15T11:50:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2021\\\/02\\\/01\\\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;ASTAG constate qu&#8217;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ASTAG constate qu'apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ASTAG constate qu'apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro - Loginfo24.","og_description":"L&rsquo;association suisse des v\u00e9hicules utilitaires ASTAG souligne que depuis exactement 20 ans, le secteur du transport routier contribue efficacement \u00e0 la politique de transfert avec des [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-02-01T16:56:21+00:00","article_modified_time":"2025-12-15T11:50:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/"},"author":{"name":"","@id":""},"headline":"L&rsquo;ASTAG constate qu&rsquo;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro","datePublished":"2021-02-01T16:56:21+00:00","dateModified":"2025-12-15T11:50:59+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/"},"wordCount":748,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/","url":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/","name":"L'ASTAG constate qu'apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2021-02-01T16:56:21+00:00","dateModified":"2025-12-15T11:50:59+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2021\/02\/01\/lastag-constate-quapres-20-ans-de-lsva-les-emissions-de-polluants-sont-a-zero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;ASTAG constate qu&#8217;apr\u00e8s 20 ans de LSVA, les \u00e9missions de polluants sont \u00e0 z\u00e9ro"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/22993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=22993"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/22993\/revisions"}],"predecessor-version":[{"id":41712,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/22993\/revisions\/41712"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=22993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=22993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=22993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}