{"id":19366,"date":"2020-08-28T07:00:49","date_gmt":"2020-08-28T05:00:49","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/"},"modified":"2025-12-15T12:35:05","modified_gmt":"2025-12-15T11:35:05","slug":"de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/","title":{"rendered":"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&rsquo;entrep\u00f4t \u00e9largie"},"content":{"rendered":"<p>La Jentsch Logistik GmbH, d\u00e9j\u00e0 membre du groupe Gras, \u00e0 Cologne, sera renomm\u00e9e Gras Logistik GmbH \u00e0 partir du 1er septembre. En m\u00eame temps, la surface d&rsquo;entrep\u00f4t sera \u00e9tendue \u00e0 10 000 m2. Cela permettra \u00e0 Gras d&rsquo;am\u00e9liorer sa capacit\u00e9 op\u00e9rationnelle \u00e0 Cologne et d&rsquo;offrir une meilleure offre \u00e0 ses clients.<\/p>\n<p>(Neuwied) \u00c0 partir du 1er septembre 2020, la Jentsch Logistik GmbH (Cologne), membre du groupe Gras (Neuwied) depuis 2007, sera renomm\u00e9e Gras Logistik GmbH. Cela fait suite \u00e0 l&rsquo;extension de la surface d&rsquo;entrep\u00f4t \u00e0 10 000 m\u00b2 apr\u00e8s le d\u00e9part contractuel de l&rsquo;ancien sous-locataire. Ainsi, le partenaire IDS Gras et le transitaire r\u00e9gional pour Cologne et ses environs disposeront de capacit\u00e9s suffisantes \u2013 tant pour le volume de colis accru que pour une croissance future.<\/p>\n<p>\u00ab Avec l&rsquo;extension de notre installation de transport \u00e0 Cologne, nous am\u00e9liorons consid\u00e9rablement notre capacit\u00e9 op\u00e9rationnelle et pouvons offrir \u00e0 nos clients dans la r\u00e9gion de Cologne un package de services optimal et un service complet \u00bb, se r\u00e9jouit Madeleine Boos, directrice g\u00e9n\u00e9rale du groupe Gras. Le package de services du groupe Gras \u00e0 ses cinq sites de transport \u00e0 Neuwied, \u00d6tzingen (Westerwald), Cologne, Mannheim et \u00d6tigheim va du transport de marchandises \u00e0 la logistique contractuelle, en passant par les chargements partiels et complets ainsi que le fret maritime et a\u00e9rien.<\/p>\n<h5>R\u00e9action \u00e0 la croissance et aux besoins des clients<\/h5>\n<p>\u00ab Avec maintenant un total de 42 800 m\u00b2 de surface fonci\u00e8re, 10 000 m\u00b2 de surface de transbordement couverte et 120 portes, nous pouvons r\u00e9agir encore mieux et plus rapidement aux besoins croissants des clients et \u00e0 la croissance \u00bb, d\u00e9clare Andreas Teichhof, directeur g\u00e9n\u00e9ral de la Jentsch Logistik GmbH depuis avril 2020 et prochainement de la Gras Logistik GmbH. Jusqu&rsquo;\u00e0 3 000 envois sont trait\u00e9s ici chaque jour.<\/p>\n<p>Id\u00e9alement situ\u00e9 directement sur l&rsquo;autoroute A4, Gras Logistik et le \u00ab roi r\u00e9gional IDS \u00bb \u00e0 la porte Eifel de Cologne desservent depuis plus de 13 ans une zone allant de Bedburg \u00e0 Dahlem et d&rsquo;Aix-la-Chapelle \u00e0 Lohmar. Les clients comprennent principalement des entreprises du secteur papetier, du bricolage et de l&rsquo;industrie des biens de consommation, ainsi que des fabricants de produits d&rsquo;hygi\u00e8ne.<\/p>\n<h5><strong>Groupe Gras<\/strong><\/h5>\n<p>Le groupe Gras comprend les entreprises de transport Gras Spedition GmbH &amp; Co. KG \u00e0 Neuwied et \u00d6tzingen (Westerwald), Gras Logistik GmbH \u00e0 Cologne ainsi que Network Logistics GmbH avec des sites \u00e0 Mannheim et \u00d6tigheim. Tous sont partenaires de la coop\u00e9ration IDS pour le transport de marchandises. L&rsquo;offre du groupe Gras comprend des concepts de transport pour l&rsquo;approvisionnement et la distribution, des livraisons B2B ou aux particuliers, ainsi que de la logistique contractuelle et d&rsquo;entrep\u00f4t, ainsi que du fret maritime et a\u00e9rien. D&rsquo;autres filiales incluent Informatik Team GmbH (Neuwied) et le prestataire logistique Gras Transpack GmbH (Polch). Au total, le groupe Gras emploie plus de 600 personnes, transporte environ 8 000 envois par jour et g\u00e9n\u00e8re un chiffre d&rsquo;affaires de plus de 120 millions d&rsquo;euros (2019).<\/p>\n<p>Photo : \u00a9 Gras<\/p>\n<p><a href=\"https:\/\/www.grasgruppe.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.grasgruppe.de<\/a> \u00a0\u00a0\u00a0<a href=\"https:\/\/www.jentsch-logistik.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.jentsch-logistik.de\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Jentsch Logistik GmbH, d\u00e9j\u00e0 membre du groupe Gras, \u00e0 Cologne, sera renomm\u00e9e Gras Logistik GmbH \u00e0 partir du 1er septembre. En m\u00eame temps, la surface<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1560,1561],"tags":[],"class_list":["post-19366","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&#039;entrep\u00f4t \u00e9largie - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&#039;entrep\u00f4t \u00e9largie - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"La Jentsch Logistik GmbH, d\u00e9j\u00e0 membre du groupe Gras, \u00e0 Cologne, sera renomm\u00e9e Gras Logistik GmbH \u00e0 partir du 1er septembre. En m\u00eame temps, la surface [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-28T05:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:35:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&rsquo;entrep\u00f4t \u00e9largie\",\"datePublished\":\"2020-08-28T05:00:49+00:00\",\"dateModified\":\"2025-12-15T11:35:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/\"},\"wordCount\":514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/\",\"name\":\"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d'entrep\u00f4t \u00e9largie - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-08-28T05:00:49+00:00\",\"dateModified\":\"2025-12-15T11:35:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/08\\\/28\\\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&#8217;entrep\u00f4t \u00e9largie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d'entrep\u00f4t \u00e9largie - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/","og_locale":"fr_FR","og_type":"article","og_title":"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d'entrep\u00f4t \u00e9largie - Loginfo24.","og_description":"La Jentsch Logistik GmbH, d\u00e9j\u00e0 membre du groupe Gras, \u00e0 Cologne, sera renomm\u00e9e Gras Logistik GmbH \u00e0 partir du 1er septembre. En m\u00eame temps, la surface [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-08-28T05:00:49+00:00","article_modified_time":"2025-12-15T11:35:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/"},"author":{"name":"","@id":""},"headline":"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&rsquo;entrep\u00f4t \u00e9largie","datePublished":"2020-08-28T05:00:49+00:00","dateModified":"2025-12-15T11:35:05+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/"},"wordCount":514,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/","url":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/","name":"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d'entrep\u00f4t \u00e9largie - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2020-08-28T05:00:49+00:00","dateModified":"2025-12-15T11:35:05+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2020\/08\/28\/de-jentsch-a-cologne-devient-gras-logistik-gmbh-avec-une-surface-dentrepot-elargie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"De Jentsch \u00e0 Cologne devient Gras Logistik GmbH avec une surface d&#8217;entrep\u00f4t \u00e9largie"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/19366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=19366"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/19366\/revisions"}],"predecessor-version":[{"id":35020,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/19366\/revisions\/35020"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=19366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=19366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=19366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}