{"id":17725,"date":"2020-06-02T07:00:37","date_gmt":"2020-06-02T05:00:37","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/"},"modified":"2025-12-15T12:28:23","modified_gmt":"2025-12-15T11:28:23","slug":"le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/","title":{"rendered":"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower"},"content":{"rendered":"<p>Le ferry hybride &lsquo;Copenhagen&rsquo; de Scandlines navigue d\u00e9sormais avec une voile rotor de 30 m\u00e8tres de haut de Norsepower, qui devrait r\u00e9duire les \u00e9missions de CO2 d&rsquo;environ quatre \u00e0 cinq pour cent. La voile a \u00e9t\u00e9 install\u00e9e au port maritime de Rostock.<\/p>\n<p>(Rostock) Scandlines, pionnier dans le domaine du transport maritime \u00e9cologique, et Norsepower Oy Ltd., l&rsquo;une des entreprises leaders en technologie propre et en ing\u00e9nierie, ainsi que pr\u00e9curseur dans le domaine de la technologie moderne de propulsion \u00e9olienne, ont annonc\u00e9 l&rsquo;installation r\u00e9ussie de la voile rotor de Norsepower. L&rsquo;installation a pu \u00eatre r\u00e9alis\u00e9e en seulement quelques heures lors d&rsquo;un s\u00e9jour nocturne pr\u00e9vu \u00e0 bord du ferry hybride de Scandlines &lsquo;Copenhagen&rsquo;.<\/p>\n<p>Le ferry hybride &lsquo;Copenhagen&rsquo;, qui navigue entre Rostock et Gedser, a \u00e9t\u00e9 \u00e9quip\u00e9 d&rsquo;une voile rotor de la soci\u00e9t\u00e9 Norsepower, mesurant 30 m de haut et ayant un diam\u00e8tre de cinq m\u00e8tres. Apr\u00e8s une pr\u00e9paration minutieuse au cours des derniers mois, l&rsquo;installation a pu \u00eatre effectu\u00e9e en quelques heures.<\/p>\n<p>La voile rotor de Norsepower \u2013 qui peut \u00eatre install\u00e9e sur de nouveaux navires ainsi que sur des navires existants \u2013 est une version moderne d&rsquo;un rotor Flettner, un cylindre rotatif dont la technologie est bas\u00e9e sur l&rsquo;effet Magnus et qui propulse le navire gr\u00e2ce \u00e0 l&rsquo;\u00e9nergie \u00e9olienne. Gr\u00e2ce \u00e0 l&rsquo;installation de la voile rotor, la quatri\u00e8me installation r\u00e9ussie r\u00e9alis\u00e9e par Norsepower, les \u00e9missions de CO2 devraient \u00eatre r\u00e9duites d&rsquo;environ quatre \u00e0 cinq pour cent, sans affecter la vitesse et le temps de trajet.<\/p>\n<p>Tuomas Riski, PDG de Norsepower, a comment\u00e9 l&rsquo;installation comme suit : \u00ab\u00a0Nous sommes tr\u00e8s heureux d&rsquo;annoncer l&rsquo;installation r\u00e9cemment r\u00e9ussie de la voile rotor, qui montre que la r\u00e9trofit peut \u00eatre r\u00e9alis\u00e9e sans interruptions prolong\u00e9es ou pannes des op\u00e9rations quotidiennes. Scandlines peut se vanter de succ\u00e8s notables dans l&rsquo;investissement dans de nouvelles technologies propres qui r\u00e9duisent les \u00e9missions de CO2 de sa flotte. L&rsquo;ajout de la voile rotor de Norsepower fait du &lsquo;Copenhagen&rsquo; l&rsquo;un des ferries les plus \u00e9co\u00e9nerg\u00e9tiques au monde.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Avec la pression r\u00e9glementaire et publique internationale croissante sur l&rsquo;industrie maritime pour r\u00e9duire les \u00e9missions de CO2, il est important que le secteur reconnaisse la valeur de l&rsquo;une des plus anciennes formes de propulsion \u2013 la valeur du vent. Le march\u00e9 de la propulsion \u00e9olienne est en croissance, et cette installation illustre comment la combinaison de toutes les m\u00e9thodes d&rsquo;optimisation des navires est la cl\u00e9 d&rsquo;un progr\u00e8s plus complet.\u00a0\u00bb<\/p>\n<p>Le PDG de Scandlines, S\u00f8ren Poulsgaard Jensen, ajoute : \u00ab\u00a0Nous voyons une valeur \u00e9norme dans les investissements dans des technologies visant \u00e0 r\u00e9duire les \u00e9missions de CO2. La collaboration avec Norsepower sur cette solution innovante a parfaitement compl\u00e9t\u00e9 nos valeurs et objectifs en mati\u00e8re de navigation durable. Sur notre ferry hybride moderne, cette solution compl\u00e9tera l&rsquo;optimisation hydrodynamique de la coque du navire et un syst\u00e8me de propulsion hybride \u00e9lectrique avec un syst\u00e8me de stockage d&rsquo;\u00e9nergie aliment\u00e9 par batterie, am\u00e9liorant non seulement notre efficacit\u00e9, mais aussi notre rentabilit\u00e9. Nous sommes impatients de voir les avantages imm\u00e9diats de cette technologie.\u00a0\u00bb<\/p>\n<p>La voile rotor est la premi\u00e8re technologie de propulsion \u00e9olienne additionnelle test\u00e9e et commercialement fonctionnelle de l&rsquo;industrie maritime mondiale. La solution est enti\u00e8rement automatis\u00e9e et d\u00e9tecte lorsque le vent est suffisamment fort pour g\u00e9n\u00e9rer des \u00e9conomies d&rsquo;\u00e9missions, et d\u00e9marre automatiquement la voile rotor.<\/p>\n<p><strong>\u00c0 propos de Scandlines<\/strong><\/p>\n<p>Scandlines est le symbole d&rsquo;une coop\u00e9ration historique et \u00e9troite entre l&rsquo;Allemagne et le Danemark. Scandlines exploite deux lignes de ferry \u00e0 haute fr\u00e9quence et capacit\u00e9, avec une vision verte pour l&rsquo;avenir.<\/p>\n<p>Avec plus de 41 500 d\u00e9parts r\u00e9partis sur 8 ferries, Scandlines a transport\u00e9 en 2019 un total de 7,2 millions de passagers, 1,7 million de voitures et environ 700 000 unit\u00e9s de fret sur les routes Puttgarden-R\u00f8dby et Rostock-Gedser.<\/p>\n<p>Le projet Wind Assisted Ship Propulsion (WASP) est financ\u00e9 dans le cadre du programme Interreg North Sea Europe, qui fait partie du Fonds europ\u00e9en de d\u00e9veloppement r\u00e9gional (FEDER), et le projet dispose de 5,4 millions d&rsquo;euros. Le projet r\u00e9unit des universit\u00e9s et des fournisseurs de technologie de propulsion \u00e9olienne avec des compagnies maritimes pour explorer, tester et valider la performance op\u00e9rationnelle de diverses solutions de propulsion \u00e9olienne. Cela vise \u00e0 permettre une p\u00e9n\u00e9tration sur le march\u00e9 de la technologie de propulsion \u00e9olienne, contribuant \u00e0 un syst\u00e8me de transport plus \u00e9cologique en mer du Nord gr\u00e2ce \u00e0 l&rsquo;exploitation du potentiel \u00e9olien consid\u00e9rable de la r\u00e9gion. Cela correspond pleinement \u00e0 l&rsquo;objectif global du programme de promouvoir le d\u00e9veloppement et l&rsquo;adoption de produits, services et processus pour acc\u00e9l\u00e9rer l&rsquo;\u00e9cologisation de la r\u00e9gion de la mer du Nord. Scandlines fait partie du projet WASP.<\/p>\n<p><strong>\u00c0 propos de Norsepower<\/strong><\/p>\n<p>Norsepower Oy Ltd est une entreprise finlandaise de technologie propre et d&rsquo;ing\u00e9nierie, ainsi que pr\u00e9curseur dans le domaine de la technologie moderne de propulsion \u00e9olienne pour l&rsquo;industrie maritime mondiale. La voile rotor de Norsepower est une technologie \u00e9conome en \u00e9nergie, test\u00e9e, n\u00e9cessitant peu d&rsquo;entretien, conviviale et fiable, qui soutient la r\u00e9duction des \u00e9missions de CO2 dans le secteur maritime.<\/p>\n<p>Depuis sa cr\u00e9ation en 2012, Norsepower a g\u00e9n\u00e9r\u00e9 plus de 20 millions d&rsquo;euros et a install\u00e9 des voiles rotors \u00e0 bord de quatre navires, y compris la derni\u00e8re installation \u00e0 bord du ferry hybride de Scandlines &lsquo;Copenhagen&rsquo;. Chaque installation a conduit \u00e0 des r\u00e9ductions significatives des co\u00fbts de carburant et des \u00e9missions, confirm\u00e9es par des \u00e9valuateurs ind\u00e9pendants tels qu&rsquo;ABB, NAPA et Lloyd&rsquo;s Register. D&rsquo;autres compagnies maritimes, affr\u00e9teurs et chantiers navals ont \u00e9t\u00e9 convaincus des avantages de la technologie de la voile rotor et travaillent \u00e0 examiner la faisabilit\u00e9 technique et \u00e9conomique de la propulsion \u00e9olienne dans leur flotte sur la base de ces r\u00e9sultats positifs.<\/p>\n<p>Photo : Scandlines \/ Matthias Tasler<\/p>\n<p><a href=\"https:\/\/www.scandlines.de\">www.scandlines.de<\/a> - <a href=\"https:\/\/www.norsepower.com\">www.norsepower.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ferry hybride &lsquo;Copenhagen&rsquo; de Scandlines navigue d\u00e9sormais avec une voile rotor de 30 m\u00e8tres de haut de Norsepower, qui devrait r\u00e9duire les \u00e9missions de CO2<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-17725","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower - Loginfo24.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower - Loginfo24.\" \/>\n<meta property=\"og:description\" content=\"Le ferry hybride &lsquo;Copenhagen&rsquo; de Scandlines navigue d\u00e9sormais avec une voile rotor de 30 m\u00e8tres de haut de Norsepower, qui devrait r\u00e9duire les \u00e9missions de CO2 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-02T05:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:28:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower\",\"datePublished\":\"2020-06-02T05:00:37+00:00\",\"dateModified\":\"2025-12-15T11:28:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/\"},\"wordCount\":1043,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/\",\"name\":\"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower - Loginfo24.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-06-02T05:00:37+00:00\",\"dateModified\":\"2025-12-15T11:28:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/2020\\\/06\\\/02\\\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#organization\",\"name\":\"Groupe Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Groupe Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower - Loginfo24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/","og_locale":"fr_FR","og_type":"article","og_title":"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower - Loginfo24.","og_description":"Le ferry hybride &lsquo;Copenhagen&rsquo; de Scandlines navigue d\u00e9sormais avec une voile rotor de 30 m\u00e8tres de haut de Norsepower, qui devrait r\u00e9duire les \u00e9missions de CO2 [\u2026]","og_url":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-06-02T05:00:37+00:00","article_modified_time":"2025-12-15T11:28:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/"},"author":{"name":"","@id":""},"headline":"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower","datePublished":"2020-06-02T05:00:37+00:00","dateModified":"2025-12-15T11:28:23+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/"},"wordCount":1043,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/","url":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/","name":"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower - Loginfo24.","isPartOf":{"@id":"https:\/\/loginfo24.com\/fr\/#website"},"datePublished":"2020-06-02T05:00:37+00:00","dateModified":"2025-12-15T11:28:23+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/fr\/2020\/06\/02\/le-ferry-hybride-de-scandlines-navigue-desormais-avec-la-voile-rotor-de-norsepower\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le ferry hybride de Scandlines navigue d\u00e9sormais avec la voile rotor de Norsepower"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/fr\/#website","url":"https:\/\/loginfo24.com\/fr\/","name":"Loginfo24","description":"Loginfo24 est la plateforme d\u00e9di\u00e9e \u00e0 la logistique et aux cha\u00eenes d&#039;approvisionnement qui fournit des informations 24 heures sur 24.","publisher":{"@id":"https:\/\/loginfo24.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/fr\/#organization","name":"Groupe Logismedia AG","url":"https:\/\/loginfo24.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Groupe Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/17725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/comments?post=17725"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/17725\/revisions"}],"predecessor-version":[{"id":31792,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/posts\/17725\/revisions\/31792"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/media?parent=17725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/categories?post=17725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/fr\/wp-json\/wp\/v2\/tags?post=17725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}