{"id":75446,"date":"2026-02-25T12:13:37","date_gmt":"2026-02-25T12:13:37","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/"},"modified":"2026-02-25T12:13:37","modified_gmt":"2026-02-25T12:13:37","slug":"dachser-y-fraunhofer-iml-premiados","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/","title":{"rendered":"Dachser y Fraunhofer IML premiados"},"content":{"rendered":"<p>Dachser y Fraunhofer IML fueron galardonados con el European Logistics Association (ELA) Award por su gemelo digital @ILO desarrollado conjuntamente. La entrega de premios tuvo lugar el 19 de febrero de 2026 en Viena. El ELA Award reconoce proyectos innovadores y logros destacados en el \u00e1mbito de la log\u00edstica y la gesti\u00f3n de la cadena de suministro, y es otorgado por una asociaci\u00f3n de asociaciones log\u00edsticas nacionales de Europa y m\u00e1s all\u00e1. Ya en 2023, @ILO recibi\u00f3 el Premio Alem\u00e1n de Log\u00edstica de la Asociaci\u00f3n Federal de Log\u00edstica (BVL).<\/p>\n<h3>Tecnolog\u00eda y aplicaci\u00f3n de @ILO<\/h3>\n<p>El gemelo digital @ILO crea una representaci\u00f3n digital automatizada de todos los paquetes, activos y procesos en el almac\u00e9n de transbordo. Esta informaci\u00f3n se muestra de manera clara a los empleados en dispositivos m\u00f3viles y pantallas, lo que aumenta la transparencia y reduce los tiempos de proceso en el almac\u00e9n. Los clientes tambi\u00e9n se benefician de la tecnolog\u00eda, ya que reciben informaci\u00f3n m\u00e1s precisa sobre sus env\u00edos. @ILO es el resultado de a\u00f1os de trabajo de investigaci\u00f3n en el Dachser Enterprise Lab, donde expertas y expertos de Dachser y investigadores de Fraunhofer IML trabajan en equipos \u00e1giles peque\u00f1os en innovaciones para la red de carga europea. Tras la introducci\u00f3n de @ILO en dos instalaciones piloto, la tecnolog\u00eda se utiliza actualmente en otras nueve ubicaciones de Dachser. Para finales de 2026, se planean hasta diez sucursales adicionales, con el objetivo de integrar a largo plazo m\u00e1s de 100 ubicaciones en la red europea de Dachser.<\/p>\n<p>\u201eEstamos muy contentos por el reconocimiento de nuestra innovaci\u00f3n en la log\u00edstica de carga. Con @ILO alcanzamos un nuevo nivel de transparencia en la cadena de suministro\u201c, dijo Stefan Hohm, Chief Development Officer (CDO) de Dachser. Subray\u00f3 que el \u201eDachser Future Terminal\u201c en combinaci\u00f3n con @ILO representa uno de los proyectos de investigaci\u00f3n m\u00e1s extensos del Dachser Enterprise Lab y es una inversi\u00f3n significativa en la digitalizaci\u00f3n de la empresa. La Prof. Dr.-Ing. Alice Kirchheim, directora del instituto en Fraunhofer IML, agreg\u00f3 que @ILO es el resultado de una colaboraci\u00f3n a largo plazo entre ambas instituciones y muestra c\u00f3mo las innovaciones desarrolladas conjuntamente pueden mejorar la vida cotidiana en la log\u00edstica.<\/p>\n<h3>Aumentos de eficiencia a trav\u00e9s de @ILO<\/h3>\n<p>La introducci\u00f3n de @ILO ha llevado a aumentos significativos en la eficiencia de los procesos entre la entrada y salida de mercanc\u00edas. En 2025, ya se hab\u00edan ahorrado m\u00e1s de cuatro millones de escaneos manuales de c\u00f3digos de barras en las once sucursales existentes de @ILO. Adem\u00e1s, se elimina la toma manual diaria de todos los paquetes en el almac\u00e9n, y las paletas pueden ser localizadas en tiempo real. Esto permite que los veh\u00edculos de transporte local comiencen m\u00e1s r\u00e1pido con la entrega de mercanc\u00edas, lo que ahorra a los conductores un tiempo valioso en el tr\u00e1fico.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/magazin.dachser.de\/digitaler-zwilling-so-funktioniert-ilo\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.dachser.at<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dachser y Fraunhofer IML fueron galardonados con el ELA Award por su Gemelo Digital @ILO, que reconoce proyectos log\u00edsticos innovadores y se entreg\u00f3 el 19 de febrero de 2026 en Viena.<\/p>\n","protected":false},"author":12,"featured_media":75443,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6657,6679,1603,1605],"tags":[11322,11323,11324,11325,11326,11327,10343,11328,11329,11330,11331,2115,2116,11332,11333,11334,11335,11336,11337,8361,3234,2123,11338,11339,11340,11341,11342,2131,11343,2134,11344,2136,2176,11345,11346,11347,11348,11349,3157,2148,11350,11351,11352,11353,11354,11355,11356,11357,2106,11358,11359,11360,11361,11362],"class_list":["post-75446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-austria","category-europa","category-personas-y-empresas","category-expedicion-y-logistica","tag-ameliorations-de-lefficacite-grace-a-la-technologie","tag-appareils-mobiles-dans-la-logistique","tag-automated-processes-in-warehouses","tag-automatisierte-ablaeufe-im-lager","tag-dachser-enterprise-lab","tag-delivery-vehicles","tag-deutsch-dachser","tag-digital-innovations-in-logistics","tag-digital-twin","tag-digitale-innovationen-in-der-logistik","tag-digitaler-zwilling","tag-digitalisierung-in-der-logistik","tag-digitalization-in-logistics","tag-efficiency-improvements-through-technology","tag-effizienzsteigerung-durch-technologie","tag-ela-award","tag-europaeisches-stueckgutnetzwerk","tag-european-freight-network","tag-forschungsprojekte-in-der-logistik","tag-fraunhofer-iml","tag-freight-logistics","tag-gestion-de-la-chaine-dapprovisionnement","tag-inbound-and-outbound-logistics","tag-innovations-numeriques-dans-la-logistique","tag-jumeau-numerique","tag-localisation-des-palettes-en-temps-reel","tag-localizing-pallets-in-real-time","tag-logistics","tag-logistics-service-providers-francais-dachser","tag-logistik","tag-logistikdienstleister-english-dachser","tag-logistique","tag-logistique-de-fret","tag-logistique-entrante-et-sortante","tag-manuelle-barcode-scans-reduzieren","tag-mobile-devices-in-logistics","tag-mobile-geraete-in-der-logistik","tag-nahverkehrsfahrzeuge","tag-numerisation-dans-la-logistique","tag-prestataires-de-services-logistiques","tag-prix-ela","tag-processus-automatises-dans-les-entrepots","tag-projets-de-recherche-en-logistique","tag-reducing-manual-barcode-scans","tag-reduction-des-scans-de-codes-barres-manuels","tag-research-projects-in-logistics","tag-reseau-de-fret-europeen","tag-stueckgutlogistik","tag-supply-chain-management","tag-transparence-dans-la-chaine-dapprovisionnement","tag-transparency-in-the-supply-chain","tag-transparenz-in-der-lieferkette","tag-vehicules-de-livraison","tag-wareneingang-und-warenausgang"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachser y Fraunhofer IML premiados - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachser y Fraunhofer IML premiados - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Dachser y Fraunhofer IML fueron galardonados con el ELA Award por su Gemelo Digital @ILO, que reconoce proyectos log\u00edsticos innovadores y se entreg\u00f3 el 19 de febrero de 2026 en Viena.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T12:13:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2047\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Dachser y Fraunhofer IML premiados\",\"datePublished\":\"2026-02-25T12:13:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/\"},\"wordCount\":518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg\",\"keywords\":[\"am\u00e9liorations de l'efficacit\u00e9 gr\u00e2ce \u00e0 la technologie\",\"appareils mobiles dans la logistique\",\"automated processes in warehouses\",\"automatisierte Abl\u00e4ufe im Lager\",\"Dachser Enterprise Lab\",\"delivery vehicles\",\"Deutsch DACHSER\",\"digital innovations in logistics\",\"digital twin\",\"digitale Innovationen in der Logistik\",\"Digitaler Zwilling\",\"Digitalisierung in der Logistik\",\"digitalization in logistics\",\"efficiency improvements through technology\",\"Effizienzsteigerung durch Technologie\",\"ELA Award\",\"europ\u00e4isches St\u00fcckgutnetzwerk\",\"European freight network\",\"Forschungsprojekte in der Logistik\",\"Fraunhofer IML\",\"freight logistics\",\"gestion de la cha\u00eene d'approvisionnement\",\"inbound and outbound logistics\",\"innovations num\u00e9riques dans la logistique\",\"jumeau num\u00e9rique\",\"localisation des palettes en temps r\u00e9el\",\"localizing pallets in real-time\",\"logistics\",\"logistics service providers Fran\u00e7ais Dachser\",\"Logistik\",\"Logistikdienstleister English Dachser\",\"logistique\",\"logistique de fret\",\"logistique entrante et sortante\",\"manuelle Barcode-Scans reduzieren\",\"mobile devices in logistics\",\"mobile Ger\u00e4te in der Logistik\",\"Nahverkehrsfahrzeuge\",\"num\u00e9risation dans la logistique\",\"prestataires de services logistiques\",\"prix ELA\",\"processus automatis\u00e9s dans les entrep\u00f4ts\",\"projets de recherche en logistique\",\"reducing manual barcode scans\",\"r\u00e9duction des scans de codes-barres manuels\",\"research projects in logistics\",\"r\u00e9seau de fret europ\u00e9en\",\"St\u00fcckgutlogistik\",\"Supply Chain Management\",\"transparence dans la cha\u00eene d'approvisionnement\",\"transparency in the supply chain\",\"Transparenz in der Lieferkette\",\"v\u00e9hicules de livraison\",\"Wareneingang und Warenausgang\"],\"articleSection\":[\"Austria\",\"Europa\",\"Personas y empresas\",\"Transporte de mercanc\u00edas y log\u00edstica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/\",\"name\":\"Dachser y Fraunhofer IML premiados - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg\",\"datePublished\":\"2026-02-25T12:13:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg\",\"width\":2047,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/25\\\/dachser-y-fraunhofer-iml-premiados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dachser y Fraunhofer IML premiados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dachser y Fraunhofer IML premiados - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/","og_locale":"es_ES","og_type":"article","og_title":"Dachser y Fraunhofer IML premiados - Loginfo24","og_description":"Dachser y Fraunhofer IML fueron galardonados con el ELA Award por su Gemelo Digital @ILO, que reconoce proyectos log\u00edsticos innovadores y se entreg\u00f3 el 19 de febrero de 2026 en Viena.","og_url":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-02-25T12:13:37+00:00","og_image":[{"width":2047,"height":1152,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg","type":"image\/jpeg"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andreas Haug","Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Dachser y Fraunhofer IML premiados","datePublished":"2026-02-25T12:13:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/"},"wordCount":518,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg","keywords":["am\u00e9liorations de l'efficacit\u00e9 gr\u00e2ce \u00e0 la technologie","appareils mobiles dans la logistique","automated processes in warehouses","automatisierte Abl\u00e4ufe im Lager","Dachser Enterprise Lab","delivery vehicles","Deutsch DACHSER","digital innovations in logistics","digital twin","digitale Innovationen in der Logistik","Digitaler Zwilling","Digitalisierung in der Logistik","digitalization in logistics","efficiency improvements through technology","Effizienzsteigerung durch Technologie","ELA Award","europ\u00e4isches St\u00fcckgutnetzwerk","European freight network","Forschungsprojekte in der Logistik","Fraunhofer IML","freight logistics","gestion de la cha\u00eene d'approvisionnement","inbound and outbound logistics","innovations num\u00e9riques dans la logistique","jumeau num\u00e9rique","localisation des palettes en temps r\u00e9el","localizing pallets in real-time","logistics","logistics service providers Fran\u00e7ais Dachser","Logistik","Logistikdienstleister English Dachser","logistique","logistique de fret","logistique entrante et sortante","manuelle Barcode-Scans reduzieren","mobile devices in logistics","mobile Ger\u00e4te in der Logistik","Nahverkehrsfahrzeuge","num\u00e9risation dans la logistique","prestataires de services logistiques","prix ELA","processus automatis\u00e9s dans les entrep\u00f4ts","projets de recherche en logistique","reducing manual barcode scans","r\u00e9duction des scans de codes-barres manuels","research projects in logistics","r\u00e9seau de fret europ\u00e9en","St\u00fcckgutlogistik","Supply Chain Management","transparence dans la cha\u00eene d'approvisionnement","transparency in the supply chain","Transparenz in der Lieferkette","v\u00e9hicules de livraison","Wareneingang und Warenausgang"],"articleSection":["Austria","Europa","Personas y empresas","Transporte de mercanc\u00edas y log\u00edstica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/","url":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/","name":"Dachser y Fraunhofer IML premiados - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg","datePublished":"2026-02-25T12:13:37+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/Verleihung-ELA-Award-Dachser-und-Fraunhofer-IML.jpg","width":2047,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/25\/dachser-y-fraunhofer-iml-premiados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dachser y Fraunhofer IML premiados"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/loginfo24.com\/es\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/75446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=75446"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/75446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/75443"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=75446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=75446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=75446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}