{"id":74573,"date":"2026-02-03T10:21:21","date_gmt":"2026-02-03T09:21:21","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/"},"modified":"2026-02-03T10:21:21","modified_gmt":"2026-02-03T10:21:21","slug":"rheincargo-asume-el-transporte-de-cal","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/","title":{"rendered":"RheinCargo asume el transporte de cal"},"content":{"rendered":"<p>RheinCargo ha llegado a un acuerdo a largo plazo con thyssenkrupp Steel para hacerse cargo del transporte de cal de la empresa SCHAEFER KALK en Kerkerbach a la planta de thyssenkrupp Steel en Duisburg-Nord. Esta colaboraci\u00f3n comenz\u00f3 a principios de a\u00f1o y prev\u00e9 un volumen de transporte anual de aproximadamente 75,000 toneladas de cal. Para manejar esta cantidad, se utilizar\u00e1n dos recorridos de trenes de pendulaci\u00f3n por semana, cada uno con doce vagones de carga, seg\u00fan informa RheinCargo.<\/p>\n<h3>Transporte mediante tecnolog\u00eda h\u00edbrida<\/h3>\n<p>Para los transportes de cal, RheinCargo utiliza una locomotora h\u00edbrida del tipo &#8222;Vectron Dual Mode&#8220; de Siemens. Esta locomotora permite alcanzar la l\u00ednea no electrificada hacia Kerkerbach y realizar las maniobras all\u00ed sin una locomotora de maniobra. Seg\u00fan la empresa, el motor di\u00e9sel se utiliza solo en la primera y \u00faltima milla, mientras que el recorrido principal se realiza bajo tracci\u00f3n el\u00e9ctrica. Este enfoque ayuda a evitar viajes en vac\u00edo y garantiza un transporte de bajas emisiones, seg\u00fan informa RheinCargo.<\/p>\n<p>Adem\u00e1s, RheinCargo enfrenta un desaf\u00edo en el marco del proyecto de construcci\u00f3n &#8222;Rehabilitaci\u00f3n general del r\u00edo derecho&#8220;, que se lleva a cabo entre Troisdorf y Wiesbaden. A partir de julio de 2026, una parte de la l\u00ednea entre Kerkerbach y Duisburg-Nord estar\u00e1 cerrada durante varios meses. Para garantizar el suministro durante este tiempo, RheinCargo planea utilizar conexiones alternativas a trav\u00e9s de las l\u00edneas del lado izquierdo del Rin o la zona de Lahn-Dill.<\/p>\n<p><a href=\"https:\/\/rheincargo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.rheincargo.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RheinCargo ha llegado a un acuerdo con thyssenkrupp Steel para el transporte de cal y planea rutas alternativas durante el cierre de la l\u00ednea a partir de julio de 2026.<\/p>\n","protected":false},"author":10,"featured_media":74570,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6655,6679,1604],"tags":[8834,8835,8836,7632,8837,8838,8839,8840,8841,8842,8843,8844,8845,8846,2125,4166,4167,8847,8848,8849,8850,8851,8852,2431,2622,8853,8854,1800,8855,8856,4178,2193,8857,8858,8859,1916,8860,8861,2641,8862,8863,8864,8865,3125,2155,2449,2450,1837,8866,8867],"class_list":["post-74573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alemania","category-europa","category-intermodal-carretera","tag-alternative-routes","tag-alternative-verbindungen","tag-cycles-de-train-navette","tag-deutsch-rheincargo","tag-diesel-drive","tag-dieselantrieb","tag-duisburg-nord","tag-emissionsarmer-transport","tag-empty-train-runs-francais-rheincargo","tag-freight-cars","tag-generalsanierung-rechter-rhein","tag-gueterwagen","tag-hybrid-locomotive","tag-hybridlokomotive","tag-industrie-du-transport","tag-infrastructure-projects","tag-infrastrukturprojekte","tag-itineraires-alternatifs","tag-kalktransporte","tag-kerkerbach","tag-leerlokfahrten-english-rheincargo","tag-lime-transport","tag-locomotive-hybride","tag-logistique-de-transport","tag-logistique-durable","tag-low-emission-transport","tag-moteur-diesel","tag-nachhaltige-logistik","tag-operations-de-manoeuvre","tag-pendelzug-rundlaeufe","tag-projets-dinfrastructure","tag-rail-freight-transport","tag-rangierarbeiten","tag-renovation-de-la-rive-droite-du-rhin","tag-right-rhine-renovation","tag-schienengueterverkehr","tag-shunting-operations","tag-shuttle-train-cycles","tag-sustainable-logistics","tag-thyssenkrupp-steel","tag-trajets-de-train-vides","tag-transport-a-faibles-emissions","tag-transport-de-chaux","tag-transport-ferroviaire-de-marchandises","tag-transport-industry","tag-transport-logistics","tag-transportlogistik","tag-transportwirtschaft","tag-vectron-dual-mode","tag-wagons-de-marchandises"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RheinCargo asume el transporte de cal - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RheinCargo asume el transporte de cal - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"RheinCargo ha llegado a un acuerdo con thyssenkrupp Steel para el transporte de cal y planea rutas alternativas durante el cierre de la l\u00ednea a partir de julio de 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T09:21:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T10:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeremy Soland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Soland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/\"},\"author\":{\"name\":\"Jeremy Soland\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\"},\"headline\":\"RheinCargo asume el transporte de cal\",\"datePublished\":\"2026-02-03T09:21:21+00:00\",\"dateModified\":\"2026-02-03T10:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/\"},\"wordCount\":265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"keywords\":[\"alternative routes\",\"alternative Verbindungen\",\"cycles de train navette\",\"Deutsch RheinCargo\",\"diesel drive\",\"Dieselantrieb\",\"Duisburg-Nord\",\"emissionsarmer Transport\",\"empty train runs Fran\u00e7ais RheinCargo\",\"freight cars\",\"Generalsanierung rechter Rhein\",\"G\u00fcterwagen\",\"hybrid locomotive\",\"Hybridlokomotive\",\"industrie du transport\",\"infrastructure projects\",\"Infrastrukturprojekte\",\"itin\u00e9raires alternatifs\",\"Kalktransporte\",\"Kerkerbach\",\"Leerlokfahrten English RheinCargo\",\"lime transport\",\"locomotive hybride\",\"logistique de transport\",\"logistique durable\",\"low-emission transport\",\"moteur diesel\",\"nachhaltige Logistik\",\"op\u00e9rations de man\u0153uvre\",\"Pendelzug-Rundl\u00e4ufe\",\"projets d'infrastructure\",\"rail freight transport\",\"Rangierarbeiten\",\"r\u00e9novation de la rive droite du Rhin\",\"right Rhine renovation\",\"Schieneng\u00fcterverkehr\",\"shunting operations\",\"shuttle train cycles\",\"sustainable logistics\",\"thyssenkrupp Steel\",\"trajets de train vides\",\"transport \u00e0 faibles \u00e9missions\",\"transport de chaux\",\"transport ferroviaire de marchandises\",\"transport industry\",\"transport logistics\",\"Transportlogistik\",\"Transportwirtschaft\",\"Vectron Dual Mode\",\"wagons de marchandises\"],\"articleSection\":[\"Alemania\",\"Europa\",\"Intermodal \\\/ Carretera\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/\",\"name\":\"RheinCargo asume el transporte de cal - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"datePublished\":\"2026-02-03T09:21:21+00:00\",\"dateModified\":\"2026-02-03T10:21:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2026\\\/02\\\/03\\\/rheincargo-asume-el-transporte-de-cal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RheinCargo asume el transporte de cal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\",\"name\":\"Jeremy Soland\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/author\\\/jeremy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RheinCargo asume el transporte de cal - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/","og_locale":"es_ES","og_type":"article","og_title":"RheinCargo asume el transporte de cal - Loginfo24","og_description":"RheinCargo ha llegado a un acuerdo con thyssenkrupp Steel para el transporte de cal y planea rutas alternativas durante el cierre de la l\u00ednea a partir de julio de 2026.","og_url":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-02-03T09:21:21+00:00","article_modified_time":"2026-02-03T10:21:21+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg","type":"image\/jpeg"}],"author":"Jeremy Soland","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jeremy Soland","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/"},"author":{"name":"Jeremy Soland","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa"},"headline":"RheinCargo asume el transporte de cal","datePublished":"2026-02-03T09:21:21+00:00","dateModified":"2026-02-03T10:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/"},"wordCount":265,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg","keywords":["alternative routes","alternative Verbindungen","cycles de train navette","Deutsch RheinCargo","diesel drive","Dieselantrieb","Duisburg-Nord","emissionsarmer Transport","empty train runs Fran\u00e7ais RheinCargo","freight cars","Generalsanierung rechter Rhein","G\u00fcterwagen","hybrid locomotive","Hybridlokomotive","industrie du transport","infrastructure projects","Infrastrukturprojekte","itin\u00e9raires alternatifs","Kalktransporte","Kerkerbach","Leerlokfahrten English RheinCargo","lime transport","locomotive hybride","logistique de transport","logistique durable","low-emission transport","moteur diesel","nachhaltige Logistik","op\u00e9rations de man\u0153uvre","Pendelzug-Rundl\u00e4ufe","projets d'infrastructure","rail freight transport","Rangierarbeiten","r\u00e9novation de la rive droite du Rhin","right Rhine renovation","Schieneng\u00fcterverkehr","shunting operations","shuttle train cycles","sustainable logistics","thyssenkrupp Steel","trajets de train vides","transport \u00e0 faibles \u00e9missions","transport de chaux","transport ferroviaire de marchandises","transport industry","transport logistics","Transportlogistik","Transportwirtschaft","Vectron Dual Mode","wagons de marchandises"],"articleSection":["Alemania","Europa","Intermodal \/ Carretera"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/","url":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/","name":"RheinCargo asume el transporte de cal - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg","datePublished":"2026-02-03T09:21:21+00:00","dateModified":"2026-02-03T10:21:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/2026_02_03_RC_Kerkerbach_tk-scaled-aspect-ratio-1400-788-scaled-1.jpg","width":2560,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2026\/02\/03\/rheincargo-asume-el-transporte-de-cal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"RheinCargo asume el transporte de cal"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa","name":"Jeremy Soland","url":"https:\/\/loginfo24.com\/es\/author\/jeremy\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/74573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=74573"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/74573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/74570"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=74573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=74573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=74573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}