{"id":69731,"date":"2025-07-04T16:51:14","date_gmt":"2025-07-04T14:51:14","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/"},"modified":"2025-07-04T16:51:14","modified_gmt":"2025-07-04T14:51:14","slug":"el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/","title":{"rendered":"El grupo L.I.T. adquiere dataform dialogservices GmbH"},"content":{"rendered":"<h5><strong><span style=\"font-family: 'Arial',sans-serif\">A partir del 1 de agosto de 2025, la dataform dialogservices GmbH, con sede en Ro\u00dftal cerca de N\u00faremberg, formar\u00e1 parte del grupo L.I.T. La adquisici\u00f3n se realiza a partir de un procedimiento de insolvencia provisional. Con esta compra, el proveedor de servicios log\u00edsticos ampl\u00eda su cartera con servicios en las \u00e1reas de marketing de di\u00e1logo, cumplimiento de comercio electr\u00f3nico, as\u00ed como gesti\u00f3n de impresi\u00f3n y salida digitalmente apoyada. La ubicaci\u00f3n se mantendr\u00e1 y todos los 230 empleados continuar\u00e1n empleados.<\/span><\/strong><\/h5>\n<p><span style=\"font-family: 'Arial',sans-serif\">(Brake\/Rosstal) De este modo, el grupo L.I.T. establece un hito importante para la expansi\u00f3n dirigida de su competencia en cumplimiento y comercio electr\u00f3nico, y abre nuevas oportunidades de mercado en marketing de di\u00e1logo e impresi\u00f3n digital.<\/span><\/p>\n<p><span style=\"font-family: 'Arial',sans-serif\">\u201cCon dataform, ganamos una empresa con alta especializaci\u00f3n t\u00e9cnica en el \u00e1rea de cumplimiento, procesos de impresi\u00f3n y env\u00edo digital, as\u00ed como servicios de di\u00e1logo integrados en el sistema\u201d, dice Claas Durach, futuro director general de dataform dialog solutions GmbH. La empresa se caracteriza por un setup t\u00e9cnicamente maduro, procesos automatizados, acceso a diversos nuevos segmentos de clientes y, por lo tanto, forma una excelente base para fortalecer de manera espec\u00edfica la cartera de servicios a lo largo de toda la cadena de valor. Durach destaca que incluso durante la fase de insolvencia provisional se pudieron ganar nuevos clientes y pedidos, lo que subraya la posici\u00f3n en el mercado y la capacidad de rendimiento de dataform.<\/span><\/p>\n<h5><strong><span style=\"font-family: 'Arial',sans-serif\">Expansi\u00f3n estrat\u00e9gica en el \u00e1rea de cumplimiento y comunicaci\u00f3n<\/span><\/strong><\/h5>\n<p><span style=\"font-family: 'Arial',sans-serif\">dataform cuenta con una moderna infraestructura log\u00edstica de aproximadamente 45,000 metros cuadrados de espacio de almacenamiento y producci\u00f3n, log\u00edstica intralog\u00edstica automatizada con 18 estaciones de preparaci\u00f3n de pedidos, alrededor de 30,000 espacios para palets y 90,000 espacios de estanter\u00edas. La empresa ofrece servicios a lo largo de toda la cadena de valor del comercio electr\u00f3nico: desde la recepci\u00f3n de mercanc\u00edas, procesamiento de pedidos, confecci\u00f3n, gesti\u00f3n de env\u00edos hasta el manejo de devoluciones. La oferta de cumplimiento se complementa con una amplia cartera de servicios orientados al di\u00e1logo, como env\u00edos personalizados, impresi\u00f3n digital, producci\u00f3n de cat\u00e1logos, gesti\u00f3n de franqueo y soluciones de env\u00edo h\u00edbridas. Para clientes comerciales, dataform tambi\u00e9n se encarga de toda la gesti\u00f3n de salida de facturas, confirmaciones de pedidos, otros documentos comerciales y servicios de atenci\u00f3n al cliente.<\/span><\/p>\n<h5><strong><span style=\"font-family: 'Arial',sans-serif\">Integraci\u00f3n en el grupo y perspectivas<\/span><\/strong><\/h5>\n<p><span style=\"font-family: 'Arial',sans-serif\">La dataform dialog solutions GmbH continuar\u00e1 operando la actividad comercial anterior de dataform dialogservices GmbH como una empresa operativamente independiente dentro del grupo L.I.T. La adquisici\u00f3n permite la interconexi\u00f3n de procesos log\u00edsticos existentes con los servicios de comunicaci\u00f3n digital de la nueva filial. Con esta adquisici\u00f3n, el grupo L.I.T. tambi\u00e9n fortalece su posici\u00f3n en el mercado en el sur de Alemania.<\/span><\/p>\n<p><span style=\"font-family: 'Arial',sans-serif\">Klaus Vollmer, futuro miembro de la direcci\u00f3n de dataform dialog solutions GmbH, se muestra entusiasmado por la nueva perspectiva dentro del grupo L.I.T.: \u201cNuestra ubicaci\u00f3n, nuestros sistemas y la experiencia de nuestro equipo son un buen complemento para las estructuras existentes. Juntos, en el marco de la nueva pertenencia al grupo, implementaremos servicios adicionales.\u201d<\/span><\/p>\n<p><span style=\"font-family: 'Arial',sans-serif\">Para abordar de manera espec\u00edfica el creciente mercado de comercio electr\u00f3nico, el grupo L.I.T. tambi\u00e9n planea fundar una nueva empresa: L.I.T. eCommerce Solutions GmbH. Durach a\u00f1ade: \u201cA trav\u00e9s de la creaci\u00f3n de una empresa propia de comercio electr\u00f3nico, continuamos desarrollando nuestras fortalezas existentes dentro del grupo L.I.T. y creamos nuevos valores para nuestros clientes en el comercio digital.\u201d<\/span><\/p>\n<p>Foto: \u00a9 datalog dialogservices<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 1 de agosto de 2025, la dataform dialogservices GmbH, con sede en Ro\u00dftal cerca de N\u00faremberg, formar\u00e1 parte del grupo L.I.T. La adquisici\u00f3n<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-69731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El grupo L.I.T. adquiere dataform dialogservices GmbH - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El grupo L.I.T. adquiere dataform dialogservices GmbH - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A partir del 1 de agosto de 2025, la dataform dialogservices GmbH, con sede en Ro\u00dftal cerca de N\u00faremberg, formar\u00e1 parte del grupo L.I.T. La adquisici\u00f3n [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T14:51:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/L.I.T._4.7.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El grupo L.I.T. adquiere dataform dialogservices GmbH\",\"datePublished\":\"2025-07-04T14:51:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/\"},\"wordCount\":638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/L.I.T._4.7.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/\",\"name\":\"El grupo L.I.T. adquiere dataform dialogservices GmbH - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/L.I.T._4.7.25.jpg\",\"datePublished\":\"2025-07-04T14:51:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/L.I.T._4.7.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/L.I.T._4.7.25.jpg\",\"width\":1240,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/07\\\/04\\\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El grupo L.I.T. adquiere dataform dialogservices GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El grupo L.I.T. adquiere dataform dialogservices GmbH - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/","og_locale":"es_ES","og_type":"article","og_title":"El grupo L.I.T. adquiere dataform dialogservices GmbH - Loginfo24","og_description":"A partir del 1 de agosto de 2025, la dataform dialogservices GmbH, con sede en Ro\u00dftal cerca de N\u00faremberg, formar\u00e1 parte del grupo L.I.T. La adquisici\u00f3n [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-07-04T14:51:14+00:00","og_image":[{"width":1240,"height":749,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/L.I.T._4.7.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/"},"author":{"name":"","@id":""},"headline":"El grupo L.I.T. adquiere dataform dialogservices GmbH","datePublished":"2025-07-04T14:51:14+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/"},"wordCount":638,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/L.I.T._4.7.25.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/","url":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/","name":"El grupo L.I.T. adquiere dataform dialogservices GmbH - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/L.I.T._4.7.25.jpg","datePublished":"2025-07-04T14:51:14+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/L.I.T._4.7.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/L.I.T._4.7.25.jpg","width":1240,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2025\/07\/04\/el-grupo-l-i-t-adquiere-dataform-dialogservices-gmbh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"El grupo L.I.T. adquiere dataform dialogservices GmbH"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/69731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=69731"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/69731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/4801"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=69731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=69731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=69731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}