{"id":69320,"date":"2025-05-28T19:49:21","date_gmt":"2025-05-28T17:49:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/"},"modified":"2025-05-28T19:49:21","modified_gmt":"2025-05-28T17:49:21","slug":"g-englmayer-se-une-a-cargoboard-austria","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/","title":{"rendered":"G. Englmayer se une a Cargoboard Austria"},"content":{"rendered":"<h5><strong>Cargoboard y la tradicional empresa de transporte austriaca G. Englmayer unen fuerzas: G. Englmayer se une a Cargoboard Austria a partir del 1 de junio de 2025. El objetivo del acuerdo es expandir de manera espec\u00edfica la posici\u00f3n de mercado conjunta en Austria y mejorar a\u00fan m\u00e1s la calidad del servicio.<\/strong><\/h5>\n<p>(Paderborn\/Wels) Englmayer no solo aporta d\u00e9cadas de experiencia, sino tambi\u00e9n una red de transporte nacional propia y una fuerte presencia en el mercado de Europa del Este, creando as\u00ed las condiciones ideales para combinar la innovaci\u00f3n digital y la excelencia operativa con esta asociaci\u00f3n estrat\u00e9gica. A partir del pr\u00f3ximo mes, todo el negocio en Austria de la empresa de transporte digital se gestionar\u00e1 a trav\u00e9s de la nueva sociedad. La direcci\u00f3n de Cargoboard Austria estar\u00e1 a cargo de Lukas Petrasch, CEO de Cargoboard, Daniel Grobbel, apoderado de Cargoboard Austria, y Josef Sch\u00f6llhuber, apoderado de G. Englmayer.<\/p>\n<p>Austria ocupa el segundo lugar en los mercados m\u00e1s rentables para Cargoboard, detr\u00e1s de la Rep\u00fablica Federal. La participaci\u00f3n de G. Englmayer en la plataforma de transporte digital demuestra el impacto que los modelos de negocio innovadores pueden tener en empresas tradicionales establecidas para el crecimiento empresarial. Los socios esbozan los efectos de sinergia previstos de la siguiente manera: G. Englmayer se posiciona de manera segura para el futuro en el entorno digital y Cargoboard asegura calidad operativa, combinada con fuerza regional.<\/p>\n<h5><strong>Alianza estrat\u00e9gica para el mercado austriaco<\/strong><\/h5>\n<p>\u00abHemos fundado Cargoboard Austria de manera consciente y temprana para crear una base s\u00f3lida para una fuerte asociaci\u00f3n. Con G. Englmayer tenemos el socio adecuado a nuestro lado para expandir nuestra posici\u00f3n en el mercado de manera sostenible\u00bb, dice Lukas Petrasch.<\/p>\n<p>Josef Sch\u00f6llhuber tambi\u00e9n ve un gran potencial: \u00abCargoboard aporta su plataforma digital, que cambiar\u00e1 de manera sostenible el mercado de transporte. Nosotros aportamos el conocimiento del mercado local y la excelencia operativa. As\u00ed se crea una situaci\u00f3n de ganar-ganar.\u00bb<\/p>\n<p>Cargoboard ha demostrado desde su fundaci\u00f3n en Alemania c\u00f3mo funciona la digitalizaci\u00f3n en la log\u00edstica: una plataforma intuitiva, procesos \u00e1giles y socios fuertes como la red Cargoline. Este concepto viable se adaptar\u00e1 ahora de manera adecuada para Austria.<\/p>\n<h5><strong>Oferta de transporte notablemente mejorada<\/strong><\/h5>\n<p>La gesti\u00f3n a trav\u00e9s de una empresa austriaca simplifica los procesos, acorta las distancias y aporta claridad legal. Al mismo tiempo, la oferta de transporte para el pa\u00eds alpino \u2013 ya sea en importaci\u00f3n o exportaci\u00f3n \u2013 se mejora notablemente. Gracias a la estrecha interconexi\u00f3n entre la plataforma digital y la competencia log\u00edstica local, los clientes se benefician de tiempos de entrega r\u00e1pidos y procesos m\u00e1s fluidos en el transporte de mercanc\u00edas.<\/p>\n<p>Foto: \u00a9 G. Englmayer \/ <strong><em>Pie de foto<\/em><\/strong><em> (de izq. a der.): Andreas Gaber (CEO de G. Englmayer), Mag. Klaus K\u00f6glberger (miembro del consejo de la fundaci\u00f3n), Mag. Alexander P\u00f6ttinger (CFO de G. Englmayer), Robert Breitwieser (COO de G. Englmayer), Daniel Grobbel (apoderado de Cargoboard Austria), Dr. Gernot Fellner (notario y miembro del consejo de la fundaci\u00f3n), Lukas Petrasch<\/em> (CEO de Cargoboard) y Josef Sch\u00f6llhuber (apoderado de G. Englmayer)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cargoboard y la tradicional empresa de transporte austriaca G. Englmayer unen fuerzas: G. Englmayer se une a Cargoboard Austria a partir del 1 de junio de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-69320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G. Englmayer se une a Cargoboard Austria - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G. Englmayer se une a Cargoboard Austria - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Cargoboard y la tradicional empresa de transporte austriaca G. Englmayer unen fuerzas: G. Englmayer se une a Cargoboard Austria a partir del 1 de junio de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T17:49:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"G. Englmayer se une a Cargoboard Austria\",\"datePublished\":\"2025-05-28T17:49:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/\"},\"wordCount\":544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"articleSection\":[\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/\",\"name\":\"G. Englmayer se une a Cargoboard Austria - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"datePublished\":\"2025-05-28T17:49:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"width\":2560,\"height\":2110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/05\\\/28\\\/g-englmayer-se-une-a-cargoboard-austria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G. Englmayer se une a Cargoboard Austria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G. Englmayer se une a Cargoboard Austria - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/","og_locale":"es_ES","og_type":"article","og_title":"G. Englmayer se une a Cargoboard Austria - Loginfo24","og_description":"Cargoboard y la tradicional empresa de transporte austriaca G. Englmayer unen fuerzas: G. Englmayer se une a Cargoboard Austria a partir del 1 de junio de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-05-28T17:49:21+00:00","og_image":[{"width":2560,"height":2110,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/"},"author":{"name":"","@id":""},"headline":"G. Englmayer se une a Cargoboard Austria","datePublished":"2025-05-28T17:49:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/"},"wordCount":544,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","articleSection":["Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/","url":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/","name":"G. Englmayer se une a Cargoboard Austria - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","datePublished":"2025-05-28T17:49:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","width":2560,"height":2110},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2025\/05\/28\/g-englmayer-se-une-a-cargoboard-austria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"G. Englmayer se une a Cargoboard Austria"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/69320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=69320"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/69320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/4951"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=69320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=69320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=69320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}