{"id":68822,"date":"2025-04-15T15:18:18","date_gmt":"2025-04-15T13:18:18","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/"},"modified":"2025-04-15T15:18:18","modified_gmt":"2025-04-15T13:18:18","slug":"lpr-la-palette-rouge-renueva-la-certificacion-pefc","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/","title":{"rendered":"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC"},"content":{"rendered":"<h5><strong>LPR - La Palette Rouge<\/strong><strong>, <\/strong><strong>una divisi\u00f3n del Euro Pool Group y especialista en pooling de palets en el comercio minorista y FMCG, se complace en anunciar la exitosa renovaci\u00f3n de su certificaci\u00f3n PEFC para los pr\u00f3ximos cinco a\u00f1os. Esto confirma su compromiso continuo con la gesti\u00f3n forestal sostenible.<\/strong><\/h5>\n<p>(Rijswijk) La certificaci\u00f3n fue adquirida originalmente en 2010 y es v\u00e1lida para todas las filiales del grupo. La auditor\u00eda para la extensi\u00f3n en 2025 se llev\u00f3 a cabo en varias ubicaciones, incluidas los pa\u00edses Benelux, Portugal, Polonia y la sede de LPR en Toulouse, y ha confirmado que la divisi\u00f3n LPR cumple completamente con los requisitos de PEFC sin desviaciones.<\/p>\n<p>La certificaci\u00f3n garantiza de manera independiente y verificable que la madera utilizada para la fabricaci\u00f3n de los palets LPR proviene exclusivamente de bosques gestionados de manera sostenible, sin ning\u00fan v\u00ednculo con la deforestaci\u00f3n o el da\u00f1o forestal.<\/p>\n<p>Sobre las exigencias: un comportamiento responsable reforzado<br \/>\nEn l\u00ednea con su compromiso con una log\u00edstica m\u00e1s sostenible, LPR - La Palette Rouge va un paso m\u00e1s all\u00e1 al abastecerse exclusivamente de madera de bosques europeos. Esto garantiza la trazabilidad y una menor huella de CO\u2082. Adem\u00e1s, el 100 % de los fabricantes y proveedores de la empresa est\u00e1n certificados por PEFC, FSC o incluso con doble certificaci\u00f3n, lo que es un signo de una pol\u00edtica de compras exigente y responsable.<\/p>\n<h5>Reconocimiento por un compromiso a largo plazo<\/h5>\n<p>\u00abLa certificaci\u00f3n es un reconocimiento de nuestro compromiso a largo plazo con una log\u00edstica m\u00e1s sostenible. Continuaremos innovando y mejorando nuestro enfoque para acompa\u00f1ar a nuestros clientes en su camino hacia soluciones cada vez m\u00e1s responsables,\u00bb enfatiza Jean-Luc Guenard, director general de LPR.<\/p>\n<p>Foto: \u00a9 LPR - La Palette Rouge<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LPR - La Palette Rouge, una divisi\u00f3n del Euro Pool Group y especialista en pooling de palets en el comercio minorista y FMCG, se complace en<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-68822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"LPR - La Palette Rouge, una divisi\u00f3n del Euro Pool Group y especialista en pooling de palets en el comercio minorista y FMCG, se complace en [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-15T13:18:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LPR_15.4.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1249\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC\",\"datePublished\":\"2025-04-15T13:18:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/\"},\"wordCount\":319,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LPR_15.4.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/\",\"name\":\"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LPR_15.4.25.jpg\",\"datePublished\":\"2025-04-15T13:18:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LPR_15.4.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LPR_15.4.25.jpg\",\"width\":1249,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/04\\\/15\\\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LPR &#8211; La Palette Rouge renueva la certificaci\u00f3n PEFC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/","og_locale":"es_ES","og_type":"article","og_title":"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC - Loginfo24","og_description":"LPR - La Palette Rouge, una divisi\u00f3n del Euro Pool Group y especialista en pooling de palets en el comercio minorista y FMCG, se complace en [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-04-15T13:18:18+00:00","og_image":[{"width":1249,"height":725,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LPR_15.4.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/"},"author":{"name":"","@id":""},"headline":"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC","datePublished":"2025-04-15T13:18:18+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/"},"wordCount":319,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LPR_15.4.25.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/","url":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/","name":"LPR - La Palette Rouge renueva la certificaci\u00f3n PEFC - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LPR_15.4.25.jpg","datePublished":"2025-04-15T13:18:18+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LPR_15.4.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LPR_15.4.25.jpg","width":1249,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2025\/04\/15\/lpr-la-palette-rouge-renueva-la-certificacion-pefc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"LPR &#8211; La Palette Rouge renueva la certificaci\u00f3n PEFC"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/68822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=68822"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/68822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/5138"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=68822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=68822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=68822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}