{"id":68559,"date":"2025-03-21T18:53:50","date_gmt":"2025-03-21T17:53:50","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/"},"modified":"2025-03-21T18:53:50","modified_gmt":"2025-03-21T17:53:50","slug":"schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/","title":{"rendered":"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania"},"content":{"rendered":"<h5>Schmitz Cargobull ha entregado seis remolques ligeros curtainsider ecoCHAMP LTO de BERGERecotrail\u00ae a PepsiCo Alemania. En los nuevos veh\u00edculos, la distancia entre ejes se ha acortado para maximizar la carga \u00fatil sin sobrecargar el eje motriz del tractor. Esto es especialmente importante cuando los remolques est\u00e1n en uso con tractores el\u00e9ctricos o con carga completa.<\/h5>\n<p>(Horstmar\/Neu-Isenburg) La entrega oficial de veh\u00edculos tuvo lugar en febrero de 2025 en la sucursal de Rodgau\/Alemania, en presencia de Adrian Burlacu, especialista en transporte de PepsiCo, y J\u00f6rg Irsfeld, director de gesti\u00f3n de cuentas clave internacional de Schmitz Cargobull. Adem\u00e1s, PepsiCo ha puesto en operaci\u00f3n otros seis veh\u00edculos ligeros BERGERecotrail\u00ae en combinaci\u00f3n con camiones el\u00e9ctricos a trav\u00e9s de un arrendador. Los remolques ligeros de la marca BERGERecotrail\u00ae son especialmente adecuados para el transporte de bebidas gracias a su alta capacidad de carga \u00fatil.<\/p>\n<p>\u00abEstamos encantados de ampliar nuestra flota con los ligeros ecoCHAMP LTO de Berger. Ofrecen la m\u00e1xima carga \u00fatil posible y nos ayudan a reducir las emisiones de CO2 en nuestra flota. La innovadora construcci\u00f3n ligera y las ventajas que la distancia entre ejes acortada ofrece tambi\u00e9n en relaci\u00f3n con la transformaci\u00f3n de los motores de camiones cumplen perfectamente con nuestros requisitos de soluciones de transporte eficientes y sostenibles\u00bb, dice Adrian Burlacu.<\/p>\n<p>\u00abEl ecoCHAMP LTO es un ejemplo destacado de la capacidad de innovaci\u00f3n y el know-how t\u00e9cnico de la marca BERGERecotrail\u00ae en el \u00e1rea de construcci\u00f3n ligera. Estos veh\u00edculos establecen nuevos est\u00e1ndares en t\u00e9rminos de eficiencia y sostenibilidad y subrayan nuestro compromiso conjunto con soluciones de transporte avanzadas\u00bb, a\u00f1ade J\u00f6rg Irsfeld.<\/p>\n<p>El ecoCHAMP LTO, con un peso propio a partir de 4,7 toneladas, es el todoterreno vers\u00e1til entre los veh\u00edculos ligeros. Gracias a la opci\u00f3n de acortar la distancia entre ejes del remolque, se evita la sobrecarga del eje motriz al utilizar tractores pesados, incluidos los camiones el\u00e9ctricos, al aprovechar la carga \u00fatil completa. El nuevo ecoCHAMP LTO puede reducir el n\u00famero de viajes en hasta un 10 por ciento gracias a su alta carga \u00fatil y es ideal para su uso en combinaci\u00f3n con un tractor de remolque el\u00e9ctrico.<\/p>\n<p>Desde principios de 2024, los remolques ligeros especiales de la marca BERGERecotrail\u00ae est\u00e1n disponibles a trav\u00e9s de la red de ventas de Schmitz Cargobull. Tambi\u00e9n se garantiza el suministro de piezas de repuesto en toda Europa a trav\u00e9s de la red de socios de servicio de Schmitz Cargobull, as\u00ed como el uso de otros servicios de Schmitz Cargobull, como financiaci\u00f3n, seguros y el equipamiento est\u00e1ndar de los remolques con el sistema de telem\u00e1tica TrailerConnect\u00ae, que incluye un sistema de control de presi\u00f3n de neum\u00e1ticos con funci\u00f3n de autolocalizaci\u00f3n.<\/p>\n<h5>Consumidores en m\u00e1s de 200 pa\u00edses<\/h5>\n<p>PepsiCo es fabricante de marcas de alimentos y bebidas y uno de los l\u00edderes mundiales en el \u00e1rea de alimentos convenientes y bebidas. Los productos de PepsiCo son consumidos diariamente por consumidores en m\u00e1s de 200 pa\u00edses y regiones de todo el mundo. Muchas de las marcas ic\u00f3nicas alcanzan un estimado de m\u00e1s de 92 mil millones de d\u00f3lares en ventas anuales en el comercio minorista. PepsiCo ha estado firmemente establecida en el norte de Europa durante m\u00e1s de 70 a\u00f1os, proporcionando alimentos y bebidas a numerosos pa\u00edses europeos.<\/p>\n<p>Foto: \u00a9 Schmitz Cargobull<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schmitz Cargobull ha entregado seis remolques ligeros curtainsider ecoCHAMP LTO de BERGERecotrail\u00ae a PepsiCo Alemania. En los nuevos veh\u00edculos, la distancia entre ejes se ha acortado<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-68559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Schmitz Cargobull ha entregado seis remolques ligeros curtainsider ecoCHAMP LTO de BERGERecotrail\u00ae a PepsiCo Alemania. En los nuevos veh\u00edculos, la distancia entre ejes se ha acortado [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T17:53:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_21.5.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1186\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania\",\"datePublished\":\"2025-03-21T17:53:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_21.5.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/\",\"name\":\"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_21.5.25.jpg\",\"datePublished\":\"2025-03-21T17:53:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_21.5.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_21.5.25.jpg\",\"width\":1186,\"height\":732},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2025\\\/03\\\/21\\\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/","og_locale":"es_ES","og_type":"article","og_title":"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania - Loginfo24","og_description":"Schmitz Cargobull ha entregado seis remolques ligeros curtainsider ecoCHAMP LTO de BERGERecotrail\u00ae a PepsiCo Alemania. En los nuevos veh\u00edculos, la distancia entre ejes se ha acortado [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-03-21T17:53:50+00:00","og_image":[{"width":1186,"height":732,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_21.5.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/"},"author":{"name":"","@id":""},"headline":"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania","datePublished":"2025-03-21T17:53:50+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_21.5.25.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/","url":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/","name":"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_21.5.25.jpg","datePublished":"2025-03-21T17:53:50+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_21.5.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_21.5.25.jpg","width":1186,"height":732},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2025\/03\/21\/schmitz-cargobull-entrega-6-remolques-a-pepsico-alemania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Schmitz Cargobull entrega 6 remolques a PepsiCo Alemania"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/68559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=68559"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/68559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/5250"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=68559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=68559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=68559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}