{"id":67566,"date":"2024-12-19T13:29:36","date_gmt":"2024-12-19T12:29:36","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/"},"modified":"2024-12-19T13:29:36","modified_gmt":"2024-12-19T12:29:36","slug":"panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/","title":{"rendered":"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser"},"content":{"rendered":"<h5>Panattoni ha entregado otra propiedad Build-to-suit (BTS) para Dachser en Landsberg, en el estado de Sajonia-Anhalt. El complejo de edificios a medida sirve al proveedor de log\u00edstica para expandir sus actividades comerciales en la sucursal existente. Con esto, Dachser contin\u00faa su exitosa asociaci\u00f3n con Panattoni: ya es la novena vez que ambas empresas han llevado a cabo un proyecto conjunto.<\/h5>\n<p>(Hamburgo\/Landsberg) La nueva instalaci\u00f3n en Landsberg est\u00e1 excelentemente conectada a las autopistas A9 y A14, y se encuentra a solo unos 20 km del Terminal de Contenedores de Halle\/Saale y a 25 km del Aeropuerto de Halle\/Leipzig. La nueva construcci\u00f3n abarca aproximadamente 18,000 m\u00b2 de espacio de almac\u00e9n, 700 m\u00b2 de entreplanta y 1,400 m\u00b2 para oficinas y \u00e1reas sociales. Se ha prestado especial atenci\u00f3n a la flexibilidad del dise\u00f1o de la propiedad para satisfacer las diversas necesidades de los diferentes clientes de Dachser, principalmente en el sector minorista. As\u00ed, tres de las cuatro secciones del almac\u00e9n est\u00e1n equipadas con funciones de refrigeraci\u00f3n y est\u00e1n especialmente dise\u00f1adas para el almacenamiento de alimentos sensibles a la temperatura, como productos de panader\u00eda, carne o productos l\u00e1cteos.<\/p>\n<p>\u00abLa finalizaci\u00f3n de este proyecto de construcci\u00f3n es un hito importante para nuestro centro log\u00edstico de Leipzig\/Halle. Con la nueva propiedad, podemos ampliar nuestras capacidades y ofrecer a nuestros clientes soluciones de almacenamiento personalizadas\u00bb, explica Thomas Burger, Jefe de Construcci\u00f3n y Bienes Ra\u00edces en Dachser. Fred-Markus Bohne, Socio Gerente de Panattoni Alemania y Austria, se alegra de la confianza que el proveedor de log\u00edstica deposita en Panattoni: \u00abEstamos orgullosos de haber realizado otro proyecto con Dachser que establece est\u00e1ndares en t\u00e9rminos de flexibilidad y sostenibilidad. No menos gracias a la estrecha colaboraci\u00f3n, hemos logrado completar la propiedad a tiempo y con este alto est\u00e1ndar.\u00bb<\/p>\n<h5>1,000 kilovatios pico para el suministro de energ\u00eda propia<\/h5>\n<p>El alto est\u00e1ndar tambi\u00e9n incluye los requisitos de sostenibilidad de la propiedad. El edificio a medida se ha construido de acuerdo con el est\u00e1ndar de oro de la Sociedad Alemana para la Construcci\u00f3n Sostenible (DGNB). Entre otras cosas, una planta fotovoltaica en el techo, con una capacidad de casi 1,000 kilovatios pico, apoya el suministro de energ\u00eda propia del edificio.<\/p>\n<p>Foto: \u00a9 Panattoni<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panattoni ha entregado otra propiedad Build-to-suit (BTS) para Dachser en Landsberg, en el estado de Sajonia-Anhalt. El complejo de edificios a medida sirve al proveedor de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-67566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Panattoni ha entregado otra propiedad Build-to-suit (BTS) para Dachser en Landsberg, en el estado de Sajonia-Anhalt. El complejo de edificios a medida sirve al proveedor de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-19T12:29:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Panattoni_19.12.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser\",\"datePublished\":\"2024-12-19T12:29:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Panattoni_19.12.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/\",\"name\":\"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Panattoni_19.12.24.jpg\",\"datePublished\":\"2024-12-19T12:29:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Panattoni_19.12.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Panattoni_19.12.24.jpg\",\"width\":1131,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/12\\\/19\\\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/","og_locale":"es_ES","og_type":"article","og_title":"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser - Loginfo24","og_description":"Panattoni ha entregado otra propiedad Build-to-suit (BTS) para Dachser en Landsberg, en el estado de Sajonia-Anhalt. El complejo de edificios a medida sirve al proveedor de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-12-19T12:29:36+00:00","og_image":[{"width":1131,"height":598,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Panattoni_19.12.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/"},"author":{"name":"","@id":""},"headline":"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser","datePublished":"2024-12-19T12:29:36+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Panattoni_19.12.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/","url":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/","name":"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Panattoni_19.12.24.jpg","datePublished":"2024-12-19T12:29:36+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Panattoni_19.12.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Panattoni_19.12.24.jpg","width":1131,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/12\/19\/panattoni-entrega-propiedad-logistica-en-landsberg-a-dachser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Panattoni entrega propiedad log\u00edstica en Landsberg a Dachser"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/67566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=67566"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/67566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/5601"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=67566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=67566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=67566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}