{"id":66851,"date":"2024-10-10T13:27:52","date_gmt":"2024-10-10T11:27:52","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/"},"modified":"2024-10-10T13:27:52","modified_gmt":"2024-10-10T11:27:52","slug":"craiss-amplia-su-ubicacion-en-weiz-austria","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/","title":{"rendered":"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria"},"content":{"rendered":"<h5><strong>La Craiss Generation Logistik Austria GmbH &amp; Co. KG contin\u00faa su curso de crecimiento y anuncia una amplia expansi\u00f3n de su ubicaci\u00f3n en Weiz, Austria. Con la ampliaci\u00f3n de aproximadamente 20,000 metros cuadrados, Craiss responde a las crecientes demandas de su cliente tecnol\u00f3gico Siemens Energy.<\/strong><\/h5>\n<p>(M\u00fchlacker\/Weiz) Desde la apertura del \u00abDedicated Warehouse\u00bb en 2021, la empresa de log\u00edstica en Weiz, Estiria Oriental, ofrece servicios especializados que van m\u00e1s all\u00e1 de la log\u00edstica de almacenamiento convencional. Las obras comenzaron con una ceremonia de colocaci\u00f3n de la primera piedra el 8 de octubre.<\/p>\n<p>\u00abNuestro objetivo es asegurar la competitividad de Siemens Energy a largo plazo mientras maximizamos nuestro propio potencial de crecimiento. La proximidad a la planta de nuestro cliente nos permite reaccionar r\u00e1pida y flexiblemente a sus necesidades y ofrecer soluciones log\u00edsticas a medida\u00bb, explica Michael Craiss, director general de Craiss Generation Logistik Austria GmbH &amp; Co. KG. La expansi\u00f3n se completar\u00e1 a principios de 2026 y proporcionar\u00e1 al fabricante de tecnolog\u00eda el\u00e9ctrica y energ\u00e9tica espacios de producci\u00f3n adicionales que no puede realizar en su planta principal.<\/p>\n<h5><strong>Aumento de la eficiencia y reducci\u00f3n de costos mediante la consolidaci\u00f3n<\/strong><\/h5>\n<p>La expansi\u00f3n incluye aproximadamente 20,000 metros cuadrados de espacio de almacenamiento y producci\u00f3n, 10,500 metros cuadrados de espacio adicional al aire libre y m\u00e1s de 600 metros cuadrados de espacio de oficina. Con la ampliaci\u00f3n, la empresa puede consolidar sus almacenes exteriores, aumentando as\u00ed la eficiencia y reduciendo costos y emisiones. Una ventaja clave de la expansi\u00f3n es la proximidad a la conexi\u00f3n ferroviaria, que se utiliza tanto para la planta de producci\u00f3n como para el centro log\u00edstico. \u00abCon la conexi\u00f3n ferroviaria, reducimos el tr\u00e1fico de camiones y, por lo tanto, disminuimos las emisiones de CO2. Este es un paso importante hacia una log\u00edstica m\u00e1s sostenible\u00bb, enfatiza Craiss.<\/p>\n<h5><strong>Servicios especializados para clientes tecnol\u00f3gicos exigentes<\/strong><\/h5>\n<p>Adem\u00e1s de la log\u00edstica de almacenamiento cl\u00e1sica, Craiss Generation Logistik Austria GmbH &amp; Co. KG ofrece una variedad de servicios adicionales en su ubicaci\u00f3n en Weiz. \u00abNuestro portafolio incluye pinturas, controles de calidad y soluciones de embalaje especiales. Estos servicios requieren personal altamente calificado y un profundo conocimiento que seguimos ampliando\u00bb, explica Craiss. La nueva conexi\u00f3n ferroviaria optimizar\u00e1 el transporte de componentes que pesan varias toneladas y que presentan requisitos especiales para las soluciones log\u00edsticas.<\/p>\n<h5><strong>Sostenibilidad y relevancia econ\u00f3mica para la regi\u00f3n<\/strong><\/h5>\n<p>La expansi\u00f3n fortalece la ubicaci\u00f3n econ\u00f3mica de Weiz y al mismo tiempo se enfoca en la sostenibilidad. \u00abIntegramos energ\u00edas renovables como la calefacci\u00f3n urbana y la fotovoltaica en nuestro concepto. Al concentrar las capacidades de almacenamiento en una sola ubicaci\u00f3n, tambi\u00e9n reducimos significativamente el tr\u00e1fico de camiones\u00bb, explica Craiss. Adem\u00e1s, la empresa apuesta por tecnolog\u00edas verdes en su ubicaci\u00f3n en Weiz: \u00abPara minimizar a\u00fan m\u00e1s nuestra huella ecol\u00f3gica, estamos invirtiendo en camiones el\u00e9ctricos que comenzar\u00e1n a operar entre la planta de producci\u00f3n y el centro log\u00edstico a partir de noviembre de este a\u00f1o. Aunque esto inicialmente conlleva costos m\u00e1s altos, lo consideramos un paso importante para mejorar nuestro balance ambiental.\u00bb Con el crecimiento del cliente, se crear\u00e1n nuevos puestos de trabajo, de modo que en el futuro entre 100 y 120 empleados trabajar\u00e1n en la ubicaci\u00f3n de Weiz.<\/p>\n<h5><strong>Weiz como un punto estrat\u00e9gico<\/strong><\/h5>\n<p>Debido a la proximidad a Graz, el director general considera la regi\u00f3n como estrat\u00e9gicamente favorable. Adem\u00e1s, el apoyo de las autoridades locales contribuye significativamente a la exitosa implementaci\u00f3n del proyecto. \u00abNos vemos como un socio a largo plazo tanto para nuestros clientes como para la regi\u00f3n. La colaboraci\u00f3n con las autoridades locales y nuestro cliente en la planificaci\u00f3n ha sido extraordinariamente cooperativa\u00bb, enfatiza Craiss.<\/p>\n<p>Para los pr\u00f3ximos a\u00f1os, la empresa planea m\u00e1s inversiones en Austria, entre ellas en Ebergassing, para apoyar el crecimiento continuo. \u00abNuestra tarea es ayudar a nuestros clientes a mantener su competitividad en el mercado global. Solo si \u00e9l se mantiene fuerte, nosotros tambi\u00e9n podemos actuar con \u00e9xito\u00bb, concluye Craiss.<\/p>\n<p>Foto: \u00a9 Craiss \/ <em><strong>Pie de foto:<\/strong><\/em> <em>Participantes en el proyecto de expansi\u00f3n de la ubicaci\u00f3n (de izq. a der.):<\/em> <em>Matthias Unger (CEO y propietario de Unger Stahlbau Ges.m.b.H.), Michael Craiss (socio gerente de Craiss Generation Logistik GmbH &amp; Co. KG) y Hagen Temmel (socio de CUT Logistikimmobilien GmbH) durante la colocaci\u00f3n de la primera piedra para la expansi\u00f3n de la ubicaci\u00f3n en Weiz<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Craiss Generation Logistik Austria GmbH &amp; Co. KG contin\u00faa su curso de crecimiento y anuncia una amplia expansi\u00f3n de su ubicaci\u00f3n en Weiz, Austria. Con<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-66851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Craiss Generation Logistik Austria GmbH &amp; Co. KG contin\u00faa su curso de crecimiento y anuncia una amplia expansi\u00f3n de su ubicaci\u00f3n en Weiz, Austria. Con [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T11:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Craiss_10.10.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1158\" \/>\n\t<meta property=\"og:image:height\" content=\"632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria\",\"datePublished\":\"2024-10-10T11:27:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/\"},\"wordCount\":785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Craiss_10.10.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/\",\"name\":\"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Craiss_10.10.24.jpg\",\"datePublished\":\"2024-10-10T11:27:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Craiss_10.10.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Craiss_10.10.24.jpg\",\"width\":1158,\"height\":632},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/10\\\/10\\\/craiss-amplia-su-ubicacion-en-weiz-austria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/","og_locale":"es_ES","og_type":"article","og_title":"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria - Loginfo24","og_description":"La Craiss Generation Logistik Austria GmbH &amp; Co. KG contin\u00faa su curso de crecimiento y anuncia una amplia expansi\u00f3n de su ubicaci\u00f3n en Weiz, Austria. Con [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-10-10T11:27:52+00:00","og_image":[{"width":1158,"height":632,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Craiss_10.10.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/"},"author":{"name":"","@id":""},"headline":"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria","datePublished":"2024-10-10T11:27:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Craiss_10.10.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/","url":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/","name":"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Craiss_10.10.24.jpg","datePublished":"2024-10-10T11:27:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Craiss_10.10.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Craiss_10.10.24.jpg","width":1158,"height":632},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/10\/10\/craiss-amplia-su-ubicacion-en-weiz-austria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Craiss ampl\u00eda su ubicaci\u00f3n en Weiz, Austria"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/66851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=66851"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/66851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/5888"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=66851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=66851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=66851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}