{"id":66486,"date":"2024-09-10T19:51:12","date_gmt":"2024-09-10T17:51:12","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/"},"modified":"2024-09-10T19:51:12","modified_gmt":"2024-09-10T17:51:12","slug":"sbb-cargo-registra-una-perdida-de-426-millones-de-chf","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/","title":{"rendered":"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF"},"content":{"rendered":"<h5>La SBB transport\u00f3 en el primer semestre de 2024 a m\u00e1s viajeros que nunca. Adem\u00e1s, se construy\u00f3 en varias miles de obras en la red ferroviaria. La ganancia semestral asciende a 50,8 millones de francos, la situaci\u00f3n financiera de la SBB sigue siendo tensa. SBB Cargo registr\u00f3 una p\u00e9rdida de 42,6 millones de francos.<\/h5>\n<p>(Berna) En el primer semestre, diariamente 1,34 millones de viajeros estaban en los trenes de la SBB. Esto representa un 0,7 por ciento m\u00e1s que en el mismo per\u00edodo del a\u00f1o anterior. A pesar de este n\u00famero r\u00e9cord de viajeros y de varias miles de obras, los trenes de pasajeros fueron puntuales en un 93,8 por ciento, m\u00e1s que nunca en un primer semestre. Se garantizaron el 98,9 por ciento de las conexiones. En particular, en Suiza Occidental y en el Tesino, la puntualidad mejor\u00f3 notablemente. La puntualidad de las entregas en SBB Cargo disminuy\u00f3 en m\u00e1s de cinco puntos porcentuales en comparaci\u00f3n con el a\u00f1o anterior, alcanzando el 87,1 por ciento. Las razones incluyen la situaci\u00f3n desafiante en el Gotardo, la disminuci\u00f3n de la fiabilidad de las locomotoras de carga y la disponibilidad de personal.<\/p>\n<h5>SBB quiere ser m\u00e1s eficiente y productiva<\/h5>\n<p>En el primer semestre de 2024, la SBB obtuvo una ganancia de 50,8 millones de francos, aproximadamente la mitad de lo que gan\u00f3 el a\u00f1o anterior. Las principales razones son menores ingresos en el transporte de mercanc\u00edas y mayores costos en infraestructura y transporte regional (ver cifras en el recuadro a continuaci\u00f3n).<\/p>\n<p>La situaci\u00f3n financiera sigue siendo tensa. Para una estabilizaci\u00f3n financiera sostenible, la SBB necesita una ganancia anual de alrededor de 500 millones de francos. La deuda neta, con 11,6 mil millones de francos, sigue siendo demasiado alta. La SBB contin\u00faa superando el grado de cobertura de deuda establecido por el gobierno para 2030. La presi\u00f3n para ahorrar y ser eficiente sigue siendo alta. La SBB se mantiene firme en sus objetivos: quiere ser m\u00e1s eficiente y productiva y cumplir con el grado de cobertura de deuda de 6,5 establecido por el propietario para 2030.<\/p>\n<p>En marzo de 2024, la SBB realiz\u00f3 una evaluaci\u00f3n de su situaci\u00f3n y esboz\u00f3 una visi\u00f3n a largo plazo para el ferrocarril. La SBB est\u00e1 trabajando para concretar esta visi\u00f3n. Para la SBB, lo siguiente es fundamental: la expansi\u00f3n de la red ferroviaria es absolutamente necesaria para poder satisfacer las necesidades de movilidad en Suiza tambi\u00e9n en el futuro. El mantenimiento es prioritario para que la infraestructura ferroviaria siga siendo eficiente. Adem\u00e1s, se requieren medidas para que a\u00fan m\u00e1s trenes puedan operar en la red existente. Desde la perspectiva de la SBB, se necesita una expansi\u00f3n donde la mayor cantidad de viajeros pueda beneficiarse.<\/p>\n<blockquote>\n<h4>El primer semestre de 2024 en cifras<\/h4>\n<h5>Transporte de pasajeros<\/h5>\n<p>El resultado semestral en el transporte de larga distancia aument\u00f3 de 13,7 millones de francos a 32,3 millones de francos. Esto se debe principalmente al desarrollo positivo de la demanda, especialmente en el transporte de fin de semana. A pesar de un desarrollo de mercado igualmente positivo, el resultado en el transporte regional cay\u00f3 de 18,3 millones de francos a -5,9 millones de francos. Esto se debe principalmente a los costos aumentados, especialmente por los servicios de mantenimiento programados para el material rodante, que fluct\u00faan debido a los ciclos de mantenimiento en ciertos a\u00f1os.<\/p>\n<h5>Inmuebles<\/h5>\n<p>El resultado nuevamente positivo en el sector inmobiliario tuvo un efecto estabilizador, aumentando de 114,4 a 121,3 millones de francos. Los ingresos por alquiler de terceros aumentaron en m\u00e1s del cinco por ciento. Las razones son los mayores alquileres comerciales en las estaciones debido al aumento de la frecuencia de clientes, as\u00ed como nuevos arrendamientos de propiedades residenciales y comerciales.<\/p>\n<h5>Transporte de mercanc\u00edas<\/h5>\n<p>El transporte de mercanc\u00edas registr\u00f3 una p\u00e9rdida total de -42,6 millones de francos (2023: -18,0 millones de francos) debido a menores vol\u00famenes en el transporte nacional e internacional. Algunas industrias, como la construcci\u00f3n, causaron la disminuci\u00f3n en el transporte nacional. En el transporte internacional, la situaci\u00f3n econ\u00f3mica, especialmente en Alemania e Italia, las restricciones en el t\u00fanel base del Gotardo y el aumento de la actividad de construcci\u00f3n en ciertas rutas en Alemania fueron las razones del resultado m\u00e1s bajo.<\/p>\n<p>&nbsp;<\/p>\n<p>Para transportar m\u00e1s mercanc\u00edas de manera ecol\u00f3gica por ferrocarril, la SBB quiere, con la ayuda del gobierno, establecer el transporte de mercanc\u00edas sobre una base econ\u00f3micamente sostenible: se debe eliminar el d\u00e9ficit estructural en el transporte de carga por unidades de SBB Cargo. Para ello, se necesita la renovaci\u00f3n del material rodante, la digitalizaci\u00f3n y la automatizaci\u00f3n, as\u00ed como precios justos.<\/p>\n<h5>Infraestructura<\/h5>\n<p>La infraestructura de la red registr\u00f3 un resultado peor que en el per\u00edodo del a\u00f1o anterior debido a mayores costos, especialmente para el mantenimiento de la infraestructura ferroviaria (2024: -37,8 millones de francos, 2023: -17,1 millones de francos). El resultado de infraestructura energ\u00e9tica se mantuvo en el nivel del a\u00f1o anterior con una ganancia de 48,6 millones de francos (2023: 48,5 millones de francos). Los ingresos energ\u00e9ticos reducidos fueron compensados por un entorno de mercado m\u00e1s estable.<\/p><\/blockquote>\n<p>Foto: \u00a9 SBB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La SBB transport\u00f3 en el primer semestre de 2024 a m\u00e1s viajeros que nunca. Adem\u00e1s, se construy\u00f3 en varias miles de obras en la red ferroviaria.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-66486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La SBB transport\u00f3 en el primer semestre de 2024 a m\u00e1s viajeros que nunca. Adem\u00e1s, se construy\u00f3 en varias miles de obras en la red ferroviaria. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T17:51:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SBB_10.9.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1099\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF\",\"datePublished\":\"2024-09-10T17:51:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/\"},\"wordCount\":882,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SBB_10.9.24.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/\",\"name\":\"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SBB_10.9.24.jpg\",\"datePublished\":\"2024-09-10T17:51:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SBB_10.9.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SBB_10.9.24.jpg\",\"width\":1099,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/09\\\/10\\\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/","og_locale":"es_ES","og_type":"article","og_title":"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF - Loginfo24","og_description":"La SBB transport\u00f3 en el primer semestre de 2024 a m\u00e1s viajeros que nunca. Adem\u00e1s, se construy\u00f3 en varias miles de obras en la red ferroviaria. [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-09-10T17:51:12+00:00","og_image":[{"width":1099,"height":640,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SBB_10.9.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/"},"author":{"name":"","@id":""},"headline":"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF","datePublished":"2024-09-10T17:51:12+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/"},"wordCount":882,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SBB_10.9.24.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/","url":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/","name":"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SBB_10.9.24.jpg","datePublished":"2024-09-10T17:51:12+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SBB_10.9.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SBB_10.9.24.jpg","width":1099,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/09\/10\/sbb-cargo-registra-una-perdida-de-426-millones-de-chf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"SBB Cargo registra una p\u00e9rdida de 42,6 millones de CHF"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/66486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=66486"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/66486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6032"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=66486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=66486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=66486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}