{"id":66306,"date":"2024-08-27T15:49:15","date_gmt":"2024-08-27T13:49:15","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/"},"modified":"2024-08-27T15:49:15","modified_gmt":"2024-08-27T13:49:15","slug":"data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/","title":{"rendered":"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE"},"content":{"rendered":"<h5><strong>Los esfuerzos hacia la neutralidad clim\u00e1tica y la econom\u00eda circular est\u00e1n hoy en d\u00eda integrados en muchas estrategias empresariales. El Pacto Verde de la UE acelera estos esfuerzos a trav\u00e9s de regulaciones correspondientes y puede convertirse en un desaf\u00edo para algunas empresas. La demanda de mayor transparencia en relaci\u00f3n con sus actividades y logros de sostenibilidad ocupa a las empresas a diario. <\/strong><\/h5>\n<p>(K\u00f6ln) Los clientes est\u00e1n interesados en el origen y el impacto ambiental de los productos, los inversores exigen detalles sobre los posibles riesgos ambientales y los legisladores definen requisitos para la presentaci\u00f3n de informes empresariales, deberes de diligencia en las cadenas de suministro y comunicaci\u00f3n con los consumidores.<\/p>\n<p>Entre tales requisitos se encuentran, por ejemplo, el Reglamento de la UE sobre la Deforestaci\u00f3n (EUDR) y la Directiva de Informes de Sostenibilidad Corporativa (CSRD). La EUDR es un reglamento sobre cadenas de suministro libres de deforestaci\u00f3n que entrar\u00e1 en vigor el 30 de diciembre de 2024. La CSRD es una directiva de la UE sobre informes de sostenibilidad que obliga a las empresas a publicar informes regulares sobre sus riesgos sociales y ecol\u00f3gicos. Estas exigencias son impulsadas por el Pacto Verde de la UE, cuyo objetivo general es alcanzar la neutralidad clim\u00e1tica de la UE para el a\u00f1o 2050.<\/p>\n<h5><strong>No es una tarea f\u00e1cil para las empresas<\/strong><\/h5>\n<p>No es una tarea f\u00e1cil para las empresas, ya que el plazo para la implementaci\u00f3n es corto y el enfoque a veces es poco claro. Las solicitudes paralelas con diferentes enfoques a los participantes de la cadena de suministro pueden llevar a un trabajo adicional evitable. Adem\u00e1s, la creciente complejidad del intercambio de datos entre empresas juega un papel importante. La informaci\u00f3n necesaria, en la mayor\u00eda de los casos, no puede ser proporcionada por una sola empresa. Para que la informaci\u00f3n sea significativa y se garantice la comparabilidad entre diferentes empresas, tambi\u00e9n se requieren definiciones, m\u00e9todos de medici\u00f3n y procedimientos de c\u00e1lculo uniformes.<\/p>\n<p>Para superar estos desaf\u00edos, las empresas deben cooperar y seguir un enfoque com\u00fan. \u00abAqu\u00ed es donde entra en juego el programa GS1 Data for Sustainability. Con el programa, GS1 Germany ofrece un enfoque colaborativo como plataforma y multiplicador\u00bb, explica Christian Przybilla, director del programa y l\u00edder de Master Data y Data Exchange en GS1 Germany. Agrega: \u00abEl objetivo del programa es desarrollar un lenguaje com\u00fan basado en los est\u00e1ndares GS1 para la informaci\u00f3n de sostenibilidad, que permita la transformaci\u00f3n dentro de las empresas y simplifique los enfoques cooperativos m\u00e1s all\u00e1 de las fronteras empresariales.\u00bb El programa est\u00e1 dise\u00f1ado para varios a\u00f1os. Actualmente, se est\u00e1 llevando a cabo la fase 1, en la que se abordan la EUDR y la CSRD. M\u00e1s de 30 representantes de la industria de bienes de consumo de r\u00e1pido movimiento, tanto de la industria como del comercio y los servicios, est\u00e1n involucrados. Entre ellos, empresas reconocidas como dm-drogerie markt GmbH &amp; Co. KG, REWE Group Buying GmbH, Henkel AG &amp; Co. KGaA o Alfred Ritter GmbH &amp; Co. KG.<\/p>\n<h5>La estandarizaci\u00f3n de datos es importante para el proceso de creaci\u00f3n de valor<\/h5>\n<p>\u00abDesde 2019, los minoristas pueden resaltar el contenido de material reciclado en los envases en el punto de venta. Esto ha promovido de manera comprobable envases m\u00e1s sostenibles. Esto se logr\u00f3 mediante la implementaci\u00f3n del atributo de datos &#8216;Porcentaje de material reciclado&#8217; en el GDSN. Este ejemplo ilustra cu\u00e1n importante es la estandarizaci\u00f3n de datos para transformar de manera efectiva todo el proceso de creaci\u00f3n de valor hacia una forma de econom\u00eda sostenible. Por eso seguimos comprometidos activamente en este \u00e1mbito\u00bb, informa Dagmar Glatz, gesti\u00f3n de productos, sostenibilidad\/envases en dm-drogerie markt.<\/p>\n<p>El Dr. Arndt Scheidgen, director de Product Stewardship en Henkel Consumer Brands, explica: \u00abConsideramos que la participaci\u00f3n en el programa GS1 &#8216;Data for Sustainability&#8217; (D4S) es esencial, ya que actualmente muchas legislaciones est\u00e1n entrando en vigor o est\u00e1n en preparaci\u00f3n, que requieren la colaboraci\u00f3n de todos los actores de la cadena de suministro. Cada actor depende de datos de sostenibilidad fiables de la cadena de suministro anterior y de una transmisi\u00f3n estandarizada. Los datos de sostenibilidad son el mayor campo de trabajo de la industria y el comercio en la d\u00e9cada de 2020.\u00bb<\/p>\n<p>Para el a\u00f1o 2024, Data for Sustainability se centrar\u00e1 inicialmente en las regulaciones del Pacto Verde de la UE EUDR y CSRD. En un primer paquete de trabajo, se describir\u00e1n sem\u00e1nticamente los puntos de datos relevantes entre empresas para crear un entendimiento com\u00fan con enfoque en la industria de bienes de consumo de r\u00e1pido movimiento. Luego, los puntos de datos se mapear\u00e1n a los est\u00e1ndares GS1 correspondientes para su transmisi\u00f3n entre los socios en la cadena de suministro. Si faltan opciones de declaraci\u00f3n en los est\u00e1ndares GS1, se incorporar\u00e1n a los est\u00e1ndares globales. A largo plazo, se priorizar\u00e1 la automatizaci\u00f3n a trav\u00e9s de la digitalizaci\u00f3n, lo que permitir\u00e1 un aumento sostenible del rendimiento de sostenibilidad dentro de las empresas.<\/p>\n<p>Foto: \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los esfuerzos hacia la neutralidad clim\u00e1tica y la econom\u00eda circular est\u00e1n hoy en d\u00eda integrados en muchas estrategias empresariales. El Pacto Verde de la UE acelera<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1561],"tags":[],"class_list":["post-66306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Los esfuerzos hacia la neutralidad clim\u00e1tica y la econom\u00eda circular est\u00e1n hoy en d\u00eda integrados en muchas estrategias empresariales. El Pacto Verde de la UE acelera [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T13:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GS1_Germany_27.8.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE\",\"datePublished\":\"2024-08-27T13:49:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/\"},\"wordCount\":891,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GS1_Germany_27.8.24.jpg\",\"articleSection\":[\"Categories\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/\",\"name\":\"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GS1_Germany_27.8.24.jpg\",\"datePublished\":\"2024-08-27T13:49:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GS1_Germany_27.8.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GS1_Germany_27.8.24.jpg\",\"width\":1260,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/08\\\/27\\\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/","og_locale":"es_ES","og_type":"article","og_title":"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE - Loginfo24","og_description":"Los esfuerzos hacia la neutralidad clim\u00e1tica y la econom\u00eda circular est\u00e1n hoy en d\u00eda integrados en muchas estrategias empresariales. El Pacto Verde de la UE acelera [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-08-27T13:49:15+00:00","og_image":[{"width":1260,"height":772,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GS1_Germany_27.8.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/"},"author":{"name":"","@id":""},"headline":"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE","datePublished":"2024-08-27T13:49:15+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/"},"wordCount":891,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GS1_Germany_27.8.24.jpg","articleSection":["Categories","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/","url":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/","name":"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GS1_Germany_27.8.24.jpg","datePublished":"2024-08-27T13:49:15+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GS1_Germany_27.8.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GS1_Germany_27.8.24.jpg","width":1260,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/08\/27\/data-for-sustainability-ayuda-con-el-desafio-del-pacto-verde-de-la-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Data for Sustainability ayuda con el desaf\u00edo del Pacto Verde de la UE"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/66306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=66306"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/66306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6096"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=66306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=66306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=66306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}