{"id":65757,"date":"2024-07-09T17:53:31","date_gmt":"2024-07-09T15:53:31","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/"},"modified":"2024-07-09T17:53:31","modified_gmt":"2024-07-09T15:53:31","slug":"hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/","title":{"rendered":"Hermes Germany equipa a los primeros empleados con exoesqueletos"},"content":{"rendered":"<h5><strong>En la log\u00edstica de paquetes, hay muchos pasos de trabajo que son f\u00edsicamente desafiantes; especialmente la clasificaci\u00f3n de grandes piezas y art\u00edculos voluminosos, es decir, env\u00edos pesados y voluminosos, cuenta entre ellos. Para aliviar a sus empleados, especialmente en los tres sitios con mayores proporciones de grandes piezas y art\u00edculos voluminosos, Hermes Germany ha adquirido seis exoesqueletos de espalda para uso regular.<\/strong><\/h5>\n<p>(Hamburgo) Como el primer operador log\u00edstico de paquetes en Alemania, la empresa ha estado utilizando desde julio de este a\u00f1o en sus centros log\u00edsticos en Friedewald, Graben y Langenhagen el modelo IX BACK AIR de SUITX by Ottobock en uso continuo. El exoesqueleto de espalda m\u00e1s ligero de su tipo alivia la columna vertebral y al mismo tiempo permite una total libertad de movimiento, de modo que los empleados se benefician de un alivio inmediato.<\/p>\n<p>Desde peque\u00f1os y ligeros como una camiseta de f\u00fatbol hasta grandes y pesados como un mueble, hoy en d\u00eda se compran muchos art\u00edculos de la vida cotidiana en l\u00ednea. La mayor parte de los paquetes y cajas enviados a trav\u00e9s del pa\u00eds son generalmente m\u00e1s bien peque\u00f1os y manejables, y el peso promedio de un env\u00edo en Hermes Germany fue de alrededor de dos kilogramos. Trabajar con grandes piezas y art\u00edculos voluminosos, aunque su proporci\u00f3n en el total de env\u00edos es relativamente baja, es f\u00edsicamente mucho m\u00e1s exigente. Por lo tanto, es especialmente importante encontrar soluciones en t\u00e9rminos de promoci\u00f3n de la salud para facilitar el trabajo de los empleados.<\/p>\n<p>Aqu\u00ed es donde entran en juego los exoesqueletos de espalda, que se han adquirido espec\u00edficamente para los centros log\u00edsticos de Hermes en Friedewald (Hesse), Graben (Baviera) y Langenhagen (Baja Sajonia), tres ubicaciones con un alto volumen de grandes piezas. En Friedewald, por ejemplo, la proporci\u00f3n de env\u00edos grandes y voluminosos es m\u00e1s del doble que el promedio nacional, y en las otras dos ubicaciones se encuentra en un nivel similar. \u00abCon los exoesqueletos de espalda, se puede reducir especialmente la carga f\u00edsica de los empleados en el \u00e1rea de grandes piezas y art\u00edculos voluminosos\u00bb, explica Dennis Isern. El gerente del centro log\u00edstico de Friedewald ha impulsado este tema en Hermes Germany. \u00abLos exoesqueletos optimizan el movimiento y reducen efectivamente la carga al levantar hasta 15 kilogramos.\u00bb El peso m\u00e1ximo de los paquetes enviados por Hermes Germany es de 31,5 kilogramos. Sin embargo, la gran mayor\u00eda de los env\u00edos son significativamente m\u00e1s ligeros: los env\u00edos de m\u00e1s de 20 kilogramos representan menos del dos por ciento del portafolio de env\u00edos de la empresa.<\/p>\n<h5><strong>Alta aceptaci\u00f3n entre los empleados<\/strong><strong> \u00a0 <\/strong><\/h5>\n<p>Hermes Germany ya ha probado varios modelos de exoesqueletos en el pasado. Adem\u00e1s de la efectiva reducci\u00f3n de carga, para el operador log\u00edstico de paquetes, la aceptaci\u00f3n entre los empleados es especialmente importante. Arne Zieris, gerente del centro log\u00edstico de Langenhagen, explica: \u00abPara nuestros colegas, juegan un papel fundamental razones muy pr\u00e1cticas: el dispositivo debe ser lo m\u00e1s ligero posible y f\u00e1cil de cambiar durante el cambio de turno.\u00bb Ambos puntos son cumplidos por los exoesqueletos adquiridos, lo que aumenta significativamente la aceptaci\u00f3n: con un peso propio de casi tres kilogramos, el IX BACK AIR se puede poner y quitar en menos de medio minuto. El empleado solo tiene que colocarse un ligero cintur\u00f3n textil alrededor de la cintura, en el que se engancha el dispositivo, que se adapta, entre otras cosas, a la altura del cuerpo. \u00abEl exoesqueleto se puede llevar durante todo el turno sin necesidad de cambiar bater\u00edas, ya que utiliza energ\u00eda del cuerpo\u00bb, explica Arne Zieris. SUITX by Ottobock se basa en sistemas biomec\u00e1nicos.<\/p>\n<h5><strong>Alivio palpable inmediatamente experimentable<\/strong><strong> \u00a0 <\/strong><\/h5>\n<p>Con la introducci\u00f3n de los exoesqueletos de espalda en los centros log\u00edsticos de Friedewald, Graben y Langenhagen, inicialmente dos usuarios principales por ubicaci\u00f3n comenzar\u00e1n a trabajar con el dispositivo. En un taller conjunto a finales de junio de 2024, los empleados recibieron una capacitaci\u00f3n detallada sobre el uso de los exoesqueletos, para que puedan beneficiarse al m\u00e1ximo del apoyo en su trabajo en el futuro. Para hacer que el alivio sea directamente experimentable en comparaci\u00f3n inmediata, los usuarios principales trabajar\u00e1n inicialmente con el dispositivo durante seis semanas, antes de que luego se clasifique durante dos semanas sin el exoesqueleto. De esta manera, Hermes Germany podr\u00e1 evaluar directamente con los empleados c\u00f3mo afecta el uso de exoesqueletos al trabajo y a la salud.<\/p>\n<p>Las expectativas sobre la nueva tecnolog\u00eda en los tres sitios son altas. C\u00f3mo experimentan los empleados esta nueva forma de apoyo se ver\u00e1 en las pr\u00f3ximas semanas. \u00abEstoy muy contento de que con los exoesqueletos de espalda podamos marcar un hito en t\u00e9rminos de salud de los empleados. Antes, nos convencieron especialmente los factores de comodidad, movilidad y r\u00e1pida puesta y retirada; ahora estamos muy ansiosos por ver c\u00f3mo se comportan estos puntos en la pr\u00e1ctica diaria\u00bb, dice Wolfgang Fackelmann, gerente del centro log\u00edstico de Graben. Las primeras impresiones ya son positivas, informa, por ejemplo, Dennis Isern desde Friedewald, Hesse.<\/p>\n<h5><strong>Se ha dado el primer paso hacia la promoci\u00f3n de la salud<\/strong><\/h5>\n<p>El primer paso en el \u00e1rea de exoesqueletos como un componente de la promoci\u00f3n de la salud en el sector comercial ha sido dado en Hermes Germany. \u00abSeguiremos observando qu\u00e9 nuevos desarrollos surgen en el mercado en los pr\u00f3ximos a\u00f1os para proporcionar m\u00e1s alivio a nuestros colegas con procesos de trabajo din\u00e1micos\u00bb, dice Dennis Isern. Adem\u00e1s del apoyo t\u00e9cnico, por ejemplo, tambi\u00e9n en forma de sistemas de clasificaci\u00f3n autom\u00e1ticos, Hermes Germany contin\u00faa organizando d\u00edas de salud y colaborando con socios m\u00e9dicos laborales.<\/p>\n<p>Foto: \u00a9 Hermes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la log\u00edstica de paquetes, hay muchos pasos de trabajo que son f\u00edsicamente desafiantes; especialmente la clasificaci\u00f3n de grandes piezas y art\u00edculos voluminosos, es decir, env\u00edos<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-65757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hermes Germany equipa a los primeros empleados con exoesqueletos - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hermes Germany equipa a los primeros empleados con exoesqueletos - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"En la log\u00edstica de paquetes, hay muchos pasos de trabajo que son f\u00edsicamente desafiantes; especialmente la clasificaci\u00f3n de grandes piezas y art\u00edculos voluminosos, es decir, env\u00edos [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T15:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hermes_9.7.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"848\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hermes Germany equipa a los primeros empleados con exoesqueletos\",\"datePublished\":\"2024-07-09T15:53:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/\"},\"wordCount\":1006,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hermes_9.7.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/\",\"name\":\"Hermes Germany equipa a los primeros empleados con exoesqueletos - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hermes_9.7.24.jpg\",\"datePublished\":\"2024-07-09T15:53:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hermes_9.7.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hermes_9.7.24.jpg\",\"width\":1404,\"height\":848},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/07\\\/09\\\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hermes Germany equipa a los primeros empleados con exoesqueletos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hermes Germany equipa a los primeros empleados con exoesqueletos - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/","og_locale":"es_ES","og_type":"article","og_title":"Hermes Germany equipa a los primeros empleados con exoesqueletos - Loginfo24","og_description":"En la log\u00edstica de paquetes, hay muchos pasos de trabajo que son f\u00edsicamente desafiantes; especialmente la clasificaci\u00f3n de grandes piezas y art\u00edculos voluminosos, es decir, env\u00edos [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-07-09T15:53:31+00:00","og_image":[{"width":1404,"height":848,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hermes_9.7.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/"},"author":{"name":"","@id":""},"headline":"Hermes Germany equipa a los primeros empleados con exoesqueletos","datePublished":"2024-07-09T15:53:31+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/"},"wordCount":1006,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hermes_9.7.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/","url":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/","name":"Hermes Germany equipa a los primeros empleados con exoesqueletos - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hermes_9.7.24.jpg","datePublished":"2024-07-09T15:53:31+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hermes_9.7.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hermes_9.7.24.jpg","width":1404,"height":848},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/07\/09\/hermes-germany-equipa-a-los-primeros-empleados-con-exoesqueletos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hermes Germany equipa a los primeros empleados con exoesqueletos"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=65757"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6320"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=65757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=65757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=65757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}