{"id":65611,"date":"2024-06-12T15:23:20","date_gmt":"2024-06-12T13:23:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/"},"modified":"2024-06-12T15:23:20","modified_gmt":"2024-06-12T13:23:20","slug":"el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/","title":{"rendered":"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing"},"content":{"rendered":"<h5><strong>Para el creciente volumen de pedidos y la creciente necesidad de fabricaci\u00f3n y entrega puntual de piezas de repuesto, se han optimizado y ampliado los procesos establecidos y el equipamiento de almac\u00e9n en la ubicaci\u00f3n del Grupo BMW en Dingolfing, con el fin de aumentar a\u00fan m\u00e1s la eficiencia y la ergonom\u00eda en el almacenamiento, la preparaci\u00f3n de pedidos, el embalaje y el env\u00edo.<\/strong><\/h5>\n<p>(Pressebox: Neckarwestheim\/Dingolfing) El integrador de sistemas Inther Group en Neckarwestheim recibi\u00f3 el encargo de implementar un concepto integral con un Almac\u00e9n Automatizado de Peque\u00f1as Piezas (AKL), flujos de material inteligentes e integraci\u00f3n de tecnolog\u00eda de transporte de \u00faltima generaci\u00f3n. La sede en los Pa\u00edses Bajos en Venray apoy\u00f3 el an\u00e1lisis exhaustivo, el dise\u00f1o y la planificaci\u00f3n de las instalaciones en la fase previa, as\u00ed como la realizaci\u00f3n del proyecto en Dingolfing. Adem\u00e1s, la empresa de consultor\u00eda y planificaci\u00f3n de Heidelberg, io, acompa\u00f1\u00f3 el proyecto desde la licitaci\u00f3n y adjudicaci\u00f3n hasta la realizaci\u00f3n y aceptaci\u00f3n final.<\/p>\n<p>Como pieza central de la instalaci\u00f3n log\u00edstica, Inther estableci\u00f3 un nuevo almac\u00e9n de peque\u00f1as piezas con cuatro pasillos y alta automatizaci\u00f3n (AKL). Con un almacenamiento de cuatro niveles en 20 niveles, el AKL ofrece una enorme capacidad de aproximadamente 80,000 espacios para contenedores para el almacenamiento de piezas de repuesto. Se utilizan contenedores con dimensiones de 650 x 450 x 270 mm y un peso total m\u00e1ximo de 30 kg. \u00abLos shuttles est\u00e1n dise\u00f1ados espec\u00edficamente para las demandas de los almacenes de peque\u00f1as piezas actuales y futuras\u00bb, explica Stefan Weisshap, director general de Inther Group Alemania. \u00abCon su almacenamiento de cuatro niveles, el AKL de shuttle ofrece una enorme capacidad en un almacenamiento compacto y altamente denso, y la automatizaci\u00f3n en la extracci\u00f3n acelera la entrega de mercanc\u00edas a los puestos de preparaci\u00f3n de pedidos.\u00bb Esto permite almacenar m\u00e1s art\u00edculos con un menor espacio requerido y aumentar la velocidad de procesamiento de pedidos.<\/p>\n<h5>Puestos de trabajo desde una perspectiva ergon\u00f3mica<\/h5>\n<p>Se han establecido puestos de trabajo para la preparaci\u00f3n de pedidos de env\u00edo y su embalaje. Adem\u00e1s, se instalaron tres estaciones de trabajo en el \u00e1rea de recepci\u00f3n de mercanc\u00edas. Para la interconexi\u00f3n del AKL y los puestos de trabajo de almacenamiento, preparaci\u00f3n de pedidos y embalaje, dise\u00f1ados seg\u00fan aspectos ergon\u00f3micos \u00f3ptimos y ajustables en altura, Inther implement\u00f3 un concepto de tecnolog\u00eda de transporte inteligente y din\u00e1mico, incluyendo un buffer para contenedores vac\u00edos. En circuitos en rutas de transporte especiales para contenedores de origen, contenedores de destino y cajas de env\u00edo, la tecnolog\u00eda de transporte abastece las estaciones de trabajo a una velocidad de 0.8 m\/s.<\/p>\n<p>Las estaciones de preparaci\u00f3n de pedidos son abastecidas desde el AKL con contenedores de origen. Las estaciones est\u00e1n equipadas con buffers de contenedores vac\u00edos conectados. Las piezas de repuesto se preparan para el env\u00edo seg\u00fan un sistema de Pick-by-light en cajas o contenedores reutilizables. Los formadores de cajas suministran las cajas prefabricadas. En consecuencia, la tecnolog\u00eda de transporte est\u00e1 dise\u00f1ada para el transporte de ambos tipos de soportes de carga. Tras completar la preparaci\u00f3n de pedidos, la tecnolog\u00eda de transporte devuelve los contenedores abiertos a los puntos de entrega en el AKL. Los contenedores y cajas de destino llegan a los cuatro puestos de embalaje a trav\u00e9s de la ruta de transporte. Los soportes de carga listos para el env\u00edo son conducidos por la tecnolog\u00eda de transporte al \u00e1rea de env\u00edo. A trav\u00e9s de controles de peso automatizados en la ruta de transporte, se verifica la correcta preparaci\u00f3n de pedidos mediante la comparaci\u00f3n con los datos de pedidos y maestros. Las cajas defectuosas son desviadas a un bucle NiO.<\/p>\n<h5>Tecnolog\u00eda de transporte creada seg\u00fan el concepto de bypass<\/h5>\n<p>A continuaci\u00f3n, las cajas pasan por una m\u00e1quina de cierre de cajas, los contenedores se tapan antes de que finalmente se realice una etiquetado autom\u00e1tico en la ruta de transporte. \u00abToda la tecnolog\u00eda de transporte se ha creado seg\u00fan un concepto de bypass\u00bb, explica Weisshap. \u00abEsto permite que el AKL y todas las estaciones se sirvan mutuamente seg\u00fan sea necesario, para realizar devoluciones m\u00e1s r\u00e1pidamente, evitar o eludir atascos o fallos de componentes a corto plazo en la instalaci\u00f3n.\u00bb<\/p>\n<p>La nueva tecnolog\u00eda de almacenamiento y transporte automatizada fue adem\u00e1s conectada sin problemas a la tecnolog\u00eda de instalaci\u00f3n existente. La visualizaci\u00f3n de la tecnolog\u00eda de transporte se realiza a trav\u00e9s del software Zenon, que Inther configur\u00f3 seg\u00fan los requisitos existentes en BMW. El procesamiento de la recepci\u00f3n de mercanc\u00edas, la preparaci\u00f3n de pedidos y el embalaje, as\u00ed como los di\u00e1logos de los puestos de trabajo, son controlados por SAP. Esto tambi\u00e9n se aplica al sistema de shuttles y la impresi\u00f3n de documentos para las cajas y contenedores de env\u00edo.<\/p>\n<h5>Soluci\u00f3n de automatizaci\u00f3n de alto rendimiento<\/h5>\n<p>Con los servicios de postventa acordados para el mantenimiento y la atenci\u00f3n de la instalaci\u00f3n, Inther Group garantiza una disponibilidad confiable a largo plazo de la instalaci\u00f3n. \u00abUna soluci\u00f3n de automatizaci\u00f3n de alto rendimiento que proporciona una enorme capacidad de almacenamiento, procesos eficientes y una calidad de preparaci\u00f3n de pedidos confiable para un suministro r\u00e1pido de piezas de repuesto\u00bb, resume el director general de Inther, Weisshap.<\/p>\n<p>Foto: \u00a9 Inther Group<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para el creciente volumen de pedidos y la creciente necesidad de fabricaci\u00f3n y entrega puntual de piezas de repuesto, se han optimizado y ampliado los procesos<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-65611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Para el creciente volumen de pedidos y la creciente necesidad de fabricaci\u00f3n y entrega puntual de piezas de repuesto, se han optimizado y ampliado los procesos [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T13:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Inther_12.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1282\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing\",\"datePublished\":\"2024-06-12T13:23:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/\"},\"wordCount\":963,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Inther_12.6.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/\",\"name\":\"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Inther_12.6.24.jpg\",\"datePublished\":\"2024-06-12T13:23:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Inther_12.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Inther_12.6.24.jpg\",\"width\":1282,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/12\\\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/","og_locale":"es_ES","og_type":"article","og_title":"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing - Loginfo24","og_description":"Para el creciente volumen de pedidos y la creciente necesidad de fabricaci\u00f3n y entrega puntual de piezas de repuesto, se han optimizado y ampliado los procesos [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-12T13:23:20+00:00","og_image":[{"width":1282,"height":788,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Inther_12.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/"},"author":{"name":"","@id":""},"headline":"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing","datePublished":"2024-06-12T13:23:20+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/"},"wordCount":963,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Inther_12.6.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/","url":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/","name":"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Inther_12.6.24.jpg","datePublished":"2024-06-12T13:23:20+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Inther_12.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Inther_12.6.24.jpg","width":1282,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/12\/el-integrador-de-sistemas-inther-group-optimiza-el-almacen-de-bmw-en-dingolfing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"El integrador de sistemas Inther Group optimiza el almac\u00e9n de BMW en Dingolfing"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=65611"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6383"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=65611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=65611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=65611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}