{"id":65447,"date":"2024-06-01T18:35:37","date_gmt":"2024-06-01T16:35:37","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/"},"modified":"2024-06-01T18:35:37","modified_gmt":"2024-06-01T16:35:37","slug":"arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/","title":{"rendered":"Arvato pone en funcionamiento un robot paletizador en Venlo"},"content":{"rendered":"<h5>Arvato ha puesto en funcionamiento con \u00e9xito un nuevo robot paletizador en su ubicaci\u00f3n en Venlo, Pa\u00edses Bajos. El robot es parte del proceso de recepci\u00f3n y almacenamiento de mercanc\u00edas y no solo paletiza cajas de contenedores cargados a granel, sino que tambi\u00e9n envuelve la paleta y coloca la etiqueta de seguimiento. Con esta soluci\u00f3n rob\u00f3tica, el proveedor de servicios de cadena de suministro y comercio electr\u00f3nico contin\u00faa implementando de manera coherente su estrategia de automatizaci\u00f3n en sus centros log\u00edsticos en todo el mundo.<\/h5>\n<p>(G\u00fctersloh\/Venlo) \u00abLa implementaci\u00f3n del robot paletizador, al que hemos apodado internamente &#8216;Bucky&#8217; en honor al superh\u00e9roe Bucky Barnes, es el siguiente paso en el \u00e1mbito de la rob\u00f3tica. Despu\u00e9s del \u00e9xito inicial de nuestros tres robots de desapilado, hemos implementado gradualmente m\u00e1s soluciones rob\u00f3ticas, desde robots de preparaci\u00f3n de pedidos hasta la descarga de contenedores\u00bb, dice Karoline Kowalik, ingeniera log\u00edstica en Arvato. \u00abBucky no es un sistema aislado, sino un componente m\u00e1s de nuestra estrategia de automatizaci\u00f3n, con el que estamos transformando y completando la cadena de procesos hacia un proceso de recepci\u00f3n de mercanc\u00edas totalmente automatizado\u00bb, subraya Bernhard Lembeck, jefe del departamento de Future Warehouse en Arvato. \u00abQueremos utilizar &#8216;Stretch\u00ae&#8217; de Boston Dynamics en el contenedor, Bucky para escanear, paletizar y empaquetar, as\u00ed como sistemas de transporte aut\u00f3nomos (FTS) para el almacenamiento en el actual sistema de paletas. Actualmente estamos trabajando intensamente para integrar todo de manera \u00f3ptima en el proceso general.\u00bb<\/p>\n<h5>Puede agarrar varias cajas a la vez<\/h5>\n<p>La nueva soluci\u00f3n rob\u00f3tica en Venlo fue planificada y probada en conjunto por un equipo de las \u00e1reas de operaciones, t\u00e9cnica, gesti\u00f3n de proyectos y desarrollo de TI. El robot paletizador, suministrado por el especialista en automatizaci\u00f3n Segbert, puede agarrar varias cajas a la vez con su agarre de vac\u00edo y procesar entre 700 y 3,000 cajas por hora, dependiendo del tama\u00f1o. Karoline Kowalik: \u00abLo especial de Bucky es que se trata de una soluci\u00f3n llave en mano que integra varios pasos del proceso.\u00bb As\u00ed, Bucky paletiza en el proceso de entrada las cajas de contenedores cargados a granel, captura simult\u00e1neamente los n\u00fameros de serie y los asigna a una paleta. Una vez que la paleta est\u00e1 completamente ensamblada seg\u00fan un patr\u00f3n predefinido, se transporta a la m\u00e1quina de embalaje, se envuelve con film y se le asigna un n\u00famero de paleta, todo de manera autom\u00e1tica.<\/p>\n<p>\u00abCon respecto a los tiempos de procesamiento, la falta de personal, la salud de los empleados y la sostenibilidad, surgen numerosas ventajas\u00bb, enfatiza Karoline Kowalik. \u00abDe este modo, podemos reducir el tiempo en el proceso de entrada en aproximadamente un tercio, lo que ofrece a nuestros clientes un mayor rendimiento y un mejor servicio.\u00bb Otros puntos a favor: para llevar a cabo los procesos, solo se necesitan dos empleados en lugar de cuatro, lo que permite utilizar las capacidades liberadas de manera diferente. Adem\u00e1s, los empleados ya no tienen que levantar cajas pesadas, ya que la cinta transportadora de entrada es ajustable en altura.<\/p>\n<h5>Se evita el desperdicio de cart\u00f3n<\/h5>\n<p>El uso del robot paletizador tambi\u00e9n cuida el medio ambiente y aumenta la sostenibilidad, ya que la combinaci\u00f3n de robot y shuttle evita el desperdicio de cart\u00f3n, como cajas de esquina o tapas de papel. Karoline Kowalik: \u00abSin embargo, el uso de Bucky no debe limitarse a Venlo, ya que valoramos mucho las soluciones modulares y escalables en la automatizaci\u00f3n, que se pueden implementar en toda la red global de Arvato.\u00bb<\/p>\n<p>Foto: \u00a9 Arvato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arvato ha puesto en funcionamiento con \u00e9xito un nuevo robot paletizador en su ubicaci\u00f3n en Venlo, Pa\u00edses Bajos. El robot es parte del proceso de recepci\u00f3n<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-65447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arvato pone en funcionamiento un robot paletizador en Venlo - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arvato pone en funcionamiento un robot paletizador en Venlo - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Arvato ha puesto en funcionamiento con \u00e9xito un nuevo robot paletizador en su ubicaci\u00f3n en Venlo, Pa\u00edses Bajos. El robot es parte del proceso de recepci\u00f3n [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-01T16:35:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_1.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1561\" \/>\n\t<meta property=\"og:image:height\" content=\"1115\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Arvato pone en funcionamiento un robot paletizador en Venlo\",\"datePublished\":\"2024-06-01T16:35:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/\"},\"wordCount\":627,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_1.6.24.jpg\",\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/\",\"name\":\"Arvato pone en funcionamiento un robot paletizador en Venlo - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_1.6.24.jpg\",\"datePublished\":\"2024-06-01T16:35:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_1.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_1.6.24.jpg\",\"width\":1561,\"height\":1115},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/06\\\/01\\\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arvato pone en funcionamiento un robot paletizador en Venlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arvato pone en funcionamiento un robot paletizador en Venlo - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/","og_locale":"es_ES","og_type":"article","og_title":"Arvato pone en funcionamiento un robot paletizador en Venlo - Loginfo24","og_description":"Arvato ha puesto en funcionamiento con \u00e9xito un nuevo robot paletizador en su ubicaci\u00f3n en Venlo, Pa\u00edses Bajos. El robot es parte del proceso de recepci\u00f3n [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-01T16:35:37+00:00","og_image":[{"width":1561,"height":1115,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_1.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/"},"author":{"name":"","@id":""},"headline":"Arvato pone en funcionamiento un robot paletizador en Venlo","datePublished":"2024-06-01T16:35:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/"},"wordCount":627,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_1.6.24.jpg","articleSection":["Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/","url":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/","name":"Arvato pone en funcionamiento un robot paletizador en Venlo - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_1.6.24.jpg","datePublished":"2024-06-01T16:35:37+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_1.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_1.6.24.jpg","width":1561,"height":1115},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/06\/01\/arvato-pone-en-funcionamiento-un-robot-paletizador-en-venlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Arvato pone en funcionamiento un robot paletizador en Venlo"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=65447"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6450"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=65447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=65447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=65447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}