{"id":65145,"date":"2024-05-06T20:33:13","date_gmt":"2024-05-06T18:33:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/"},"modified":"2024-05-06T20:33:13","modified_gmt":"2024-05-06T18:33:13","slug":"lantech-presenta-la-cerradora-de-cartones-cs-random-hs","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/","title":{"rendered":"Lantech presenta la cerradora de cartones CS Random HS"},"content":{"rendered":"<h5><strong>\u00bfCerrar cajas de diferentes formatos con alto rendimiento? La nueva cerradora de cartones CS Random HS lo hace posible. La m\u00e1quina de Lantech combina flexibilidad con rapidez y, por lo tanto, es adecuada incluso para aplicaciones donde se combinan varias l\u00edneas de envasado para el cierre.<\/strong><\/h5>\n<p>(Malden) Se mantiene la perpendicularidad de las cajas, que es importante para una cadena log\u00edstica eficiente y la estabilidad, y se evitan atascos de m\u00e1quina. La cerradora de cartones CS Random HS est\u00e1 disponible en versiones para cierre con cinta adhesiva o con cola caliente y se puede integrar f\u00e1cilmente en las l\u00edneas de envasado. Los usuarios alcanzan velocidades de hasta 25 ciclos por minuto (cinta adhesiva) o hasta 17 ciclos por minuto (cola caliente). A trav\u00e9s de una se\u00f1al anticipada o una c\u00e1mara en la alimentaci\u00f3n, la m\u00e1quina reconoce los formatos de cart\u00f3n que se presentan y se ajusta autom\u00e1ticamente a ellos. De este modo, se pueden procesar de forma flexible cajas con dimensiones entre 200 mm x 150 mm x 120 mm y 620 mm x 510 mm x 500 mm.<\/p>\n<h5><strong>Control absoluto sobre la caja<\/strong><\/h5>\n<p>Los sistemas de alimentaci\u00f3n ajustados autom\u00e1ticamente aseguran la correcta carga con suficiente espacio entre las cajas, evitando atascos. Las cajas se mueven sobre rodillos hacia bandas laterales con resorte que las fijan y se adaptan a las m\u00e1s peque\u00f1as variaciones en el ancho de la caja. La preplegado de las solapas cortas frontales evita da\u00f1os y optimiza la fiabilidad del proceso de envasado. Durante el transporte a trav\u00e9s de la m\u00e1quina, las solapas largas tambi\u00e9n se presionan hacia abajo y permanecen en esta posici\u00f3n hasta entrar en la unidad de cierre. Las cajas cerradas son absolutamente perpendiculares.<\/p>\n<p>Foto: \u00a9 Lantech<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCerrar cajas de diferentes formatos con alto rendimiento? La nueva cerradora de cartones CS Random HS lo hace posible. La m\u00e1quina de Lantech combina flexibilidad con<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-65145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lantech presenta la cerradora de cartones CS Random HS - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lantech presenta la cerradora de cartones CS Random HS - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"\u00bfCerrar cajas de diferentes formatos con alto rendimiento? La nueva cerradora de cartones CS Random HS lo hace posible. La m\u00e1quina de Lantech combina flexibilidad con [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T18:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Lantech_6.5.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1622\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lantech presenta la cerradora de cartones CS Random HS\",\"datePublished\":\"2024-05-06T18:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Lantech_6.5.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/\",\"name\":\"Lantech presenta la cerradora de cartones CS Random HS - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Lantech_6.5.24.jpg\",\"datePublished\":\"2024-05-06T18:33:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Lantech_6.5.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Lantech_6.5.24.jpg\",\"width\":1622,\"height\":911},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/05\\\/06\\\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lantech presenta la cerradora de cartones CS Random HS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lantech presenta la cerradora de cartones CS Random HS - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/","og_locale":"es_ES","og_type":"article","og_title":"Lantech presenta la cerradora de cartones CS Random HS - Loginfo24","og_description":"\u00bfCerrar cajas de diferentes formatos con alto rendimiento? La nueva cerradora de cartones CS Random HS lo hace posible. La m\u00e1quina de Lantech combina flexibilidad con [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-05-06T18:33:13+00:00","og_image":[{"width":1622,"height":911,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Lantech_6.5.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/"},"author":{"name":"","@id":""},"headline":"Lantech presenta la cerradora de cartones CS Random HS","datePublished":"2024-05-06T18:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Lantech_6.5.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/","url":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/","name":"Lantech presenta la cerradora de cartones CS Random HS - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Lantech_6.5.24.jpg","datePublished":"2024-05-06T18:33:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Lantech_6.5.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Lantech_6.5.24.jpg","width":1622,"height":911},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/05\/06\/lantech-presenta-la-cerradora-de-cartones-cs-random-hs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Lantech presenta la cerradora de cartones CS Random HS"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=65145"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/65145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6574"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=65145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=65145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=65145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}