{"id":64386,"date":"2024-03-01T19:42:13","date_gmt":"2024-03-01T18:42:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/"},"modified":"2024-03-01T19:42:13","modified_gmt":"2024-03-01T18:42:13","slug":"kuhnenagel-plane-la-adquisicion-de-city-zone-express","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/","title":{"rendered":"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express"},"content":{"rendered":"<div class=\"ppmodule_textblock pp_moduleblock\">\n<div class=\"text_companyprofile\">\n<div class=\"pp-overflow-hidden pp-min-width-5\">\n<h5>K\u00fchne+Nagel ha firmado un acuerdo para la adquisici\u00f3n de City Zone Express, una subsidiaria de Chasen Holdings Ltd., que cotiza en el Mainboard de la Bolsa de Singapur (SGX). City Zone Express tiene su sede en Malasia y fue fundada en 2006. La empresa emplea a m\u00e1s de 500 personas y opera en Malasia, Singapur, Vietnam, Tailandia y China. La adquisici\u00f3n de City Zone Express es inmediatamente rentable y ampliar\u00e1 estrat\u00e9gicamente la oferta de K\u00fchne+Nagel en el transporte terrestre transfronterizo en Asia.<\/h5>\n<p>(Schindellegi) Con una flota propia de 260 veh\u00edculos y un espacio de almacenamiento de 80,000 metros cuadrados, City Zone Express ofrece servicios de log\u00edstica transfronteriza en el sudeste asi\u00e1tico y hasta China. Combinado con la red y la experiencia log\u00edstica de K\u00fchne+Nagel, as\u00ed como la plataforma en l\u00ednea eTrucknow, los clientes de sectores emergentes como el comercio electr\u00f3nico, los semiconductores y la alta tecnolog\u00eda se beneficiar\u00e1n de una oferta ampliada.<\/p>\n<p>Dr. Hansj\u00f6rg Rodi, miembro de la direcci\u00f3n de K\u00fchne+Nagel International AG, responsable del \u00e1rea de transporte terrestre: \u00abDe acuerdo con nuestra hoja de ruta 2026, los mercados de crecimiento en Asia ofrecen una oportunidad atractiva para desarrollar a\u00fan m\u00e1s nuestros servicios de transporte terrestre. Con City Zone Express, adquirimos una empresa regional de renombre, cuya red y capacidades complementan nuestro propio potencial. As\u00ed, podemos apoyar mejor a nuestros clientes con soluciones de transporte terrestre personalizadas en mercados transfronterizos complejos.\u00bb<\/p>\n<h5>Demanda creciente de soluciones de transporte terrestre en el sudeste asi\u00e1tico<\/h5>\n<p>S. Pirithivaraj A\/L Selvarajoo, fundador de City Zone Express: \u00abEstamos muy contentos de convertirnos en parte del grupo K\u00fchne+Nagel, un l\u00edder de la industria en carga a\u00e9rea y mar\u00edtima y un proveedor de renombre en el transporte terrestre. Con nuestra presencia conjunta, podemos atender mejor la creciente demanda de soluciones de transporte terrestre en el sudeste asi\u00e1tico, una regi\u00f3n conocida como un importante centro de producci\u00f3n para industrias cr\u00edticas como la alta tecnolog\u00eda, los semiconductores y el comercio electr\u00f3nico.\u00bb<\/p>\n<h5>Sujeto a la aprobaci\u00f3n de las autoridades reguladoras<\/h5>\n<p>Se espera que el cierre de la transacci\u00f3n ocurra en los pr\u00f3ximos meses. La adquisici\u00f3n est\u00e1 sujeta a la aprobaci\u00f3n de las autoridades reguladoras competentes y de los accionistas de Chasen Holdings.<\/p>\n<p>Foto: \u00a9 K\u00fchne+Nagel<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fchne+Nagel ha firmado un acuerdo para la adquisici\u00f3n de City Zone Express, una subsidiaria de Chasen Holdings Ltd., que cotiza en el Mainboard de la Bolsa<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-64386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"K\u00fchne+Nagel ha firmado un acuerdo para la adquisici\u00f3n de City Zone Express, una subsidiaria de Chasen Holdings Ltd., que cotiza en el Mainboard de la Bolsa [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T18:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kuehne_Nagel_1.3.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1314\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express\",\"datePublished\":\"2024-03-01T18:42:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/\"},\"wordCount\":413,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kuehne_Nagel_1.3.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/\",\"name\":\"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kuehne_Nagel_1.3.24.jpg\",\"datePublished\":\"2024-03-01T18:42:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kuehne_Nagel_1.3.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kuehne_Nagel_1.3.24.jpg\",\"width\":1314,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2024\\\/03\\\/01\\\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/","og_locale":"es_ES","og_type":"article","og_title":"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express - Loginfo24","og_description":"K\u00fchne+Nagel ha firmado un acuerdo para la adquisici\u00f3n de City Zone Express, una subsidiaria de Chasen Holdings Ltd., que cotiza en el Mainboard de la Bolsa [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-03-01T18:42:13+00:00","og_image":[{"width":1314,"height":681,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kuehne_Nagel_1.3.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/"},"author":{"name":"","@id":""},"headline":"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express","datePublished":"2024-03-01T18:42:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/"},"wordCount":413,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kuehne_Nagel_1.3.24.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/","url":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/","name":"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kuehne_Nagel_1.3.24.jpg","datePublished":"2024-03-01T18:42:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kuehne_Nagel_1.3.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kuehne_Nagel_1.3.24.jpg","width":1314,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2024\/03\/01\/kuhnenagel-plane-la-adquisicion-de-city-zone-express\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"K\u00fchne+Nagel plane la adquisici\u00f3n de City Zone Express"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/64386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=64386"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/64386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/6868"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=64386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=64386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=64386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}