{"id":63688,"date":"2023-12-11T17:50:39","date_gmt":"2023-12-11T16:50:39","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/"},"modified":"2023-12-11T17:50:39","modified_gmt":"2023-12-11T16:50:39","slug":"la-red-ctl-refuerza-actividades-en-espana-con-seitrans","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/","title":{"rendered":"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS"},"content":{"rendered":"<h5><strong>La Cargo Trans Logistik (CTL) AG ampl\u00eda sus conexiones internacionales y a partir de ahora colabora con el especialista log\u00edstico espa\u00f1ol SEITRANS SA, una filial del grupo Italsempione. A trav\u00e9s de esta colaboraci\u00f3n, la cooperativa de carga fraccionada de tama\u00f1o medio ampl\u00eda los transportes de y hacia Espa\u00f1a para sus 180 empresas asociadas. CTL present\u00f3 a sus socios de red la cooperaci\u00f3n con SEITRANS SA y los planes de expansi\u00f3n para los pr\u00f3ximos a\u00f1os en su reuni\u00f3n estrat\u00e9gica internacional el 23 de noviembre.<\/strong><\/h5>\n<p>(Homburg\/Efze) La carga se env\u00eda a trav\u00e9s del hub CTL-West en D\u00fcsseldorf. Con salidas regulares, se garantiza la entrega en un plazo de 48 horas en los respectivos pa\u00edses. Anteriormente, el tiempo de tr\u00e1nsito era de hasta 72 horas.<\/p>\n<p>\u00abA trav\u00e9s de la nueva conexi\u00f3n, mejoramos significativamente los transportes de y hacia Espa\u00f1a para nuestros socios\u00bb, dice Francesco De Lauso, presidente del consejo de administraci\u00f3n de CTL, y a\u00f1ade: \u00abComo CTL, hemos alcanzado un tama\u00f1o que nos permite dar el paso m\u00e1s all\u00e1 de las fronteras alemanas y ofrecer transportes para nuestros socios en regiones estrat\u00e9gicamente importantes.\u00bb<\/p>\n<p>Con la colaboraci\u00f3n con SEITRANS SA, CTL crea una base a\u00fan m\u00e1s amplia para transportes internacionales exitosos entre la pen\u00ednsula ib\u00e9rica y Alemania. Con salidas regulares, las mercanc\u00edas se entregan en un m\u00e1ximo de dos d\u00edas en todo el pa\u00eds o en toda Espa\u00f1a, lo que significa al menos un tercio m\u00e1s r\u00e1pido que antes. Los transportes se realizan entre el hub de CTL en D\u00fcsseldorf y el hub de SEITRANS en Barcelona. Desde all\u00ed, se distribuye la carga fraccionada. Abraham Garcia Martinez, CFO de CTL y responsable de la internacionalizaci\u00f3n, dice: \u00abSe ha establecido un hito importante que sigue nuestra estrategia de internacionalizaci\u00f3n para los pr\u00f3ximos a\u00f1os. La mirada enfocada y la expansi\u00f3n en mercados extranjeros har\u00e1n que nuestros socios de red sean a\u00fan m\u00e1s competitivos. Los apoyaremos con medidas de ventas para que sean a\u00fan m\u00e1s exitosos a nivel internacional.\u00bb<\/p>\n<h5>Dos ubicaciones en Barcelona y Madrid<\/h5>\n<p>SEITRANS SA forma parte del grupo italiano Italsempione y cuenta con dos ubicaciones estrat\u00e9gicamente \u00f3ptimas en Barcelona y Madrid. La empresa se especializa en transporte terrestre, carga mar\u00edtima y a\u00e9rea, as\u00ed como en servicios de valor a\u00f1adido, y dispone de una red de hubs en toda Espa\u00f1a. Jose Javier Hern\u00e0ndez, gerente de red Europa en SEITRANS, dice sobre la cooperaci\u00f3n: \u00abJunto con CTL AG, creamos un valor a\u00f1adido significativo para nuestros clientes y fortalecemos la conexi\u00f3n con Europa Central y del Este. A trav\u00e9s de la red de carga fraccionada, podemos ampliar significativamente nuestros servicios en el \u00e1rea de carga consolidada y carga completa para nuestros clientes con plazos atractivos.\u00bb<\/p>\n<p>Foto: \u00a9 CTL \/ <em><strong>Descripci\u00f3n de la imagen:<\/strong> Colaboraci\u00f3n exitosa (de izq. a der.): Abraham Garcia Martinez, CFO de CTL, Tobias J\u00fcngling, jefe de desarrollo de red en CTL, Valerio Alpini, director de Italsempione spa., Francesco De Lauso, CEO de CTL, y Jos\u00e9 Javier Hern\u00e0ndez, gerente de red Europa en SEITRANS, se alegran de la cooperaci\u00f3n y de las oportunidades optimizadas para socios y clientes.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cargo Trans Logistik (CTL) AG ampl\u00eda sus conexiones internacionales y a partir de ahora colabora con el especialista log\u00edstico espa\u00f1ol SEITRANS SA, una filial del<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-63688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La red CTL refuerza actividades en Espa\u00f1a con SEITRANS - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Cargo Trans Logistik (CTL) AG ampl\u00eda sus conexiones internacionales y a partir de ahora colabora con el especialista log\u00edstico espa\u00f1ol SEITRANS SA, una filial del [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-11T16:50:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CTL_11.12.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1467\" \/>\n\t<meta property=\"og:image:height\" content=\"978\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS\",\"datePublished\":\"2023-12-11T16:50:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/\"},\"wordCount\":573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CTL_11.12.23.jpg\",\"articleSection\":[\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/\",\"name\":\"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CTL_11.12.23.jpg\",\"datePublished\":\"2023-12-11T16:50:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CTL_11.12.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CTL_11.12.23.jpg\",\"width\":1467,\"height\":978},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/12\\\/11\\\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/","og_locale":"es_ES","og_type":"article","og_title":"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS - Loginfo24","og_description":"La Cargo Trans Logistik (CTL) AG ampl\u00eda sus conexiones internacionales y a partir de ahora colabora con el especialista log\u00edstico espa\u00f1ol SEITRANS SA, una filial del [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-12-11T16:50:39+00:00","og_image":[{"width":1467,"height":978,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CTL_11.12.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/"},"author":{"name":"","@id":""},"headline":"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS","datePublished":"2023-12-11T16:50:39+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/"},"wordCount":573,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CTL_11.12.23.jpg","articleSection":["Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/","url":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/","name":"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CTL_11.12.23.jpg","datePublished":"2023-12-11T16:50:39+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CTL_11.12.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CTL_11.12.23.jpg","width":1467,"height":978},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/12\/11\/la-red-ctl-refuerza-actividades-en-espana-con-seitrans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"La red CTL refuerza actividades en Espa\u00f1a con SEITRANS"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/63688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=63688"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/63688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/7167"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=63688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=63688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=63688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}