{"id":63540,"date":"2023-11-28T20:20:36","date_gmt":"2023-11-28T19:20:36","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/"},"modified":"2023-11-28T20:20:36","modified_gmt":"2023-11-28T19:20:36","slug":"swisslog-automatiza-los-centros-logisticos-de-albert-heijn","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/","title":{"rendered":"Swisslog automatiza los centros log\u00edsticos de Albert Heijn"},"content":{"rendered":"<h5><strong>El nuevo centro de compras en casa (HSC) automatizado de Albert Heijn comenzar\u00e1 a operar en breve. El innovador proyecto se ha desarrollado en colaboraci\u00f3n con Swisslog e incluye, entre otras cosas, la automatizaci\u00f3n del almac\u00e9n utilizando un <\/strong><strong>sistema AutoStore<\/strong><strong>. En el HSC, los contenedores con mantequilla de cacahuete y tubos de pasta de dientes se desplazan autom\u00e1ticamente a trav\u00e9s de una ingeniosa red de rieles automatizados y finalmente terminan en las conocidas cajas de compras azules de los Pa\u00edses Bajos, que se entregan a los clientes en sus hogares. <\/strong><\/h5>\n<p>(Buchs\/Edegem) Marit van Egmond, CEO de Albert Heijn: \u00abComo el mayor proveedor de comercio electr\u00f3nico en el sector de supermercados del pa\u00eds, Albert Heijn se centra en la innovaci\u00f3n, el crecimiento y la sostenibilidad. Por lo tanto, estamos constantemente buscando nuevas tecnolog\u00edas que nos permitan trabajar de manera m\u00e1s inteligente y eficiente. Estoy orgullosa del nuevo paso que estamos dando en nuestro HSC en Barendrecht. Esto nos brinda otra oportunidad para crecer en el \u00e1mbito del comercio electr\u00f3nico y al mismo tiempo responde a la tensa situaci\u00f3n del mercado laboral.\u00bb<\/p>\n<p>Para el llenado autom\u00e1tico de las cajas de alimentos, Albert Heijn utiliza un sistema automatizado con robots y contenedores, capaz de reunir r\u00e1pidamente productos perecederos. El innovador proyecto tambi\u00e9n incluye el establecimiento de un centro de cumplimiento automatizado, desde el cual se entrega directamente a los hogares. El proyecto HSC abarca varios procesos, incluida la reserva, almacenamiento, clasificaci\u00f3n y carga con el sistema de transporte QuickMove, la integraci\u00f3n del software SynQ y la implementaci\u00f3n de AutoStore, un sistema de almacenamiento y preparaci\u00f3n de pedidos controlado por robots.<\/p>\n<h5>300 robots con 45,000 contenedores<\/h5>\n<p>Pronto, alrededor de 300 robots con un total de 45,000 contenedores se mover\u00e1n por el nuevo HSC para recoger los alimentos pedidos por los clientes. Esto facilitar\u00e1 el trabajo de los empleados. En el nuevo HSC, humanos y tecnolog\u00eda trabajan de la mano. Los empleados completan los pedidos, por ejemplo, a\u00f1adiendo productos frescos. Albert Heijn se ha asociado con Swisslog para la realizaci\u00f3n de este proyecto de automatizaci\u00f3n. Incluso despu\u00e9s de la implementaci\u00f3n, Swisslog sigue involucrado y ofrece apoyo y optimizaci\u00f3n a trav\u00e9s de soporte t\u00e9cnico. Esto es asegurado por un equipo dedicado de Swisslog en el lugar, que detecta posibles fallos, analiza datos y mejora procesos seg\u00fan sea necesario.<\/p>\n<h5><strong>El edificio funciona completamente sin gas<\/strong><\/h5>\n<p>El nuevo HSC no solo es innovador, sino tambi\u00e9n sostenible. Al igual que todos los dem\u00e1s centros de compras en casa y centros de distribuci\u00f3n de Albert Heijn, el edificio, que funciona completamente sin gas, recibir\u00e1 una certificaci\u00f3n BREEAM debido a varias soluciones energ\u00e9ticas sostenibles. Esto incluye el uso de 5,400 paneles solares, una c\u00e1mara frigor\u00edfica energ\u00e9ticamente eficiente, iluminaci\u00f3n LED eficiente y una bomba de calor para la climatizaci\u00f3n de las oficinas. Y con 63 estaciones de carga, el nuevo HSC est\u00e1 listo para la transici\u00f3n a la conducci\u00f3n el\u00e9ctrica.<\/p>\n<h5>El almac\u00e9n en Zwolle tambi\u00e9n ser\u00e1 automatizado<\/h5>\n<p>El HSC en Barendrecht comenzar\u00e1 pronto con este novedoso manejo de pedidos de clientes. Mientras tanto, ya han comenzado los trabajos en el pr\u00f3ximo HSC automatizado. Este se inaugurar\u00e1 a mediados de 2024 en Zwolle.<\/p>\n<p>Foto: \u00a9 Swisslog<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo centro de compras en casa (HSC) automatizado de Albert Heijn comenzar\u00e1 a operar en breve. El innovador proyecto se ha desarrollado en colaboraci\u00f3n con<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-63540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Swisslog automatiza los centros log\u00edsticos de Albert Heijn - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swisslog automatiza los centros log\u00edsticos de Albert Heijn - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El nuevo centro de compras en casa (HSC) automatizado de Albert Heijn comenzar\u00e1 a operar en breve. El innovador proyecto se ha desarrollado en colaboraci\u00f3n con [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T19:20:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swisslog_28.11.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1405\" \/>\n\t<meta property=\"og:image:height\" content=\"744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Swisslog automatiza los centros log\u00edsticos de Albert Heijn\",\"datePublished\":\"2023-11-28T19:20:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swisslog_28.11.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/\",\"name\":\"Swisslog automatiza los centros log\u00edsticos de Albert Heijn - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swisslog_28.11.23.jpg\",\"datePublished\":\"2023-11-28T19:20:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swisslog_28.11.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swisslog_28.11.23.jpg\",\"width\":1405,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/11\\\/28\\\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swisslog automatiza los centros log\u00edsticos de Albert Heijn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Swisslog automatiza los centros log\u00edsticos de Albert Heijn - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/","og_locale":"es_ES","og_type":"article","og_title":"Swisslog automatiza los centros log\u00edsticos de Albert Heijn - Loginfo24","og_description":"El nuevo centro de compras en casa (HSC) automatizado de Albert Heijn comenzar\u00e1 a operar en breve. El innovador proyecto se ha desarrollado en colaboraci\u00f3n con [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-11-28T19:20:36+00:00","og_image":[{"width":1405,"height":744,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swisslog_28.11.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/"},"author":{"name":"","@id":""},"headline":"Swisslog automatiza los centros log\u00edsticos de Albert Heijn","datePublished":"2023-11-28T19:20:36+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swisslog_28.11.23.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/","url":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/","name":"Swisslog automatiza los centros log\u00edsticos de Albert Heijn - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swisslog_28.11.23.jpg","datePublished":"2023-11-28T19:20:36+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swisslog_28.11.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swisslog_28.11.23.jpg","width":1405,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/11\/28\/swisslog-automatiza-los-centros-logisticos-de-albert-heijn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Swisslog automatiza los centros log\u00edsticos de Albert Heijn"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/63540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=63540"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/63540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/7221"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=63540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=63540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=63540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}