{"id":62190,"date":"2023-08-05T19:13:46","date_gmt":"2023-08-05T17:13:46","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/"},"modified":"2023-08-05T19:13:46","modified_gmt":"2023-08-05T17:13:46","slug":"schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/","title":{"rendered":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae"},"content":{"rendered":"<h5>Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para la telem\u00e1tica de remolques TrailerConnect\u00ae y contin\u00faa proporcionando a sus clientes farmac\u00e9uticos veh\u00edculos certificados de f\u00e1brica.<\/h5>\n<p>\u201eA trav\u00e9s de la certificaci\u00f3n de TrailerConnect\u00ae, nuestros clientes pueden presentar un certificado importante para sus auditor\u00edas GDP, que certifica la alta calidad y seguridad de nuestros productos\u201c, informa Boris Billich, miembro del consejo de ventas de Schmitz Cargobull AG. \u201eCon nuestro certificado GDP, podemos garantizar y documentar a los clientes la plena seguridad del proceso a lo largo de toda la cadena de procesos: desde la recopilaci\u00f3n de datos en el remolque, pasando por el almacenamiento de datos, hasta la representaci\u00f3n en el portal o la transmisi\u00f3n a trav\u00e9s de la API (interfaz para la transferencia de datos a sistemas externos).\u201c<\/p>\n<p>En 2013, la Comisi\u00f3n Europea introdujo las \u201eBuenas Pr\u00e1cticas de Distribuci\u00f3n de productos medicinales para uso humano\u201c (GDP) para garantizar la calidad y proteger contra medicamentos falsificados. Los fabricantes, mayoristas farmac\u00e9uticos y farmac\u00e9uticos deben someter sus procesos a auditor\u00edas GDP anuales. Los requisitos para la certificaci\u00f3n seg\u00fan GDP se revisan cada dos a\u00f1os. En una auditor\u00eda exhaustiva realizada por T\u00dcV S\u00fcd, el sistema de telem\u00e1tica de remolques TrailerConnect\u00ae de Schmitz Cargobull fue nuevamente certificado por otros dos a\u00f1os.<\/p>\n<h5>Diferentes \u00e1reas tem\u00e1ticas fueron examinadas en detalle<\/h5>\n<p>En el marco de la auditor\u00eda, se examinaron en detalle las \u00e1reas tem\u00e1ticas de descripci\u00f3n de interfaces, almacenamiento de datos, seguridad de datos, an\u00e1lisis de riesgos para el desarrollo de software\/actualizaci\u00f3n de software\/seguridad de datos, procesos organizativos y estructuras en la empresa, manual de software, especificaci\u00f3n de sensores, descripci\u00f3n de la empresa, el manual de gesti\u00f3n de calidad y la ISO 9001. Schmitz Cargobull cuenta as\u00ed con un certificado oficial con n\u00famero de verificaci\u00f3n y acreditaci\u00f3n de T\u00dcV S\u00fcd.<\/p>\n<p>Foto: \u00a9 Schmitz Cargobull<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para la telem\u00e1tica de remolques TrailerConnect\u00ae y contin\u00faa proporcionando a sus clientes farmac\u00e9uticos veh\u00edculos certificados de f\u00e1brica. \u201eA<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-62190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para la telem\u00e1tica de remolques TrailerConnect\u00ae y contin\u00faa proporcionando a sus clientes farmac\u00e9uticos veh\u00edculos certificados de f\u00e1brica. \u201eA [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-05T17:13:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_5.8.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1439\" \/>\n\t<meta property=\"og:image:height\" content=\"781\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae\",\"datePublished\":\"2023-08-05T17:13:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_5.8.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/\",\"name\":\"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_5.8.23.jpg\",\"datePublished\":\"2023-08-05T17:13:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_5.8.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schmitz_Cargobull_5.8.23.jpg\",\"width\":1439,\"height\":781},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/08\\\/05\\\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/","og_locale":"es_ES","og_type":"article","og_title":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae - Loginfo24","og_description":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para la telem\u00e1tica de remolques TrailerConnect\u00ae y contin\u00faa proporcionando a sus clientes farmac\u00e9uticos veh\u00edculos certificados de f\u00e1brica. \u201eA [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-08-05T17:13:46+00:00","og_image":[{"width":1439,"height":781,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_5.8.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/"},"author":{"name":"","@id":""},"headline":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae","datePublished":"2023-08-05T17:13:46+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_5.8.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/","url":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/","name":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_5.8.23.jpg","datePublished":"2023-08-05T17:13:46+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_5.8.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schmitz_Cargobull_5.8.23.jpg","width":1439,"height":781},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/08\/05\/schmitz-cargobull-amplia-con-exito-el-certificado-gdp-para-trailerconnect\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Schmitz Cargobull ampl\u00eda con \u00e9xito el certificado GDP para TrailerConnect\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/62190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=62190"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/62190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/7797"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=62190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=62190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=62190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}