{"id":62028,"date":"2023-07-20T10:59:00","date_gmt":"2023-07-20T08:59:00","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/"},"modified":"2023-07-20T10:59:00","modified_gmt":"2023-07-20T08:59:00","slug":"libro-la-reinvencion-de-la-logistica-de-peter-h-voss","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/","title":{"rendered":"Libro \u00abLa reinvenci\u00f3n de la log\u00edstica\u00bb de Peter H. Voss"},"content":{"rendered":"<h5>Peter H. Voss como editor y diversos coautores del entorno del Club of Logistics que \u00e9l dirige han publicado un interesante libro titulado \u00abLa reinvenci\u00f3n de la log\u00edstica\u00bb. Como eBook, ya est\u00e1 disponible en el comercio de libros habitual. La versi\u00f3n impresa encuadernada seguir\u00e1 pronto y se puede reservar. Varios autores analizan el cambio en la log\u00edstica, que se aceler\u00f3 durante la pandemia de Corona, pero que ya hab\u00eda comenzado antes. El libro ha sido publicado por SpringerGabler.<\/h5>\n<p>(Dortmund) Durante siglos, la log\u00edstica tuvo la tarea de transportar bienes de todo tipo por tierra, agua y aire a sus destinos. Con el comienzo del tercer milenio, el \u00e1mbito de competencia de la industria log\u00edstica se ampl\u00eda a todos los <em class=\"element-background-basic-colors marker\" data-color=\"gelb-light\">objetos en movimiento<\/em>, ya sean de naturaleza material o inmaterial. En este sentido, en una inversi\u00f3n de la l\u00f3gica tradicional, la log\u00edstica tendr\u00e1 cada vez m\u00e1s la intenci\u00f3n de evitar el transporte de bienes y otros objetos materiales para minimizar la carga para las personas y el medio ambiente. Las tecnolog\u00edas digitales, nuevos sistemas de propulsi\u00f3n y modelos de negocio innovadores conducir\u00e1n a una log\u00edstica que no se presenta como un freno, sino como un centro de control para la gesti\u00f3n ambientalmente consciente del suministro de bienes, materias primas, energ\u00eda e informaci\u00f3n a la poblaci\u00f3n. Las contribuciones de este libro analizan de manera ilustrativa los cambios inminentes y exploran perspectivas innovadoras para la industria log\u00edstica.<\/p>\n<h5><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-23549 size-medium\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023_2-218x300.jpg\" alt=\"\" width=\"218\" height=\"300\" \/><\/h5>\n<h5>E-Book ya disponible - La versi\u00f3n impresa encuadernada aparecer\u00e1 pronto<\/h5>\n<p>El libro est\u00e1 disponible en todas las librer\u00edas conocidas, tanto en formato h\u00edbrido como en l\u00ednea. El eBook ya se puede descargar por un precio de 29.99 euros. La versi\u00f3n impresa encuadernada se puede reservar por 39.99 euros y deber\u00eda ser entregada en las pr\u00f3ximas dos semanas.<\/p>\n<h4><a href=\"https:\/\/www.springerprofessional.de\/die-neuerfindung-der-logistik\/25420116\" target=\"_blank\" rel=\"noopener\">\u00cdndice y m\u00e1s detalles<\/a><\/h4>\n<h4><a href=\"https:\/\/link.springer.com\/book\/10.1007\/978-3-658-41084-1\" target=\"_blank\" rel=\"noopener\">Aqu\u00ed se puede pedir el libro<\/a><\/h4>\n<p>Foto: \u00a9 Springer\/Gabler<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peter H. Voss como editor y diversos coautores del entorno del Club of Logistics que \u00e9l dirige han publicado un interesante libro titulado \u00abLa reinvenci\u00f3n de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-62028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Libro &quot;La reinvenci\u00f3n de la log\u00edstica&quot; de Peter H. Voss - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libro &quot;La reinvenci\u00f3n de la log\u00edstica&quot; de Peter H. Voss - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Peter H. Voss como editor y diversos coautores del entorno del Club of Logistics que \u00e9l dirige han publicado un interesante libro titulado \u00abLa reinvenci\u00f3n de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T08:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"692\" \/>\n\t<meta property=\"og:image:height\" content=\"461\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Libro \u00abLa reinvenci\u00f3n de la log\u00edstica\u00bb de Peter H. Voss\",\"datePublished\":\"2023-07-20T08:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/\"},\"wordCount\":344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Voss_20.7.2023.jpg\",\"articleSection\":[\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/\",\"name\":\"Libro \\\"La reinvenci\u00f3n de la log\u00edstica\\\" de Peter H. Voss - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Voss_20.7.2023.jpg\",\"datePublished\":\"2023-07-20T08:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Voss_20.7.2023.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Voss_20.7.2023.jpg\",\"width\":692,\"height\":461},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/07\\\/20\\\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libro \u00abLa reinvenci\u00f3n de la log\u00edstica\u00bb de Peter H. Voss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libro \"La reinvenci\u00f3n de la log\u00edstica\" de Peter H. Voss - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/","og_locale":"es_ES","og_type":"article","og_title":"Libro \"La reinvenci\u00f3n de la log\u00edstica\" de Peter H. Voss - Loginfo24","og_description":"Peter H. Voss como editor y diversos coautores del entorno del Club of Logistics que \u00e9l dirige han publicado un interesante libro titulado \u00abLa reinvenci\u00f3n de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-07-20T08:59:00+00:00","og_image":[{"width":692,"height":461,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/"},"author":{"name":"","@id":""},"headline":"Libro \u00abLa reinvenci\u00f3n de la log\u00edstica\u00bb de Peter H. Voss","datePublished":"2023-07-20T08:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/"},"wordCount":344,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023.jpg","articleSection":["Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/","url":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/","name":"Libro \"La reinvenci\u00f3n de la log\u00edstica\" de Peter H. Voss - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023.jpg","datePublished":"2023-07-20T08:59:00+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Voss_20.7.2023.jpg","width":692,"height":461},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/07\/20\/libro-la-reinvencion-de-la-logistica-de-peter-h-voss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Libro \u00abLa reinvenci\u00f3n de la log\u00edstica\u00bb de Peter H. Voss"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/62028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=62028"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/62028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/7865"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=62028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=62028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=62028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}