{"id":61397,"date":"2023-05-10T20:57:28","date_gmt":"2023-05-10T18:57:28","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/"},"modified":"2023-05-10T20:57:28","modified_gmt":"2023-05-10T18:57:28","slug":"emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/","title":{"rendered":"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local"},"content":{"rendered":"<h5>La empresa de transporte internacional Emons, con sede en Colonia, automatizar\u00e1 y optimizar\u00e1 la disposici\u00f3n del transporte local en m\u00e1s de 20 ubicaciones con Smartlane Transport Intelligence, una soluci\u00f3n de disposici\u00f3n SaaS de la empresa de M\u00fanich Smartlane GmbH.<\/h5>\n<p>La software ya apoya con \u00e9xito en el piloto en tres ubicaciones de Emons. La empresa de transporte Emons utilizar\u00e1 en el futuro la soluci\u00f3n SaaS Smartlane Transport Intelligence para la disposici\u00f3n del transporte local. La integraci\u00f3n de Smartlane Transport Intelligence en EuroMistral\u00ae ya se realiz\u00f3 en un proyecto piloto anterior, lo que simplifica y acelera significativamente la implementaci\u00f3n en las 20 ubicaciones restantes con una flota total de transporte local de m\u00e1s de 1,000 veh\u00edculos.<\/p>\n<h5>Explotar potenciales<\/h5>\n<p>\u00abCon la implementaci\u00f3n interlocal de una soluci\u00f3n de expertos espec\u00edficamente para la disposici\u00f3n, se pretende explotar potenciales significativos y hacer que el proceso de disposici\u00f3n sea m\u00e1s transparente y sostenible para el futuro\u00bb, dice Ralf Wieland, director general\/CEO de Emons.<\/p>\n<p>Foto: \u00a9 Emons \/ <em><strong>Pie de foto:<\/strong> Ralf Wieland, CEO de Emons y Monja M\u00fchling, CEO de Fastlane, sellan la colaboraci\u00f3n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa de transporte internacional Emons, con sede en Colonia, automatizar\u00e1 y optimizar\u00e1 la disposici\u00f3n del transporte local en m\u00e1s de 20 ubicaciones con Smartlane Transport<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-61397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emons apuesta por Smartlane en la disposici\u00f3n del transporte local - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La empresa de transporte internacional Emons, con sede en Colonia, automatizar\u00e1 y optimizar\u00e1 la disposici\u00f3n del transporte local en m\u00e1s de 20 ubicaciones con Smartlane Transport [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-10T18:57:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Emons_Smartlane_10.5.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1042\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local\",\"datePublished\":\"2023-05-10T18:57:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/\"},\"wordCount\":204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Emons_Smartlane_10.5.23.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/\",\"name\":\"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Emons_Smartlane_10.5.23.jpg\",\"datePublished\":\"2023-05-10T18:57:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Emons_Smartlane_10.5.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Emons_Smartlane_10.5.23.jpg\",\"width\":1042,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/05\\\/10\\\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/","og_locale":"es_ES","og_type":"article","og_title":"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local - Loginfo24","og_description":"La empresa de transporte internacional Emons, con sede en Colonia, automatizar\u00e1 y optimizar\u00e1 la disposici\u00f3n del transporte local en m\u00e1s de 20 ubicaciones con Smartlane Transport [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-05-10T18:57:28+00:00","og_image":[{"width":1042,"height":669,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Emons_Smartlane_10.5.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/"},"author":{"name":"","@id":""},"headline":"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local","datePublished":"2023-05-10T18:57:28+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/"},"wordCount":204,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Emons_Smartlane_10.5.23.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/","url":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/","name":"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Emons_Smartlane_10.5.23.jpg","datePublished":"2023-05-10T18:57:28+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Emons_Smartlane_10.5.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Emons_Smartlane_10.5.23.jpg","width":1042,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/05\/10\/emons-apuesta-por-smartlane-en-la-disposicion-del-transporte-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Emons apuesta por Smartlane en la disposici\u00f3n del transporte local"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/61397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=61397"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/61397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/8175"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=61397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=61397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=61397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}