{"id":61266,"date":"2023-04-24T09:13:04","date_gmt":"2023-04-24T07:13:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/"},"modified":"2023-04-24T09:13:04","modified_gmt":"2023-04-24T07:13:04","slug":"la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/","title":{"rendered":"La plataforma de datos KV4.0 inicia operaciones con socios"},"content":{"rendered":"<h5><strong>Despu\u00e9s del exitoso lanzamiento de la plataforma de datos KV4.0 en marzo, los primeros socios han comenzado a intercambiar datos de producci\u00f3n para mejorar la transparencia en la cadena de suministro. La nueva plataforma de datos conecta por primera vez a todos los actores del transporte combinado.<\/strong><\/h5>\n<p>(Frankfurt) Los clientes de DXI, que incluyen transportistas y operadores de KV, terminales y empresas ferroviarias, comenzaron en marzo a intercambiar datos en tiempo real a trav\u00e9s de la plataforma de datos KV4.0. La plataforma se basa en el est\u00e1ndar de intercambio de datos #EDIGES y permite el acceso a horarios, reservas, estado de terminales, trayectos de tren, as\u00ed como a los tramos de carretera antes y despu\u00e9s. El intercambio de datos se realiza en tiempo real y sin barreras, pero siempre dentro de un c\u00edrculo de distribuci\u00f3n autorizado. La conexi\u00f3n t\u00e9cnica \u00fanica a la plataforma de datos KV4.0 tambi\u00e9n permite el intercambio de datos de pron\u00f3stico, como el Tiempo Estimado de Recogida (ETP), entre los socios involucrados, para mejorar la transparencia en la cadena de suministro. Los interesados pueden encontrar informaci\u00f3n detallada sobre la oferta de servicios de la empresa en la nueva p\u00e1gina web www.dx-intermodal.com.<\/p>\n<h5><a href=\"https:\/\/www.speditionssoftware.eu\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22862 aligncenter\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/catkin_Loginfo24_11.4.23_2.png\" alt=\"\" width=\"562\" height=\"138\" \/><\/a><\/h5>\n<h5>Plataforma de datos intersistemas<\/h5>\n<p>DXI es la nueva empresa encargada de operar la plataforma de datos KV4.0, que conecta por primera vez a todos los actores del transporte combinado a nivel de datos. Los socios son los operadores combinados Hupac y Kombiverkehr, las empresas de transporte Hoyer y Paneuropa, la empresa ferroviaria Lokomotion y el terminal combinado Ludwigshafen. La empresa, fundada a finales de junio de 2022, surgi\u00f3 del proyecto de investigaci\u00f3n \u00abDigitalizaci\u00f3n de cadenas de suministro intermodales - KV4.0\u00bb, que ha creado una plataforma de datos intersistemas para el transporte combinado.<\/p>\n<p>Foto: \u00a9 Kombiverkehr\/DXI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s del exitoso lanzamiento de la plataforma de datos KV4.0 en marzo, los primeros socios han comenzado a intercambiar datos de producci\u00f3n para mejorar la transparencia<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-61266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La plataforma de datos KV4.0 inicia operaciones con socios - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La plataforma de datos KV4.0 inicia operaciones con socios - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s del exitoso lanzamiento de la plataforma de datos KV4.0 en marzo, los primeros socios han comenzado a intercambiar datos de producci\u00f3n para mejorar la transparencia [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-24T07:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kombiverkehr_24.4.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1219\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La plataforma de datos KV4.0 inicia operaciones con socios\",\"datePublished\":\"2023-04-24T07:13:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kombiverkehr_24.4.23.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/\",\"name\":\"La plataforma de datos KV4.0 inicia operaciones con socios - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kombiverkehr_24.4.23.jpg\",\"datePublished\":\"2023-04-24T07:13:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kombiverkehr_24.4.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Kombiverkehr_24.4.23.jpg\",\"width\":1219,\"height\":783},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/04\\\/24\\\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plataforma de datos KV4.0 inicia operaciones con socios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La plataforma de datos KV4.0 inicia operaciones con socios - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/","og_locale":"es_ES","og_type":"article","og_title":"La plataforma de datos KV4.0 inicia operaciones con socios - Loginfo24","og_description":"Despu\u00e9s del exitoso lanzamiento de la plataforma de datos KV4.0 en marzo, los primeros socios han comenzado a intercambiar datos de producci\u00f3n para mejorar la transparencia [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-04-24T07:13:04+00:00","og_image":[{"width":1219,"height":783,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kombiverkehr_24.4.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/"},"author":{"name":"","@id":""},"headline":"La plataforma de datos KV4.0 inicia operaciones con socios","datePublished":"2023-04-24T07:13:04+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kombiverkehr_24.4.23.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/","url":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/","name":"La plataforma de datos KV4.0 inicia operaciones con socios - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kombiverkehr_24.4.23.jpg","datePublished":"2023-04-24T07:13:04+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kombiverkehr_24.4.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Kombiverkehr_24.4.23.jpg","width":1219,"height":783},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/04\/24\/la-plataforma-de-datos-kv4-0-inicia-operaciones-con-socios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"La plataforma de datos KV4.0 inicia operaciones con socios"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/61266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=61266"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/61266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/8229"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=61266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=61266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=61266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}