{"id":60281,"date":"2023-01-21T12:24:57","date_gmt":"2023-01-21T11:24:57","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/"},"modified":"2023-01-21T12:24:57","modified_gmt":"2023-01-21T11:24:57","slug":"las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/","title":{"rendered":"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes"},"content":{"rendered":"<div class=\"row\">\n<div class=\"offset-lg-2 col-lg-8\">\n<h5>Con base en los datos hasta la mitad del a\u00f1o pasado, la <em>Agencia Federal de Redes<\/em> ha publicado hoy cifras sobre el desarrollo en los mercados ferroviarios <a href=\"https:\/\/www.bundesnetzagentur.de\/SharedDocs\/Pressemitteilungen\/DE\/2023\/20230119_MarktuntersuchungEisenbahnen.html?nn=265778\">publicadas<\/a>. La red de ferrocarriles europeos (NEE), que tambi\u00e9n opera bajo la etiqueta LAS FERROCARRILES DE CARGA, tiene ideas claras al respecto y se pronuncia al respecto.<\/h5>\n<p>(Berl\u00edn) A diferencia del transporte de pasajeros, el transporte de mercanc\u00edas solo experiment\u00f3 ca\u00eddas serias, pero no sostenibles, en el rendimiento del tr\u00e1fico en la primavera de 2020. El director general Peter Westenberger se pronuncia en nombre de LAS FERROCARRILES DE CARGA sobre el informe y las consecuencias para la pol\u00edtica de la siguiente manera:<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-lg-8\">\n<blockquote>\n<div id=\"attachment_22230\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22230\" class=\"size-medium wp-image-22230\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23_1-300x264.jpg\" alt=\"\" width=\"300\" height=\"264\" \/><p id=\"caption-attachment-22230\" class=\"wp-caption-text\">Peter Westenberger<\/p><\/div>\n<p>\u00abLAS FERROCARRILES DE CARGA han suministrado de manera estable a la industria y el comercio en las m\u00faltiples crisis de los \u00faltimos a\u00f1os y han manejado tareas adicionales, especialmente despu\u00e9s del inicio de la guerra en Ucrania, sin ruido. Las cifras detalladas publicadas por la Agencia Federal de Redes para el a\u00f1o anterior dan importantes indicios para el dise\u00f1o de las condiciones marco por parte del gobierno y la necesidad de acci\u00f3n en la empresa de transporte ferroviario de mercanc\u00edas de propiedad estatal DB Cargo.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan las encuestas de la Agencia Federal de Redes, en 2021 se logr\u00f3 un rendimiento de tr\u00e1fico r\u00e9cord de 139 mil millones de kil\u00f3metros-tonelada en la v\u00eda. La participaci\u00f3n de la v\u00eda en el mercado de transporte de mercanc\u00edas super\u00f3 por primera vez en mucho tiempo el 20 por ciento. El crecimiento fue nuevamente impulsado por las FERROCARRILES DE CARGA que no pertenecen a DB. Aumentaron su participaci\u00f3n en el transporte ferroviario de mercanc\u00edas en tres mil millones de kil\u00f3metros-tonelada a m\u00e1s del 58 por ciento.<\/p>\n<p>&nbsp;<\/p>\n<p>El transporte de mercanc\u00edas sigue siendo intensamente competitivo, tanto entre carretera y ferrocarril como dentro del ferrocarril. En el mercado de transporte ferroviario de mercanc\u00edas de 5,8 mil millones de euros, el 87 por ciento de las empresas generaron juntas un super\u00e1vit de 112 millones de euros. Sin embargo, esto fue ampliamente compensado en una visi\u00f3n general del mercado por los d\u00e9ficits producidos principalmente en el transporte de mercanc\u00edas de DB, que alcanzaron los 385 millones de euros en el resto del 13 por ciento de las empresas. El apoyo estatal durante la crisis del coronavirus ayud\u00f3 a todas las empresas, mientras que las empresas de DB, a pesar de los altos ingresos de otros programas de apoyo, continuaron operando en el mercado con precios que no cubr\u00edan los costos. Para hacer que el crecimiento en la v\u00eda sea sostenible y lo m\u00e1s independiente posible de subsidios estatales, se deben aumentar la eficiencia y la atractividad para inversiones en nuevas ofertas de transporte.<\/p>\n<p>&nbsp;<\/p>\n<p>Ya en el segundo a\u00f1o de la pandemia, comenz\u00f3 el aumento desproporcionado del precio de la electricidad para el transporte ferroviario de mercanc\u00edas, que se opera en un 95 por ciento con electricidad, lo que afecta especialmente al mercado. Mientras que en 2021 el gobierno a\u00fan apoy\u00f3 a la industria con ayudas por el coronavirus, en 2022, en la crisis de precios de la electricidad, esto estuvo ausente hasta el final en el ferrocarril, que es amigable con el clima. Al mismo tiempo, las FERROCARRILES DE CARGA, al igual que en a\u00f1os anteriores, tuvieron que contratar m\u00e1s personal no solo para el aumento del tr\u00e1fico, sino sobre todo debido a la mala disponibilidad de la infraestructura, lo que aument\u00f3 sus costos. Cuando los trenes tienen que dar un rodeo de 200 o 300 kil\u00f3metros debido a obras, se explica la evaluaci\u00f3n de que actualmente se necesitan entre un 20 y un 30 por ciento m\u00e1s de recursos en las FERROCARRILES DE CARGA exclusivamente para hacer frente a la mala calidad de la infraestructura y que faltan para nuevas ofertas.<\/p>\n<p>&nbsp;<\/p>\n<p>Si la pol\u00edtica quiere la transformaci\u00f3n del transporte y los efectos clim\u00e1ticos de la reubicaci\u00f3n al ferrocarril, debe eliminar r\u00e1pidamente los d\u00e9ficits en la infraestructura ferroviaria, priorizar la expansi\u00f3n de la red ferroviaria, enfocar las condiciones marco de transporte para camiones y ferrocarriles en la reubicaci\u00f3n del tr\u00e1fico en lugar de en a\u00fan m\u00e1s transporte de mercanc\u00edas por carretera, financiar inversiones que aumenten la eficiencia en lugar de subsidios a los costos operativos y sanear DB Cargo.\u00bb<\/p><\/blockquote>\n<p>Fotos: \u00a9 Red de Ferrocarriles Europeos NEE<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con base en los datos hasta la mitad del a\u00f1o pasado, la Agencia Federal de Redes ha publicado hoy cifras sobre el desarrollo en los mercados<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-60281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Con base en los datos hasta la mitad del a\u00f1o pasado, la Agencia Federal de Redes ha publicado hoy cifras sobre el desarrollo en los mercados [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-21T11:24:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1217\" \/>\n\t<meta property=\"og:image:height\" content=\"737\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes\",\"datePublished\":\"2023-01-21T11:24:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/\"},\"wordCount\":770,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_20.1.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/\",\"name\":\"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_20.1.23.jpg\",\"datePublished\":\"2023-01-21T11:24:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_20.1.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NEE_20.1.23.jpg\",\"width\":1217,\"height\":737},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2023\\\/01\\\/21\\\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/","og_locale":"es_ES","og_type":"article","og_title":"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes - Loginfo24","og_description":"Con base en los datos hasta la mitad del a\u00f1o pasado, la Agencia Federal de Redes ha publicado hoy cifras sobre el desarrollo en los mercados [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-01-21T11:24:57+00:00","og_image":[{"width":1217,"height":737,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/"},"author":{"name":"","@id":""},"headline":"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes","datePublished":"2023-01-21T11:24:57+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/"},"wordCount":770,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/","url":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/","name":"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23.jpg","datePublished":"2023-01-21T11:24:57+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NEE_20.1.23.jpg","width":1217,"height":737},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2023\/01\/21\/las-ferrocarriles-de-carga-con-declaracion-a-la-agencia-federal-de-redes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"LAS FERROCARRILES DE CARGA con declaraci\u00f3n a la Agencia Federal de Redes"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/60281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=60281"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/60281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/8640"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=60281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=60281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=60281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}