{"id":59861,"date":"2022-12-11T10:15:43","date_gmt":"2022-12-11T09:15:43","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/"},"modified":"2022-12-11T10:15:43","modified_gmt":"2022-12-11T09:15:43","slug":"nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/","title":{"rendered":"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia"},"content":{"rendered":"<h5>La NOSTA Logistik Sp. z o.o., una empresa del NOSTA Group con sede en Osnabr\u00fcck, acelera su expansi\u00f3n y ampl\u00eda su gama de servicios en el mercado polaco. Con el objetivo de expandir sus actividades de carga y carga a\u00e9rea a nivel mundial, el proveedor de log\u00edstica de servicio completo acaba de abrir una nueva oficina en Varsovia.<\/h5>\n<p>(Osnabr\u00fcck\/Varsovia) De este modo, el especialista en log\u00edstica ahora est\u00e1 presente con un total de cuatro sucursales en Polonia. \u00abEn el negocio internacional y, por lo tanto, para aumentar nuestra competitividad, la carga a\u00e9rea es de vital importancia\u00bb, dice Daniel G\u0142uchowski, l\u00edder del equipo de carga a\u00e9rea en NOSTA Logistik Sp. z o.o. \u00abEn respuesta a los desaf\u00edos del mercado y las necesidades de las empresas que buscan oportunidades de crecimiento en mercados internacionales, ahora ampliamos nuestra gama de productos para incluir el \u00e1rea de carga a\u00e9rea\u00bb, contin\u00faa G\u0142uchowski. Hasta ahora, NOSTA ha estado activa principalmente en Polonia en el \u00e1mbito de los servicios de transporte por carretera y mar\u00edtimo. La apertura de una oficina propia en Varsovia, un importante nudo de transporte con la mayor terminal de carga a\u00e9rea de Polonia, es de importancia estrat\u00e9gica.<\/p>\n<h5>Servicio integral para env\u00edos de carga a\u00e9rea<\/h5>\n<p>Los servicios ofrecidos en la nueva sucursal de Varsovia est\u00e1n dise\u00f1ados para proporcionar a los clientes que env\u00edan sus env\u00edos de importaci\u00f3n y exportaci\u00f3n por carga a\u00e9rea un servicio integral, incluidos los env\u00edos expr\u00e9s. Adem\u00e1s de los servicios de transporte, NOSTA tambi\u00e9n se encarga de la consolidaci\u00f3n de env\u00edos de carga a\u00e9rea, la realizaci\u00f3n de cargas directas y vuelos ch\u00e1rter (parciales o completos), as\u00ed como servicios de despacho, despacho aduanero, transporte de\/ hacia aeropuertos y entregas de puerta a puerta. La oficina de NOSTA en Varsovia est\u00e1 especializada en la organizaci\u00f3n y ejecuci\u00f3n de transportes a\u00e9reos de todos los sectores, incluidos mercanc\u00edas peligrosas y transportes cr\u00edticos en tiempo.<\/p>\n<p>Gracias a la colaboraci\u00f3n con numerosas aerol\u00edneas y socios locales e internacionales de confianza, se pueden realizar transportes a nivel mundial a lo largo de la cadena de suministro. El enfoque de NOSTA para las entregas de carga a\u00e9rea son actualmente los EE. UU., aunque se pueden atender todos los destinos internacionales. En la organizaci\u00f3n de los transportes a EE. UU., la oficina de Varsovia ser\u00e1 apoyada en el futuro por la sucursal de NOSTA en Bensenville, cerca de Chicago, donde el especialista en log\u00edstica cuenta con un propio almac\u00e9n aduanero. Con su s\u00f3lida red log\u00edstica europea, NOSTA ofrece a partir de ahora un servicio de carga consolidada de y hacia Chicago, incluida la aduana y la entrega a destinatarios en Estados Unidos y Polonia.<\/p>\n<p>NOSTA Logistik Sp. z o.o. ha estado presente en el mercado polaco con sus servicios de transporte desde 2014. La nueva oficina en Varsovia es la cuarta ubicaci\u00f3n de NOSTA en el segundo pa\u00eds vecino m\u00e1s grande de Alemania, despu\u00e9s de Sopot, Wroc\u0142aw y S\u0142ubice. El negocio principal se centra principalmente en la organizaci\u00f3n de transportes por carretera (FTL, LTL, combinados, refrigerados, a granel, log\u00edstica de paletas) hacia Alemania y otros pa\u00edses de Europa occidental. Bas\u00e1ndose en una red mundial de m\u00e1s de 40 sucursales, la empresa tambi\u00e9n se encarga de transportes mar\u00edtimos (LCL, FCL, transporte de ida y vuelta), carga a\u00e9rea, ferroviaria y de almacenamiento. Cabe mencionar que NOSTA, como una de las pocas empresas de transporte en Polonia, tambi\u00e9n organiza entregas de bienes de consumo de r\u00e1pido movimiento (FMCG) para el comercio minorista en el marco de campa\u00f1as promocionales y estacionales. Otra fortaleza de la empresa son las soluciones de transporte especializadas para la industria metal\u00fargica y del papel.<\/p>\n<h5>Se buscan nuevos empleados para carga a\u00e9rea<\/h5>\n<p>Actualmente, NOSTA est\u00e1 contratando empleados para la carga a\u00e9rea en la nueva sucursal de Varsovia. En \u00faltima instancia, se espera que aqu\u00ed trabaje un equipo s\u00f3lido de varios especialistas con experiencia en el despacho de carga a\u00e9rea.<\/p>\n<p>Foto: \u00a9 NOSTA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NOSTA Logistik Sp. z o.o., una empresa del NOSTA Group con sede en Osnabr\u00fcck, acelera su expansi\u00f3n y ampl\u00eda su gama de servicios en el<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1561],"tags":[],"class_list":["post-59861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La NOSTA Logistik Sp. z o.o., una empresa del NOSTA Group con sede en Osnabr\u00fcck, acelera su expansi\u00f3n y ampl\u00eda su gama de servicios en el [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-11T09:15:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NOSTA_11.12.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia\",\"datePublished\":\"2022-12-11T09:15:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/\"},\"wordCount\":726,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NOSTA_11.12.22.jpg\",\"articleSection\":[\"Air Freight\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/\",\"name\":\"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NOSTA_11.12.22.jpg\",\"datePublished\":\"2022-12-11T09:15:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NOSTA_11.12.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/NOSTA_11.12.22.jpg\",\"width\":1599,\"height\":820},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/12\\\/11\\\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/","og_locale":"es_ES","og_type":"article","og_title":"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia - Loginfo24","og_description":"La NOSTA Logistik Sp. z o.o., una empresa del NOSTA Group con sede en Osnabr\u00fcck, acelera su expansi\u00f3n y ampl\u00eda su gama de servicios en el [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-12-11T09:15:43+00:00","og_image":[{"width":1599,"height":820,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NOSTA_11.12.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/"},"author":{"name":"","@id":""},"headline":"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia","datePublished":"2022-12-11T09:15:43+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/"},"wordCount":726,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NOSTA_11.12.22.jpg","articleSection":["Air Freight","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/","url":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/","name":"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NOSTA_11.12.22.jpg","datePublished":"2022-12-11T09:15:43+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NOSTA_11.12.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/NOSTA_11.12.22.jpg","width":1599,"height":820},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/12\/11\/nosta-group-abre-una-ubicacion-de-carga-aerea-en-varsovia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"NOSTA Group abre una ubicaci\u00f3n de carga a\u00e9rea en Varsovia"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/59861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=59861"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/59861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/8816"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=59861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=59861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=59861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}