{"id":57344,"date":"2022-07-19T19:10:32","date_gmt":"2022-07-19T17:10:32","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/"},"modified":"2022-07-19T19:10:32","modified_gmt":"2022-07-19T17:10:32","slug":"trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/","title":{"rendered":"trans-o-flex gana el premio EURODIS a la mejor calidad"},"content":{"rendered":"<h5><strong>Por sexta vez consecutiva, el servicio expr\u00e9s trans-o-flex ha recibido en 2022 el premio anual a la mejor calidad operativa en la red EURODIS, que es la red para el transporte internacional conjunto de paquetes y paletas en 36 pa\u00edses europeos. Los criterios para la concesi\u00f3n del premio son numerosas mediciones de calidad. As\u00ed, a lo largo de un a\u00f1o, se recogen y eval\u00faan diariamente datos como tiempos de entrega, informaci\u00f3n de estado, integridad de la transmisi\u00f3n de datos o comprobantes de entrega.<\/strong><\/h5>\n<p>(Weinheim) El premio fue otorgado a trans-o-flex durante la conferencia anual de EURODIS de este a\u00f1o, que tuvo lugar recientemente en \u00c1msterdam. \u00abAunque parezca que tenemos este premio suscrito, ganar no es en absoluto un automatismo\u00bb, dijo el CEO Wolfgang P. Albeck al recibir el premio. \u00abQuien ya es bueno, siempre tiene m\u00e1s dif\u00edcil mejorar. Y los otros socios de EURODIS est\u00e1n avanzando, por lo que la competencia en la cima se vuelve cada vez m\u00e1s re\u00f1ida. Por eso, nuestro equipo puede estar a\u00fan m\u00e1s orgulloso de haber recibido nuevamente este reconocimiento.\u00bb<\/p>\n<p>Para Jens Reibold, director general de EURODIS GmbH, que gestiona la red, el aumento extraordinariamente alto del volumen de env\u00edos de EURODIS es otra prueba de la calidad del servicio de transporte internacional. Reibold dijo en \u00c1msterdam: \u00abEl n\u00famero de env\u00edos en EURODIS ha aumentado en un 80 por ciento en el primer semestre de 2022 en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior. Sin una calidad excepcional, un crecimiento as\u00ed no ser\u00eda posible.\u00bb<\/p>\n<p>Foto: \u00a9 trans-o-flex <em>\/ <strong>Pie de foto:<\/strong> Jens Reibold, director general de EURODIS (a la derecha), felicita a Wolfgang P. Albeck, CEO de trans-o-flex.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por sexta vez consecutiva, el servicio expr\u00e9s trans-o-flex ha recibido en 2022 el premio anual a la mejor calidad operativa en la red EURODIS, que es<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-57344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>trans-o-flex gana el premio EURODIS a la mejor calidad - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"trans-o-flex gana el premio EURODIS a la mejor calidad - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Por sexta vez consecutiva, el servicio expr\u00e9s trans-o-flex ha recibido en 2022 el premio anual a la mejor calidad operativa en la red EURODIS, que es [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-19T17:10:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_20.07.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"872\" \/>\n\t<meta property=\"og:image:height\" content=\"539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"trans-o-flex gana el premio EURODIS a la mejor calidad\",\"datePublished\":\"2022-07-19T17:10:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_20.07.2022.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/\",\"name\":\"trans-o-flex gana el premio EURODIS a la mejor calidad - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_20.07.2022.jpg\",\"datePublished\":\"2022-07-19T17:10:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_20.07.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_20.07.2022.jpg\",\"width\":872,\"height\":539},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/07\\\/19\\\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"trans-o-flex gana el premio EURODIS a la mejor calidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"trans-o-flex gana el premio EURODIS a la mejor calidad - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/","og_locale":"es_ES","og_type":"article","og_title":"trans-o-flex gana el premio EURODIS a la mejor calidad - Loginfo24","og_description":"Por sexta vez consecutiva, el servicio expr\u00e9s trans-o-flex ha recibido en 2022 el premio anual a la mejor calidad operativa en la red EURODIS, que es [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-07-19T17:10:32+00:00","og_image":[{"width":872,"height":539,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_20.07.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/"},"author":{"name":"","@id":""},"headline":"trans-o-flex gana el premio EURODIS a la mejor calidad","datePublished":"2022-07-19T17:10:32+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_20.07.2022.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/","url":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/","name":"trans-o-flex gana el premio EURODIS a la mejor calidad - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_20.07.2022.jpg","datePublished":"2022-07-19T17:10:32+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_20.07.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_20.07.2022.jpg","width":872,"height":539},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/07\/19\/trans-o-flex-gana-el-premio-eurodis-a-la-mejor-calidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"trans-o-flex gana el premio EURODIS a la mejor calidad"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/57344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=57344"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/57344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/9865"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=57344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=57344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=57344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}