{"id":56890,"date":"2022-06-13T19:40:01","date_gmt":"2022-06-13T17:40:01","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/"},"modified":"2022-06-13T19:40:01","modified_gmt":"2022-06-13T17:40:01","slug":"swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/","title":{"rendered":"SWAN celebra un exitoso regreso a la feria en LogiMAT"},"content":{"rendered":"<h5><strong>La empresa SWAN GmbH hace un balance positivo tras tres intensos d\u00edas en la LogiMAT 2022. En el centro de la presentaci\u00f3n de SWAN en la feria estuvo el complemento SAP EWM propio \u00abSWAN 3D-Logistics Cockpit\u00bb. La soluci\u00f3n \u00abDigital-Twin\u00bb para SAP EWM permite una interacci\u00f3n intuitiva con los inventarios y los datos de movimiento en la log\u00edstica. Adem\u00e1s, los proyectos de migraci\u00f3n de SWAN SAP S\/4HANA con participaci\u00f3n de SAP EWM y los proyectos de SAP EWM con flujo de material automatizado tambi\u00e9n despertaron el inter\u00e9s de los visitantes.<\/strong><\/h5>\n<p>(Stuttgart) Despu\u00e9s de m\u00e1s de dos a\u00f1os de pausa obligada por la pandemia, el experto en log\u00edstica SWAN se alegra de haber tenido un LogiMAT exitoso. Desde el 31 de mayo hasta el 1 de junio, la feria especializada en intralog\u00edstica y gesti\u00f3n de procesos recibi\u00f3 a alrededor de 50,000 visitantes en sus pabellones. SWAN se muestra completamente satisfecha, tanto en t\u00e9rminos de la cantidad de visitantes como de los contactos individuales: adem\u00e1s de clientes existentes, SWAN tambi\u00e9n pudo dar la bienvenida a muchos nuevos interesados, planificadores log\u00edsticos y empresas asociadas de SAP en su stand. Hubo una gran demanda, especialmente en los campos de negocio de SAP TM y EWM. Aqu\u00ed, la empresa de proyectos para log\u00edstica SAP registr\u00f3 muchos nuevos contactos y consultas que prometen proyectos y colaboraciones emocionantes. Tambi\u00e9n despertaron un gran inter\u00e9s los proyectos de migraci\u00f3n de SAP S\/4HANA con participaci\u00f3n de SAP EWM de SWAN, as\u00ed como sus proyectos de SAP EWM con flujo de material automatizado.<\/p>\n<h5><strong>SWAN 3D-Logistics Cockpit<\/strong><\/h5>\n<p>El claro punto culminante de la presentaci\u00f3n de SWAN en la feria: su propio y continuamente desarrollado SWAN 3D-Logistics Cockpit. Este genera una representaci\u00f3n virtual en 3D del almac\u00e9n utilizando los datos disponibles de SAP EWM. Este \u00abDigital-Twin\u00bb ofrece una representaci\u00f3n realista de los inventarios y las estructuras de los almacenes en tiempo real. Esto facilita enormemente a los usuarios las tareas que deben realizar en el centro de control y minimiza los procesos de almacenamiento complejos y propensos a errores. El control se realiza de manera completamente intuitiva gracias a la interfaz 3D realista basada en SAPUI5. Los usuarios pueden crear tareas de almacenamiento f\u00e1cilmente mediante arrastrar y soltar. Las relaciones son f\u00e1ciles de reconocer gracias a la conexi\u00f3n de las estructuras de almacenamiento, estanter\u00edas y los datos actuales de inventario y ubicaci\u00f3n en un espacio representado en tres dimensiones. La captura de desviaciones de proceso se realiza as\u00ed muy r\u00e1pidamente. Diferentes soluciones de localizaci\u00f3n y ubicaci\u00f3n tambi\u00e9n se pueden integrar en la realidad virtual para el seguimiento de activos y recursos. El SWAN 3D-Logistics Cockpit se puede integrar como una aplicaci\u00f3n Fiori en cualquier sistema SAP EWM y se puede a\u00f1adir sin problemas a las instalaciones existentes.<\/p>\n<h5><strong>Log\u00edstica SAP para almacenes automatizados<\/strong><\/h5>\n<p>SWAN tambi\u00e9n ofrece un amplio portafolio de servicios de aplicaciones de log\u00edstica SAP para optimizar la digitalizaci\u00f3n y automatizaci\u00f3n de los procesos de almacenamiento. Especialmente gracias a la fusi\u00f3n con SSI Sch\u00e4fer, pero tambi\u00e9n con una amplia red de socios de otros proveedores de automatizaci\u00f3n de almacenes y rob\u00f3tica, SWAN puede ofrecer siempre la mejor opci\u00f3n entre diferentes posibilidades de soluci\u00f3n.<\/p>\n<p>En la LogiMAT 2022, destac\u00f3 especialmente la alta demanda de soluciones SAP integrativas como la planificaci\u00f3n de palets y el puesto de trabajo de preparaci\u00f3n de pedidos SWAN 3D para cajas, as\u00ed como el portafolio de soluciones SAPUI5 para diversos escenarios de puestos de trabajo.<\/p>\n<p>En general, tambi\u00e9n se observa una tendencia clara hacia nuevas instalaciones log\u00edsticas con automatizaci\u00f3n en Europa. Las dificultades con las cadenas de suministro globales, como se vio recientemente con el bloqueo del Canal de Panam\u00e1 o el confinamiento en Shangh\u00e1i, est\u00e1n impulsando este desarrollo.<\/p>\n<p>Tambi\u00e9n, en la interacci\u00f3n con las soluciones de seguimiento de activos de sus socios, SWAN crea un valor a\u00f1adido al conectar actividades log\u00edsticas manuales con instalaciones autom\u00e1ticas. Una posible soluci\u00f3n fue ilustrada y hecha tangible por SWAN en la LogiMAT, mediante la localizaci\u00f3n en vivo del personal de la feria en el stand.<\/p>\n<p>\u00abPara nosotros, no solo fue de gran importancia presentar nuestras soluciones SAP en la feria. Tambi\u00e9n fue especialmente agradable, despu\u00e9s de tanto tiempo, volver a cultivar contactos y sumergirse en conversaciones cara a cara\u00bb, resume Alexander Bernhard, director general de SWAN: \u00abAgradezco todos los inspiradores impulsos de la comunidad log\u00edstica, el intercambio abierto y el gran compromiso de nuestro equipo de feria en el lugar.\u00bb<\/p>\n<p>Foto: \u00a9 SWAN GmbH<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa SWAN GmbH hace un balance positivo tras tres intensos d\u00edas en la LogiMAT 2022. En el centro de la presentaci\u00f3n de SWAN en la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-56890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SWAN celebra un exitoso regreso a la feria en LogiMAT - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SWAN celebra un exitoso regreso a la feria en LogiMAT - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La empresa SWAN GmbH hace un balance positivo tras tres intensos d\u00edas en la LogiMAT 2022. En el centro de la presentaci\u00f3n de SWAN en la [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-13T17:40:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SWAN_14.06.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1002\" \/>\n\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SWAN celebra un exitoso regreso a la feria en LogiMAT\",\"datePublished\":\"2022-06-13T17:40:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SWAN_14.06.2022.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/\",\"name\":\"SWAN celebra un exitoso regreso a la feria en LogiMAT - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SWAN_14.06.2022.jpg\",\"datePublished\":\"2022-06-13T17:40:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SWAN_14.06.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/SWAN_14.06.2022.jpg\",\"width\":1002,\"height\":662},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/13\\\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SWAN celebra un exitoso regreso a la feria en LogiMAT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SWAN celebra un exitoso regreso a la feria en LogiMAT - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/","og_locale":"es_ES","og_type":"article","og_title":"SWAN celebra un exitoso regreso a la feria en LogiMAT - Loginfo24","og_description":"La empresa SWAN GmbH hace un balance positivo tras tres intensos d\u00edas en la LogiMAT 2022. En el centro de la presentaci\u00f3n de SWAN en la [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-13T17:40:01+00:00","og_image":[{"width":1002,"height":662,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SWAN_14.06.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/"},"author":{"name":"","@id":""},"headline":"SWAN celebra un exitoso regreso a la feria en LogiMAT","datePublished":"2022-06-13T17:40:01+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SWAN_14.06.2022.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/","url":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/","name":"SWAN celebra un exitoso regreso a la feria en LogiMAT - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SWAN_14.06.2022.jpg","datePublished":"2022-06-13T17:40:01+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SWAN_14.06.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/SWAN_14.06.2022.jpg","width":1002,"height":662},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/13\/swan-celebra-un-exitoso-regreso-a-la-feria-en-logimat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"SWAN celebra un exitoso regreso a la feria en LogiMAT"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=56890"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10063"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=56890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=56890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=56890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}