{"id":56854,"date":"2022-06-09T20:20:59","date_gmt":"2022-06-09T18:20:59","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/"},"modified":"2022-06-09T20:20:59","modified_gmt":"2022-06-09T18:20:59","slug":"dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/","title":{"rendered":"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE"},"content":{"rendered":"<h5><strong>El pleno del Parlamento Europeo vot\u00f3 ayer sobre una parte del paquete de protecci\u00f3n clim\u00e1tica \u00abFit for 55\u00bb. Al respecto, la directora del Foro Alem\u00e1n de Transporte (DVF), la Dra. Heike van Hoorn, dijo: \u00abLa industria del transporte quiere una protecci\u00f3n clim\u00e1tica ambiciosa. La necesaria transici\u00f3n de propulsi\u00f3n y combustible debe implementarse en un tiempo extremadamente corto. Lo que hemos visto hasta ahora del Parlamento Europeo y del Consejo no cumple con esta exigencia. Necesitamos m\u00e1s determinaci\u00f3n en las condiciones marco requeridas y una regulaci\u00f3n justa.\u00bb<\/strong><\/h5>\n<p>(Berl\u00edn) El informe principal sobre el desarrollo del sistema europeo de comercio de emisiones no obtuvo mayor\u00eda en el pleno del Parlamento. Por lo tanto, actualmente faltan las decisiones necesarias para incluir el transporte por carretera y el transporte mar\u00edtimo en el comercio de emisiones. Van Hoorn: \u00abLamentamos esto y pedimos al Parlamento que recupere las decisiones. Europa necesita una fijaci\u00f3n de precios del CO2 efectiva.\u00bb<\/p>\n<h5><strong>Industria de la aviaci\u00f3n<\/strong><\/h5>\n<p>Sin embargo, el Parlamento Europeo quiere poner fin a la libre asignaci\u00f3n de certificados en la aviaci\u00f3n ya en 2025, incluyendo vuelos de larga distancia desde aeropuertos de la UE y emisiones no relacionadas con el CO2 en el comercio de emisiones. \u00abAqu\u00ed el Parlamento considera demasiado poco el impacto econ\u00f3mico sobre un modo de transporte que compite a nivel mundial\u00bb, dice van Hoorn. \u00abA nadie le ayuda si debilitamos la innovadora industria de la aviaci\u00f3n europea.\u00bb<\/p>\n<h5><strong>Veh\u00edculos de pasajeros y veh\u00edculos comerciales ligeros<\/strong><\/h5>\n<p>La situaci\u00f3n sigue siendo muy desafiante en cuanto al cambio de propulsi\u00f3n en el transporte por carretera. En cuanto a los l\u00edmites de emisiones de CO2 para veh\u00edculos de pasajeros y veh\u00edculos comerciales ligeros, el Parlamento Europeo se ha pronunciado a favor de una completa neutralidad en emisiones para 2035. Para la medici\u00f3n, se basan en las emisiones del escape. Por lo tanto, faltan puntos de referencia para el uso de hidr\u00f3geno verde y combustibles sint\u00e9ticos basados en electricidad en la regulaci\u00f3n.<\/p>\n<h5><strong>Infraestructura<\/strong><\/h5>\n<p>Van Hoorn se refiri\u00f3 en este contexto al reglamento sobre la creaci\u00f3n de la infraestructura de suministro para combustibles alternativos AFIR: \u00abEl ritmo de construcci\u00f3n de la infraestructura actualmente no sigue el endurecimiento de los l\u00edmites de emisiones. Esto afecta especialmente a la red de carga para la movilidad el\u00e9ctrica, que se necesita en todas las ciudades y en toda Europa. Desafortunadamente, parece que los Estados miembros est\u00e1n diluyendo los objetivos de expansi\u00f3n en el borrador del reglamento. Necesitamos m\u00e1s ambici\u00f3n de la que contiene la propuesta de la Comisi\u00f3n, no menos.\u00bb<\/p>\n<p>El Parlamento Europeo a\u00fan no ha votado sobre el AFIR. En todas las leyes, el Consejo y el Parlamento deben alcanzar un acuerdo sustantivo para que las propuestas puedan ser aprobadas.<\/p>\n<p>El documento de posici\u00f3n del DVF sobre \u00abFit for 55\u00bb aborda m\u00e1s recomendaciones de acci\u00f3n, incluyendo los siguientes puntos:<\/p>\n<ul>\n<li>r\u00e1pido aumento de la producci\u00f3n de hidr\u00f3geno y e-fuels para aplicaciones en el sector del transporte, complementario a la movilidad el\u00e9ctrica de bater\u00eda<\/li>\n<li>cuotas para combustibles sostenibles y fiscalidad energ\u00e9tica en consonancia con los requisitos de la competencia internacional<\/li>\n<li>destinaci\u00f3n de fondos de la UE para la protecci\u00f3n clim\u00e1tica, por ejemplo, para el apoyo financiero de combustibles limpios, infraestructura e innovaciones tecnol\u00f3gicas<\/li>\n<li>expansi\u00f3n del transporte ferroviario, v\u00edas navegables, transporte p\u00fablico, tr\u00e1fico ciclista y peatonal, as\u00ed como nuevas formas de movilidad; expansi\u00f3n de interfaces entre los modos de transporte<\/li>\n<li>apoyo a la digitalizaci\u00f3n y automatizaci\u00f3n en el sector del transporte<\/li>\n<li>aceleraci\u00f3n de la planificaci\u00f3n y construcci\u00f3n para una infraestructura de transporte eficiente y sostenible, de la misma manera que para la infraestructura de energ\u00edas renovables<\/li>\n<\/ul>\n<p>Foto: \u00a9 DVF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pleno del Parlamento Europeo vot\u00f3 ayer sobre una parte del paquete de protecci\u00f3n clim\u00e1tica \u00abFit for 55\u00bb. Al respecto, la directora del Foro Alem\u00e1n de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-56854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El pleno del Parlamento Europeo vot\u00f3 ayer sobre una parte del paquete de protecci\u00f3n clim\u00e1tica \u00abFit for 55\u00bb. Al respecto, la directora del Foro Alem\u00e1n de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T18:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_10.06.2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE\",\"datePublished\":\"2022-06-09T18:20:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_10.06.2022.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/\",\"name\":\"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_10.06.2022.jpg\",\"datePublished\":\"2022-06-09T18:20:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_10.06.2022.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_10.06.2022.jpg\",\"width\":744,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/09\\\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/","og_locale":"es_ES","og_type":"article","og_title":"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE - Loginfo24","og_description":"El pleno del Parlamento Europeo vot\u00f3 ayer sobre una parte del paquete de protecci\u00f3n clim\u00e1tica \u00abFit for 55\u00bb. Al respecto, la directora del Foro Alem\u00e1n de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-09T18:20:59+00:00","og_image":[{"width":744,"height":489,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_10.06.2022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/"},"author":{"name":"","@id":""},"headline":"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE","datePublished":"2022-06-09T18:20:59+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_10.06.2022.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/","url":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/","name":"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_10.06.2022.jpg","datePublished":"2022-06-09T18:20:59+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_10.06.2022.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_10.06.2022.jpg","width":744,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/09\/dvf-el-sector-del-transporte-quiere-implementar-los-ambiciosos-objetivos-climaticos-de-la-ue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"DVF: El sector del transporte quiere implementar los ambiciosos objetivos clim\u00e1ticos de la UE"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=56854"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10078"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=56854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=56854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=56854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}