{"id":56765,"date":"2022-06-05T20:44:04","date_gmt":"2022-06-05T18:44:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/"},"modified":"2022-06-05T20:44:04","modified_gmt":"2022-06-05T18:44:04","slug":"logimat-2022-supera-claramente-las-expectativas","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/","title":{"rendered":"LogiMAT 2022 supera claramente las expectativas"},"content":{"rendered":"<h4><strong><span style=\"font-family: 'Cambria',serif\">Con una oferta integral de expositores y una alta afluencia de visitantes, la LogiMAT 2022 logra un exitoso reinicio en la era post-Corona. Los destacados cierres de negocios y acuerdos de cooperaci\u00f3n, as\u00ed como el intenso intercambio de informaci\u00f3n, subrayan la importancia de la principal feria internacional de soluciones de intralog\u00edstica y gesti\u00f3n de procesos como feria de trabajo y centro de comunicaci\u00f3n.<\/span><\/strong><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">(M\u00fanich\/Stuttgart) Con resultados estables en todas las cifras relevantes de la feria, la LogiMAT 2022 concluy\u00f3 esta tarde en Stuttgart. Con valores cercanos a los niveles previos a la Corona, la principal feria internacional de intralog\u00edstica pudo conectar sin problemas con los \u00e9xitos de los eventos anteriores. \u00abUn exitoso reinicio despu\u00e9s de casi 40 meses de pausa forzada por la pandemia\u00bb, comenta el director de la feria, Michael Ruchty, de EUROEXPO Messe- und Kongress-GmbH, M\u00fanich. \u00abAjustado por las restricciones relacionadas con la pandemia, se puede calificar este resultado en todas las categor\u00edas como una continuaci\u00f3n de la historia de \u00e9xito de LogiMAT.\u00bb<\/span><\/p>\n<p>Bajo el lema \u00abInteligente - Sostenible - Seguro\u00bb, este a\u00f1o 1.571 expositores registrados de 39 pa\u00edses, incluidos alrededor de 393 nuevos expositores y 74 proveedores destacados de ultramar, presentaron en los tres d\u00edas de la feria sus soluciones, sistemas y dispositivos actuales para una automatizaci\u00f3n confiable y transformaci\u00f3n digital. Con numerosos estrenos de productos y novedades mundiales, tambi\u00e9n establecieron importantes impulsos para procesos de intralog\u00edstica eficientes y sostenibles. Con una superficie de exposici\u00f3n de m\u00e1s de 125,000 metros cuadrados en los diez pabellones, el recinto ferial de Stuttgart tambi\u00e9n estuvo completamente reservado este a\u00f1o.<\/p>\n<h4><b><span style=\"font-family: 'Cambria',serif\">50,000 visitantes profesionales acudieron a los pabellones<\/span><\/b><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">Despu\u00e9s de dos a\u00f1os y medio de pausa forzada por la pandemia, 50,000 visitantes profesionales aprovecharon la oportunidad de informarse en el lugar sobre las \u00faltimas tecnolog\u00edas y su integraci\u00f3n en sistemas inteligentes y sostenibles, y compararlas directamente entre s\u00ed. En los momentos \u00e1lgidos, el segundo d\u00eda de la feria, 3,000 visitantes profesionales pasaron por los torniquetes en la entrada a los pabellones de la feria en solo diez minutos.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">M\u00e1s de una cuarta parte de los visitantes pertenec\u00eda al personal de grandes empresas con entre 1,000 y 9,999 empleados. Desglosados por sectores, el 58.8 por ciento de los visitantes profesionales pertenece al sector industrial, el 12.4 por ciento est\u00e1 en el comercio mayorista y otro 4.3 por ciento en el comercio minorista. El 6.9 por ciento trabaja en el sector de la log\u00edstica. La mayor\u00eda del p\u00fablico profesional (52.8%) son responsables de compras en sus empresas. Para ellos, la LogiMAT se considera la plataforma de informaci\u00f3n principal sobre las ofertas de soluciones actuales para una intralog\u00edstica eficiente. Del total de visitantes profesionales, el 55.1 por ciento vino para informarse sobre novedades y tendencias, el 27.7 por ciento quer\u00eda establecer nuevas conexiones comerciales. El inter\u00e9s se centr\u00f3 especialmente en las novedades en las \u00e1reas de tecnolog\u00eda de transporte y almacenamiento (55.8%), veh\u00edculos de transporte (38.3%) y, con un 18.3 por ciento, veh\u00edculos de transporte aut\u00f3nomos (FTF) o robots m\u00f3viles aut\u00f3nomos (AMR) - se permitieron m\u00faltiples menciones.<\/span><\/p>\n<h4><span style=\"font-family: 'Cambria',serif\">\u00a0<\/span><b><span style=\"font-family: 'Cambria',serif\">Numerosos contratos firmados<\/span><\/b><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">El 36.5 por ciento del p\u00fablico profesional tambi\u00e9n lleg\u00f3 a Stuttgart con proyectos de inversi\u00f3n concretos. Numerosos acuerdos de ventas, cierres de negocios e iniciativas de cooperaci\u00f3n firmados en la LogiMAT subrayan el car\u00e1cter de la LogiMAT como bolsa de informaci\u00f3n, plataforma de presentaci\u00f3n y comunicaci\u00f3n, as\u00ed como feria de trabajo para cierres de negocios concretos. El 5.2 por ciento de los visitantes profesionales otorgaron un contrato en la feria, el 31.7 por ciento planea otorgar contratos inmediatamente despu\u00e9s de la feria. La respuesta de los expositores fue igualmente positiva, quienes destacaron el alto nivel de conocimiento y la calidad de los contactos.<\/span><\/p>\n<p>Para llegar a la LogiMAT, el 38.5 por ciento de los visitantes recorrieron m\u00e1s de 300 kil\u00f3metros. Se ha mantenido estable el alto inter\u00e9s de visitantes y expositores internacionales. Seg\u00fan las cifras del instituto de investigaci\u00f3n de mercado independiente Wissler &amp; Partner, uno de cada cinco visitantes de la feria lleg\u00f3 del extranjero a Stuttgart. El p\u00fablico profesional internacional proven\u00eda en un 73.8 por ciento de pa\u00edses de la UE, en un 7.9 por ciento de pa\u00edses no pertenecientes a la UE y en un 8.3 por ciento de ultramar, Asia y Am\u00e9rica.<\/p>\n<h4><b><span style=\"font-family: 'Cambria',serif\">LogiMAT.digital contin\u00faa<\/span><\/b><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">\u00abEstamos muy satisfechos con las cifras y el desarrollo de la LogiMAT 2022\u00bb, resume el director de la feria, Michael Ruchty. \u00abLa continuaci\u00f3n de la LogiMAT 2022 se llevar\u00e1 a cabo en Internet en la plataforma LogiMAT.digital. All\u00ed se transmitir\u00e1n en las pr\u00f3ximas semanas las 14 series de conferencias informativas del programa de alta calidad que tuvieron lugar durante los tres d\u00edas en la LogiMAT-Arena.\u00bb<\/span><\/p>\n<p><strong><span style=\"font-family: 'Cambria',serif;font-weight: normal\">La pr\u00f3xima LogiMAT en Stuttgart se llevar\u00e1 a cabo del 25 al 27 de abril de 2023.<\/span><\/strong><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Foto: \u00a9 LogiMAT<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una oferta integral de expositores y una alta afluencia de visitantes, la LogiMAT 2022 logra un exitoso reinicio en la era post-Corona. Los destacados cierres<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1560,1561],"tags":[],"class_list":["post-56765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LogiMAT 2022 supera claramente las expectativas - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LogiMAT 2022 supera claramente las expectativas - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Con una oferta integral de expositores y una alta afluencia de visitantes, la LogiMAT 2022 logra un exitoso reinicio en la era post-Corona. Los destacados cierres [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-05T18:44:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogiMAT_5.6.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1306\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LogiMAT 2022 supera claramente las expectativas\",\"datePublished\":\"2022-06-05T18:44:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogiMAT_5.6.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/\",\"name\":\"LogiMAT 2022 supera claramente las expectativas - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogiMAT_5.6.22.jpg\",\"datePublished\":\"2022-06-05T18:44:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogiMAT_5.6.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/LogiMAT_5.6.22.jpg\",\"width\":1306,\"height\":945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/06\\\/05\\\/logimat-2022-supera-claramente-las-expectativas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LogiMAT 2022 supera claramente las expectativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LogiMAT 2022 supera claramente las expectativas - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/","og_locale":"es_ES","og_type":"article","og_title":"LogiMAT 2022 supera claramente las expectativas - Loginfo24","og_description":"Con una oferta integral de expositores y una alta afluencia de visitantes, la LogiMAT 2022 logra un exitoso reinicio en la era post-Corona. Los destacados cierres [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-05T18:44:04+00:00","og_image":[{"width":1306,"height":945,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogiMAT_5.6.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/"},"author":{"name":"","@id":""},"headline":"LogiMAT 2022 supera claramente las expectativas","datePublished":"2022-06-05T18:44:04+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogiMAT_5.6.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/","url":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/","name":"LogiMAT 2022 supera claramente las expectativas - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogiMAT_5.6.22.jpg","datePublished":"2022-06-05T18:44:04+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogiMAT_5.6.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/LogiMAT_5.6.22.jpg","width":1306,"height":945},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/06\/05\/logimat-2022-supera-claramente-las-expectativas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"LogiMAT 2022 supera claramente las expectativas"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=56765"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10111"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=56765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=56765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=56765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}