{"id":56568,"date":"2022-05-24T18:50:26","date_gmt":"2022-05-24T16:50:26","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/"},"modified":"2022-05-24T18:50:26","modified_gmt":"2022-05-24T16:50:26","slug":"anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/","title":{"rendered":"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo"},"content":{"rendered":"<h5><strong>MAN Truck &amp; Bus, Deutsche Bahn, Hochschule Fresenius y G\u00f6tting KG hacen un balance positivo a mitad de camino en el proyecto de automatizaci\u00f3n conjunto ANITA (Innovaci\u00f3n Aut\u00f3noma en el Proceso de Terminal). Con el primer viaje p\u00fablico del sistema de conducci\u00f3n aut\u00f3noma de camiones en la pista de pruebas de MAN en M\u00fanich, los socios presentaron lo logrado hasta ahora y anunciaron como siguiente paso intensos viajes de pr\u00e1ctica y desarrollo en el dep\u00f3sito de contenedores de DB Intermodal Services y el terminal DUSS (Deutsche Umschlaggesellschaft Schiene-Stra\u00dfe mbH) en Ulm Dornstadt.<\/strong><\/h5>\n<p>(M\u00fanich) El objetivo de ANITA es estabilizar los procesos de manejo de contenedores de la carretera al ferrocarril con camiones aut\u00f3nomos, haci\u00e9ndolos m\u00e1s eficientes, predecibles y al mismo tiempo m\u00e1s flexibles. De este modo, en el futuro se podr\u00e1n transportar m\u00e1s mercanc\u00edas en el transporte combinado respetuoso con el medio ambiente. Para ello, MAN afinar\u00e1 en los pr\u00f3ximos meses los sentidos electr\u00f3nicos del cami\u00f3n aut\u00f3nomo en un entorno de uso real, para que pueda percibir, reaccionar y planificar como un verdadero conductor.<\/p>\n<p>\u00abLa tecnolog\u00eda de automatizaci\u00f3n b\u00e1sica para ANITA est\u00e1 lista. Ahora vamos a entrar en un ajuste directo con la pr\u00e1ctica para seguir desarrollando el sistema con miras a la seguridad de uso y el valor a\u00f1adido para el futuro usuario\u00bb, dice el Dr. Frederik Zohm, miembro del consejo de investigaci\u00f3n y desarrollo de MAN Truck &amp; Bus, durante el viaje inaugural. \u00abEste enfoque lo seguimos de manera consistente para poder ofrecer camiones aut\u00f3nomos en el tr\u00e1fico de terminales a finales de esta d\u00e9cada como tecnolog\u00eda en serie. Socios comprometidos como Deutsche Bahn, G\u00f6tting KG y Hochschule Fresenius son esenciales en este proceso.\u00bb<\/p>\n<h5><strong>Nuevas tecnolog\u00edas para el futuro<\/strong><\/h5>\n<p>Los socios est\u00e1n planeando un a\u00f1o completo para las pruebas de conducci\u00f3n, con el fin de confrontar el prototipo aut\u00f3nomo lo m\u00e1s posible con la realidad a lo largo del desarrollo y optimizaci\u00f3n gradual. Siempre habr\u00e1 un conductor de seguridad a bordo que intervendr\u00e1 si es necesario. Las intensas pruebas no solo benefician el desarrollo del cami\u00f3n aut\u00f3nomo, sino tambi\u00e9n la preparaci\u00f3n de los terminales para la integraci\u00f3n de la nueva tecnolog\u00eda: \u00abCombinando ferrocarril y carretera, esta es la soluci\u00f3n ecol\u00f3gica para la log\u00edstica del futuro. Estamos trabajando juntos para que estos transportes intermodales crezcan. La digitalizaci\u00f3n y la automatizaci\u00f3n nos ayudan a simplificar y acelerar las interfaces con el tren de carga y los procesos en los terminales\u00bb, dice la Dra. Sigrid Nikutta, miembro del consejo de transporte de mercanc\u00edas de Deutsche Bahn AG y presidenta de DB Cargo AG.<\/p>\n<p>Para que el cami\u00f3n aut\u00f3nomo pueda cumplir su tarea de transporte en el manejo de contenedores, debe poder comunicarse con la infraestructura del dep\u00f3sito de DBIS y el terminal DUSS. Para ello, los cient\u00edficos de Hochschule Fresenius analizaron en la primera fase del proyecto los procesos, flujos y comportamientos existentes de personas y m\u00e1quinas en el lugar y los trasladaron a un marco regulador digital. La Contract Specification Language (CSL) de Deon Digital sirve como lenguaje com\u00fan para la comunicaci\u00f3n clara y completa de todos los sistemas involucrados. As\u00ed se cre\u00f3 una planificaci\u00f3n de misiones completa que conecta tanto el veh\u00edculo como los sistemas inform\u00e1ticos del dep\u00f3sito de DBIS y el terminal DUSS.<\/p>\n<p>\u00abNos alegra ver c\u00f3mo nuestro trabajo previo puede ser utilizado con \u00e9xito en la interacci\u00f3n con el cami\u00f3n en el transcurso del proyecto ANITA\u00bb, enfatiza el Prof. Dr. Christian T. Haas de Hochschule Fresenius. La planificaci\u00f3n de misiones de los cient\u00edficos transmitir\u00e1 al cami\u00f3n automatizado en los pr\u00f3ximos viajes pr\u00e1cticos sus tareas y lo acompa\u00f1ar\u00e1 a trav\u00e9s del proceso de manejo de contenedores.<\/p>\n<p>\u00abEn las pruebas pr\u00e1cticas en el terminal, aprenderemos algo nuevo cada d\u00eda\u00bb, dice la l\u00edder del proyecto de MAN, Amelie Jacquemart-Purson. \u00abRequiere una gran destreza de ingenier\u00eda: combinar, interpretar y aplicar correctamente los datos de la c\u00e1mara, Lidar y radar\u00bb.<\/p>\n<h5><strong>Desarrollo de software con IA<\/strong><\/h5>\n<p>Esto significa concretamente mucho desarrollo de software: durante las pruebas de conducci\u00f3n, MAN analizar\u00e1 el comportamiento del veh\u00edculo. Estos conocimientos se implementar\u00e1n gradualmente a trav\u00e9s de actualizaciones de software. Todas las decisiones que un conductor toma hoy en funci\u00f3n de sus impresiones sensoriales tambi\u00e9n deben ser cubiertas por el sistema aut\u00f3nomo; se trata de nada menos que reemplazar las percepciones y acciones humanas.<\/p>\n<p>El proyecto \u00abInnovaci\u00f3n Aut\u00f3noma en el Proceso de Terminal\u00bb (ANITA) comenz\u00f3 el 1 de julio de 2020 con el objetivo de automatizar la transferencia entre los modos de transporte y, por lo tanto, hacerla m\u00e1s flexible y eficiente. Se financia con fondos de 5,5 millones de euros del programa \u00abNuevas tecnolog\u00edas de veh\u00edculos y sistemas\u00bb del Ministerio Federal de Econom\u00eda y Protecci\u00f3n del Clima. La duraci\u00f3n es de 39 meses. M\u00e1s sobre el proyecto ANITA: <a href=\"https:\/\/www.anita.digital\/de\/\">https:\/\/www.anita.digital\/de\/<\/a><\/p>\n<p>Foto: \u00a9 MAN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MAN Truck &amp; Bus, Deutsche Bahn, Hochschule Fresenius y G\u00f6tting KG hacen un balance positivo a mitad de camino en el proyecto de automatizaci\u00f3n conjunto ANITA<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-56568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"MAN Truck &amp; Bus, Deutsche Bahn, Hochschule Fresenius y G\u00f6tting KG hacen un balance positivo a mitad de camino en el proyecto de automatizaci\u00f3n conjunto ANITA [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-24T16:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/MAN_25.05.2022-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo\",\"datePublished\":\"2022-05-24T16:50:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/\"},\"wordCount\":893,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/MAN_25.05.2022-scaled-1.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/\",\"name\":\"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/MAN_25.05.2022-scaled-1.jpg\",\"datePublished\":\"2022-05-24T16:50:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/MAN_25.05.2022-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/MAN_25.05.2022-scaled-1.jpg\",\"width\":2560,\"height\":1638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/24\\\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/","og_locale":"es_ES","og_type":"article","og_title":"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo - Loginfo24","og_description":"MAN Truck &amp; Bus, Deutsche Bahn, Hochschule Fresenius y G\u00f6tting KG hacen un balance positivo a mitad de camino en el proyecto de automatizaci\u00f3n conjunto ANITA [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-24T16:50:26+00:00","og_image":[{"width":2560,"height":1638,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/MAN_25.05.2022-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/"},"author":{"name":"","@id":""},"headline":"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo","datePublished":"2022-05-24T16:50:26+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/"},"wordCount":893,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/MAN_25.05.2022-scaled-1.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/","url":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/","name":"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/MAN_25.05.2022-scaled-1.jpg","datePublished":"2022-05-24T16:50:26+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/MAN_25.05.2022-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/MAN_25.05.2022-scaled-1.jpg","width":2560,"height":1638},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/24\/anita-cuando-el-camion-encuentra-su-camino-en-la-terminal-por-si-mismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"ANITA: Cuando el cami\u00f3n encuentra su camino en la terminal por s\u00ed mismo"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=56568"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10182"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=56568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=56568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=56568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}