{"id":56317,"date":"2022-05-12T13:45:41","date_gmt":"2022-05-12T11:45:41","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/"},"modified":"2022-05-12T13:45:41","modified_gmt":"2022-05-12T11:45:41","slug":"el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/","title":{"rendered":"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW)"},"content":{"rendered":"<h5><strong>Como un lugar para nuevos conceptos y como organizaci\u00f3n paraguas para startups, Cargo Digital World (CDW) de Paderborn desarrolla junto con empresas establecidas modelos de negocio digitales para la log\u00edstica del ma\u00f1ana. La fuerza impulsora es, por un lado, la creaci\u00f3n de m\u00e1s eficiencia y transparencia en los procesos log\u00edsticos. Por otro lado, los fundadores quieren explorar c\u00f3mo los usuarios de la log\u00edstica podr\u00edan ser mejor atendidos con soluciones innovadoras y fuera de lo com\u00fan.<\/strong><\/h5>\n<p>(Pressebox; Paderborn) Bajo el paraguas de la CDW, las startups Cargoboard, CargoCast, Cargonative y warespace est\u00e1n reestructurando \u00e1reas relevantes de la industria log\u00edstica. Sus servicios incluyen reservas en l\u00ednea para transportes de palets, almacenamiento de mercanc\u00edas inteligente y transfronterizo, optimizaci\u00f3n de rutas que ahorran CO<sub>2<\/sub> y modelos de IA para una planificaci\u00f3n y control de producci\u00f3n eficientes. Se espera que sigan m\u00e1s fundaciones. Gracias a la CDW, las startups reciben apoyo durante el proceso de crecimiento, se crean sinergias y se establecen redes. La empresa fue fundada en 2021 por la mayor cooperaci\u00f3n de carga fraccionada de Alemania, CargoLine, y se apoya en una amplia red de proveedores de log\u00edstica establecidos, como Hartmann International de Paderborn, para implementar modelos de negocio innovadores.<\/p>\n<p>\u00abNuestra ambici\u00f3n es construir modelos de negocio 100 % digitales\u00bb, dice el miembro de la junta de CDW, Dr. Tim Br\u00fchn, durante la visita de la empresa del alcalde de Paderborn, Michael Dreier. Junto con el promotor econ\u00f3mico Frank Wolters, Dreier visit\u00f3 la empresa, que se encuentra en el Parque Tecnol\u00f3gico 22 desde el cambio de a\u00f1o 2021\/2022, para hablar sobre las condiciones marco para startups y la infraestructura de transporte y digital en el lugar. Tambi\u00e9n estuvieron presentes Andreas Hartmann, del consejo de supervisi\u00f3n de CDW y Hartmann International, as\u00ed como los fundadores Richard Kleeschulte de Cargoboard y Simon Leontaris de CargoCast.<\/p>\n<h5><strong>Ejemplo destacado para el lugar de fundaci\u00f3n<\/strong><\/h5>\n<p>\u00abCargo Digital World es un ejemplo destacado para el lugar de fundaci\u00f3n Paderborn\u00bb, observ\u00f3 el alcalde Michael Dreier. Como municipio l\u00edder y regi\u00f3n modelo digital, el lugar est\u00e1 en el camino correcto para posicionarse de manera sostenible y orientada al futuro. Esfuerzos como los de Cargo Digital World son factores positivos que influyen en el buen desarrollo.<\/p>\n<p>La CDW tambi\u00e9n se siente a gusto en el lugar: \u00abPara nosotros, la cercan\u00eda al Centro de Startups de la Universidad de Paderborn y garage33 son factores importantes de ubicaci\u00f3n\u00bb, dice Tim Br\u00fchn. La visita del alcalde Michael Dreier y el promotor econ\u00f3mico Frank Wolters mostr\u00f3 cu\u00e1nto apoya la ciudad de Paderborn a las empresas ambiciosas \u00abcon un claro rumbo y voluntad pol\u00edtica\u00bb. Adem\u00e1s, Tim Br\u00fchn pudo abordar el tema de la promoci\u00f3n de la formaci\u00f3n. Especialmente la formaci\u00f3n en las \u00e1reas STEM es muy importante para la futura capacidad de innovaci\u00f3n de la CDW.<\/p>\n<h5><strong>Fortalecimiento duradero del lugar econ\u00f3mico<\/strong><\/h5>\n<p>El promotor econ\u00f3mico Frank Wolters: \u00abDebido a la importancia para el fortalecimiento duradero del lugar econ\u00f3mico Paderborn, estamos equipados con un claro mandato pol\u00edtico para avanzar en este tema en red con otros socios\u00bb. Actualmente se est\u00e1 preparando una conferencia especializada sobre el tema \u00abformaci\u00f3n dual como motor de la seguridad de personal cualificado\u00bb. Esta se llevar\u00e1 a cabo en la segunda mitad del a\u00f1o, informa Wolters.<\/p>\n<p>Foto: \u00a9 Tobias Vorwerk (WFG) \/ <strong><em>Pie de foto:<\/em><\/strong><em> (de izq. a der.) Simon Leontaris (Co-Fundador de CargoCast), Richard Kleeschulte (Co-Fundador y CMO de Cargoboard), Frank Wolters (Gerente de Promoci\u00f3n Econ\u00f3mica de Paderborn), Andreas Hartmann (Consejo de Supervisi\u00f3n de CDW, Socio Gerente de Hartmann International), el alcalde Michael Dreier y Dr. Tim Br\u00fchn (Miembro de la Junta de Cargo Digital World)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como un lugar para nuevos conceptos y como organizaci\u00f3n paraguas para startups, Cargo Digital World (CDW) de Paderborn desarrolla junto con empresas establecidas modelos de negocio<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-56317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW) - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW) - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Como un lugar para nuevos conceptos y como organizaci\u00f3n paraguas para startups, Cargo Digital World (CDW) de Paderborn desarrolla junto con empresas establecidas modelos de negocio [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T11:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CDW_Paderborn_12.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1489\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW)\",\"datePublished\":\"2022-05-12T11:45:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/\"},\"wordCount\":649,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CDW_Paderborn_12.5.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/\",\"name\":\"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW) - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CDW_Paderborn_12.5.22.jpg\",\"datePublished\":\"2022-05-12T11:45:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CDW_Paderborn_12.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/CDW_Paderborn_12.5.22.jpg\",\"width\":1489,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/12\\\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW) - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/","og_locale":"es_ES","og_type":"article","og_title":"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW) - Loginfo24","og_description":"Como un lugar para nuevos conceptos y como organizaci\u00f3n paraguas para startups, Cargo Digital World (CDW) de Paderborn desarrolla junto con empresas establecidas modelos de negocio [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-12T11:45:41+00:00","og_image":[{"width":1489,"height":816,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CDW_Paderborn_12.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/"},"author":{"name":"","@id":""},"headline":"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW)","datePublished":"2022-05-12T11:45:41+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/"},"wordCount":649,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CDW_Paderborn_12.5.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/","url":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/","name":"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW) - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CDW_Paderborn_12.5.22.jpg","datePublished":"2022-05-12T11:45:41+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CDW_Paderborn_12.5.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/CDW_Paderborn_12.5.22.jpg","width":1489,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/12\/el-alcalde-de-paderborn-dreier-visita-cargo-digital-world-cdw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"El alcalde de Paderborn, Dreier, visita Cargo Digital World (CDW)"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=56317"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10277"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=56317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=56317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=56317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}