{"id":56278,"date":"2022-05-11T18:02:29","date_gmt":"2022-05-11T16:02:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/"},"modified":"2022-05-11T18:02:29","modified_gmt":"2022-05-11T16:02:29","slug":"id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/","title":{"rendered":"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial"},"content":{"rendered":"<h5><strong>El proveedor de servicios contractuales ID Logistics Alemania ocupa m\u00e1s puestos de liderazgo en su sede en Alemania. Tras el nombramiento de Robin Otto como CEO de ID Logistics Alemania, el proveedor de servicios contractuales ampl\u00eda su equipo directivo con Detlef Kurzbuch como Director Comercial desde el 1 de abril de 2022. Reporta a Robin Otto, quien ocup\u00f3 este cargo junto con otras responsabilidades hasta su nombramiento como CEO.<\/strong><\/h5>\n<p>(Griesbach) Detlef Kurzbuch es miembro de la Junta Directiva y es responsable del desarrollo comercial de ID Logistics Alemania. Su \u00e1rea de responsabilidad incluye el equipo bien capacitado de Investigaci\u00f3n y Desarrollo, que es el coraz\u00f3n de soluciones log\u00edsticas bien planificadas y ejecutadas, as\u00ed como Ventas y Desarrollo de Nuevos Negocios, Bienes Ra\u00edces y Procesos de Innovaci\u00f3n.<\/p>\n<p>\u00abTambi\u00e9n en Alemania, nuestra estrategia de crecimiento est\u00e1 claramente orientada a largo plazo. Tanto las soluciones Greenfield significativas, como nuestras ubicaciones inauguradas en 2021 en Kaiserslautern y Kleinostheim, como nuestras capacidades en el \u00e1rea de transiciones operativas, como la adquisici\u00f3n de A.T.U Logistics el a\u00f1o pasado en Werl, siguen siendo el foco. Adem\u00e1s, hay proyectos desafiantes con un alto grado de innovaci\u00f3n, as\u00ed como una expansi\u00f3n de la oferta de servicios para nuestros clientes existentes y nuevos\u00bb, comenta Robin Otto, CEO de ID Logistics Alemania. \u00abDetlef Kurzbuch conoce el negocio de la log\u00edstica contractual desde sus cimientos y tiene un profundo conocimiento del mercado en relaci\u00f3n con clientes, industrias, participantes del mercado, as\u00ed como requisitos y soluciones log\u00edsticas. Con su buen sentido para los mercados y las oportunidades comerciales, estamos muy contentos de haberlo incorporado para las tareas que tenemos por delante.\u00bb<\/p>\n<h5><strong>Socio s\u00f3lido y financieramente fuerte<\/strong><\/h5>\n<p>\u00abLas empresas enfrentan grandes desaf\u00edos en todo el mundo debido a la multitud de cambios, ya sea por la pandemia, la geopol\u00edtica o la disrupci\u00f3n. Para sus procesos y redes log\u00edsticas que cambian de manera altamente din\u00e1mica, necesitan un socio s\u00f3lido, financieramente fuerte y orientado al cliente con gran experiencia pr\u00e1ctica\u00bb, contin\u00faa Robin Otto. \u00abCon su valiosa experiencia en numerosas funciones de gesti\u00f3n estrat\u00e9gica y operativa, especialmente tambi\u00e9n con su experiencia en el \u00e1rea de transiciones operativas seg\u00fan 613a hasta proyectos de M&amp;A, Detlef Kurzbuch aporta las condiciones ideales para este puesto relevante.\u00bb<\/p>\n<h5><strong>Jerarqu\u00edas planas y caminos de decisi\u00f3n cortos<\/strong><\/h5>\n<p>\u00abID Logistics es una empresa orientada a la innovaci\u00f3n y la tecnolog\u00eda, con un fuerte crecimiento y un gran enfoque en el cliente y los negocios en industrias y productos orientados al futuro. Lo que aprecio de la empresa son las jerarqu\u00edas planas y los caminos de decisi\u00f3n cortos. El excelente esp\u00edritu de equipo es una buena elecci\u00f3n para talentos, equipos y l\u00edderes por igual. Estoy muy emocionado de continuar escribiendo la positiva estrategia de crecimiento de la empresa\u00bb, dice Detlef Kurzbuch<strong>.<\/strong><\/p>\n<p>En su nueva posici\u00f3n, Detlef Kurzbuch aporta 20 a\u00f1os de experiencia en puestos de liderazgo a largo plazo en la log\u00edstica contractual en entornos nacionales e internacionales. Sus estaciones incluyen varios puestos de direcci\u00f3n y la direcci\u00f3n del desarrollo comercial en DB Schenker, as\u00ed como funciones de liderazgo en Rhenus AG, entre otros, como miembro de la Junta Ejecutiva de Log\u00edstica Contractual.<\/p>\n<h5><strong>El \u00e1rea de RRHH se fortalecer\u00e1<\/strong><\/h5>\n<p>Para un mayor apoyo, ID Logistics Alemania ampliar\u00e1 significativamente el \u00e1rea de RRHH como parte de su estrategia empresarial a largo plazo. Adem\u00e1s de la planificaci\u00f3n de personal y un equipo de reclutadores internos, el futuro se centrar\u00e1 en la expansi\u00f3n del equipo de RRHH para proyectos de adquisici\u00f3n de empresas, el desarrollo de empleados y la digitalizaci\u00f3n de los procesos de RRHH. El objetivo es apoyar de manera coherente el crecimiento y la rentabilidad de ID Logistics en Alemania con la innovaci\u00f3n a trav\u00e9s de RRHH 2.0. Para la exigente direcci\u00f3n de esta \u00e1rea de RRHH, ID Logistics pudo incorporar a un muy experimentado gerente de RRHH a partir del 1 de julio de 2022. La persona ser\u00e1 anunciada por separado.<\/p>\n<p>Foto: \u00a9 ID Logistics<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proveedor de servicios contractuales ID Logistics Alemania ocupa m\u00e1s puestos de liderazgo en su sede en Alemania. Tras el nombramiento de Robin Otto como CEO<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-56278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ID Logistics Alemania con Detlef Kurzbuch como Director Comercial - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El proveedor de servicios contractuales ID Logistics Alemania ocupa m\u00e1s puestos de liderazgo en su sede en Alemania. Tras el nombramiento de Robin Otto como CEO [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T16:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ID_Logistics_11.5.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1226\" \/>\n\t<meta property=\"og:image:height\" content=\"985\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial\",\"datePublished\":\"2022-05-11T16:02:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/\"},\"wordCount\":706,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ID_Logistics_11.5.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/\",\"name\":\"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ID_Logistics_11.5.22.jpg\",\"datePublished\":\"2022-05-11T16:02:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ID_Logistics_11.5.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ID_Logistics_11.5.22.jpg\",\"width\":1226,\"height\":985},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/05\\\/11\\\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/","og_locale":"es_ES","og_type":"article","og_title":"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial - Loginfo24","og_description":"El proveedor de servicios contractuales ID Logistics Alemania ocupa m\u00e1s puestos de liderazgo en su sede en Alemania. Tras el nombramiento de Robin Otto como CEO [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-05-11T16:02:29+00:00","og_image":[{"width":1226,"height":985,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ID_Logistics_11.5.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/"},"author":{"name":"","@id":""},"headline":"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial","datePublished":"2022-05-11T16:02:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/"},"wordCount":706,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ID_Logistics_11.5.22.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/","url":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/","name":"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ID_Logistics_11.5.22.jpg","datePublished":"2022-05-11T16:02:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ID_Logistics_11.5.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ID_Logistics_11.5.22.jpg","width":1226,"height":985},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/05\/11\/id-logistics-alemania-con-detlef-kurzbuch-como-director-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"ID Logistics Alemania con Detlef Kurzbuch como Director Comercial"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=56278"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/56278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10299"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=56278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=56278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=56278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}