{"id":55659,"date":"2022-04-07T12:36:30","date_gmt":"2022-04-07T10:36:30","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/"},"modified":"2022-04-07T12:36:30","modified_gmt":"2022-04-07T10:36:30","slug":"congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/","title":{"rendered":"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn"},"content":{"rendered":"<h5><strong>En oto\u00f1o de 2021, el Congreso Futuro Veh\u00edculos Comerciales de DEKRA tuvo que ser cancelado debido a la pandemia. Ahora se planea una nueva edici\u00f3n para el 2 y 3 de junio de 2022. Desde 2015, el evento se ha establecido como la plataforma central para el intercambio dentro de la industria del transporte y la log\u00edstica. Se prev\u00e9 que sea un evento presencial en Berl\u00edn.<\/strong><\/h5>\n<p>(Stuttgart\/Berl\u00edn) El Congreso Futuro Veh\u00edculos Comerciales de DEKRA re\u00fane a expertos de alto nivel de la industria automotriz y de proveedores, la pol\u00edtica y la ciencia. El programa se centra en el tema \u00abTransporte a prueba de futuro\u00bb y se divide en tres hilos tem\u00e1ticos que se desarrollan en parte de manera paralela: Tecnolog\u00eda de veh\u00edculos comerciales, Digitalizaci\u00f3n y \u00daltima milla.<\/p>\n<p>En total, los organizadores esperan m\u00e1s de 350 expertos, cient\u00edficos y altos directivos de empresas reconocidas en la industria de veh\u00edculos comerciales, incluidos muchos de empresas de orientaci\u00f3n internacional como Chereau SAS, Continental, Dachser, DAF, Daimler Truck, Fleetboard Logistics, Goodyear Dunlop Tires, IKEA, Knorr-Bremse, K\u00f6gel, Krone, MAN, Quantron, Rhenus, Scania, Schmitz Cargobull, Shell y ZF Friedrichshafen.<\/p>\n<h5><strong>Conferencias de pol\u00edtica y asociaciones<\/strong><\/h5>\n<p>Adem\u00e1s, tambi\u00e9n participar\u00e1n ponentes y panelistas de la pol\u00edtica, asociaciones y organizaciones europeas. Hasta ahora, han confirmado su asistencia, entre otros, Oliver Luksic (Secretario de Estado Parlamentario en el Ministerio Federal de Digitalizaci\u00f3n y Transporte), Prof. Dr. Walter Eichendorf (Presidente del Consejo de Seguridad Vial Alem\u00e1n, DVR), Andreas Rade (Director General de la Asociaci\u00f3n de la Industria Automotriz, VDA), Frank Huster (Director General de DSLV Asociaci\u00f3n Federal de Transporte y Log\u00edstica), y Thomas Fabian (Director de Veh\u00edculos Comerciales, ACEA \u2013 Asociaci\u00f3n Europea de Fabricantes de Autom\u00f3viles).<\/p>\n<h5><strong>Entrega del Premio Europeo de Seguridad Veh\u00edculos Comerciales<\/strong><\/h5>\n<p>En el Congreso Futuro tambi\u00e9n se llevar\u00e1 a cabo la entrega del Premio Europeo de Seguridad Veh\u00edculos Comerciales 2020 y 2021, que se hab\u00eda cancelado debido a la pandemia. Este premio es otorgado anualmente por DEKRA, DVR y la Asociaci\u00f3n Europea de Investigaci\u00f3n y An\u00e1lisis de Accidentes (EVU) a personalidades que, con sus logros profesionales, han contribuido de manera especial a la seguridad del veh\u00edculo comercial.<\/p>\n<p>M\u00e1s informaci\u00f3n y registro en: <a href=\"https:\/\/www.zukunftskongress-nutzfahrzeuge.de\" target=\"_blank\" rel=\"noopener\">www.zukunftskongress-nutzfahrzeuge.de<\/a><\/p>\n<p>Foto: \u00a9 DEKRA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En oto\u00f1o de 2021, el Congreso Futuro Veh\u00edculos Comerciales de DEKRA tuvo que ser cancelado debido a la pandemia. Ahora se planea una nueva edici\u00f3n para<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-55659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"En oto\u00f1o de 2021, el Congreso Futuro Veh\u00edculos Comerciales de DEKRA tuvo que ser cancelado debido a la pandemia. Ahora se planea una nueva edici\u00f3n para [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T10:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dekra_7.4.22-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1604\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn\",\"datePublished\":\"2022-04-07T10:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/\"},\"wordCount\":405,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dekra_7.4.22-1.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/\",\"name\":\"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dekra_7.4.22-1.jpg\",\"datePublished\":\"2022-04-07T10:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dekra_7.4.22-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dekra_7.4.22-1.jpg\",\"width\":1604,\"height\":765},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/04\\\/07\\\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/","og_locale":"es_ES","og_type":"article","og_title":"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn - Loginfo24","og_description":"En oto\u00f1o de 2021, el Congreso Futuro Veh\u00edculos Comerciales de DEKRA tuvo que ser cancelado debido a la pandemia. Ahora se planea una nueva edici\u00f3n para [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-04-07T10:36:30+00:00","og_image":[{"width":1604,"height":765,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dekra_7.4.22-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/"},"author":{"name":"","@id":""},"headline":"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn","datePublished":"2022-04-07T10:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/"},"wordCount":405,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dekra_7.4.22-1.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/","url":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/","name":"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dekra_7.4.22-1.jpg","datePublished":"2022-04-07T10:36:30+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dekra_7.4.22-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dekra_7.4.22-1.jpg","width":1604,"height":765},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/04\/07\/congreso-futuro-vehiculos-comerciales-de-dekra-a-principios-de-junio-en-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Congreso Futuro Veh\u00edculos Comerciales de DEKRA a principios de junio en Berl\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/55659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=55659"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/55659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10569"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=55659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=55659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=55659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}