{"id":55516,"date":"2022-03-31T19:39:25","date_gmt":"2022-03-31T17:39:25","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/"},"modified":"2022-03-31T19:39:25","modified_gmt":"2022-03-31T17:39:25","slug":"grieshaber-y-evonik-celebran-20-anos-de-colaboracion","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/","title":{"rendered":"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n"},"content":{"rendered":"<h5><strong>Desde hace 20 a\u00f1os, Grieshaber Logistics Group AG de Bad S\u00e4ckingen proporciona servicios log\u00edsticos para la l\u00ednea de negocio Silica en la ubicaci\u00f3n del grupo qu\u00edmico especializado Evonik en Rheinfelden. En febrero de 2002, se inici\u00f3 el nuevo concepto log\u00edstico con la asunci\u00f3n de las funciones de almac\u00e9n central y la gesti\u00f3n diaria (365 d\u00edas) de la producci\u00f3n desde la planta en Rheinfelden en dos turnos, as\u00ed como la gesti\u00f3n de env\u00edos a nivel mundial desde Hombourg\/Mulhouse.<\/strong><\/h5>\n<p>(Bad S\u00e4ckingen\/Rheinfelden\/DE) Adem\u00e1s de los servicios log\u00edsticos, que han crecido enormemente en los \u00faltimos a\u00f1os, tambi\u00e9n se han asumido continuamente nuevas tareas en estos 20 a\u00f1os. Entre otras cosas, el servicio se ampli\u00f3 en 2015 con la asunci\u00f3n de los servicios log\u00edsticos internos (365 d\u00edas \/ tres turnos) directamente en la planta de Rheinfelden. Desde la apertura del centro log\u00edstico, el n\u00famero de movimientos de palets ha alcanzado cifras millonarias.<\/p>\n<p>La base para una colaboraci\u00f3n tan a largo plazo y exitosa es la generaci\u00f3n continua de valor a\u00f1adido.<\/p>\n<h5>Puntos clave adem\u00e1s de la gesti\u00f3n operativa:<\/h5>\n<ul>\n<li>mejora en la utilizaci\u00f3n del espacio en la planta mediante la gesti\u00f3n continua de la producci\u00f3n (365 d\u00edas en dos turnos),<\/li>\n<li>optimizaci\u00f3n de costos con un aumento simult\u00e1neo de la flexibilidad y escalabilidad<\/li>\n<li>aumento de la puntualidad y fiabilidad de las entregas, al mismo tiempo que se reduce la tasa de reclamaciones y da\u00f1os, as\u00ed como<\/li>\n<li>aumento de la seguridad y transparencia de los procesos mediante un manejo sin documentos respaldado por un sistema y el uso integrado de un sistema de gesti\u00f3n de carretillas elevadoras.<\/li>\n<\/ul>\n<h5><strong>Los siguientes factores de \u00e9xito son esenciales:<\/strong><\/h5>\n<ul>\n<li>apertura y m\u00e1xima transparencia,<\/li>\n<li>confianza mutua, pero tambi\u00e9n evidencia de resultados (calidad y servicio)<\/li>\n<li>desarrollo continuo de los procesos, sistemas y del personal empleado de acuerdo con el lema: \u201c\u00a1Vivir el cambio activamente!\u201d<\/li>\n<\/ul>\n<p>Estos impresionantes movimientos de volumen y \u00e9xitos no habr\u00edan sido posibles sin el alto compromiso y la gran adaptabilidad de los empleados de Grieshaber y la colaboraci\u00f3n justa y en asociaci\u00f3n con el cliente.<\/p>\n<p>\u201cEstamos muy orgullosos de poder acompa\u00f1ar al fabricante de productos qu\u00edmicos especializados EVONIK, que opera a nivel mundial, con nuestro conocimiento log\u00edstico durante 20 a\u00f1os. Y esta asociaci\u00f3n sigue creciendo&#8230; \u00a1estamos emocionados por ello!\u201d dice Kurt Grieshaber, propietario y presidente del consejo de administraci\u00f3n de Grieshaber Logistics Group AG<\/p>\n<p>Foto: \u00a9 Grieshaber Logistics Group<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde hace 20 a\u00f1os, Grieshaber Logistics Group AG de Bad S\u00e4ckingen proporciona servicios log\u00edsticos para la l\u00ednea de negocio Silica en la ubicaci\u00f3n del grupo qu\u00edmico<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10621,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-55516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Desde hace 20 a\u00f1os, Grieshaber Logistics Group AG de Bad S\u00e4ckingen proporciona servicios log\u00edsticos para la l\u00ednea de negocio Silica en la ubicaci\u00f3n del grupo qu\u00edmico [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T17:39:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Grieshaber_31.3.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1221\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n\",\"datePublished\":\"2022-03-31T17:39:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/\"},\"wordCount\":437,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Grieshaber_31.3.22.jpg\",\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/\",\"name\":\"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Grieshaber_31.3.22.jpg\",\"datePublished\":\"2022-03-31T17:39:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Grieshaber_31.3.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Grieshaber_31.3.22.jpg\",\"width\":1221,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/03\\\/31\\\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/","og_locale":"es_ES","og_type":"article","og_title":"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n - Loginfo24","og_description":"Desde hace 20 a\u00f1os, Grieshaber Logistics Group AG de Bad S\u00e4ckingen proporciona servicios log\u00edsticos para la l\u00ednea de negocio Silica en la ubicaci\u00f3n del grupo qu\u00edmico [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-03-31T17:39:25+00:00","og_image":[{"width":1221,"height":715,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Grieshaber_31.3.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/"},"author":{"name":"","@id":""},"headline":"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n","datePublished":"2022-03-31T17:39:25+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/"},"wordCount":437,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Grieshaber_31.3.22.jpg","articleSection":["Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/","url":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/","name":"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Grieshaber_31.3.22.jpg","datePublished":"2022-03-31T17:39:25+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Grieshaber_31.3.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Grieshaber_31.3.22.jpg","width":1221,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/03\/31\/grieshaber-y-evonik-celebran-20-anos-de-colaboracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Grieshaber y Evonik celebran 20 a\u00f1os de colaboraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/55516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=55516"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/55516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/10621"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=55516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=55516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=55516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}