{"id":54463,"date":"2022-02-08T15:55:57","date_gmt":"2022-02-08T14:55:57","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/"},"modified":"2022-02-08T15:55:57","modified_gmt":"2022-02-08T14:55:57","slug":"dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/","title":{"rendered":"DHL compra 33 millones de litros de combustible sostenible para aviones"},"content":{"rendered":"<h5><strong>DHL Global Forwarding, el especialista en transporte a\u00e9reo y mar\u00edtimo del Deutsche Post DHL Group, ha firmado un acuerdo con Air France KLM Martinair Cargo (AFKLMP) para la compra de 33 millones de litros de combustible sostenible para aviones (SAF). La cooperaci\u00f3n est\u00e1 dise\u00f1ada para tres a\u00f1os y es una de las mayores compras de combustible sostenible para aviones en la industria de la log\u00edstica.<\/strong><\/h5>\n<p>(Bonn) DHL Global Forwarding se complace en la nueva colaboraci\u00f3n con AFKLMP, que ya ha demostrado ser un socio confiable a largo plazo y se encuentra entre los l\u00edderes del programa anual de certificaci\u00f3n de transportistas ecol\u00f3gicos del grupo. La iniciativa es parte del plan de sostenibilidad del Deutsche Post DHL Group, que prev\u00e9 inversiones de siete mil millones de euros en tecnolog\u00edas verdes hasta 2030 y tiene como objetivo reducir a cero todas las emisiones relacionadas con la log\u00edstica para 2050.<\/p>\n<p>\u00abCon nuestro plan de sostenibilidad, hemos establecido hitos desmantelados en nuestro camino hacia cero emisiones. Los combustibles sostenibles juegan un papel crucial en esto. Por lo tanto, nos comprometemos a cubrir al menos el 30 por ciento de la demanda de combustible en el transporte a\u00e9reo y mar\u00edtimo con combustibles sostenibles para 2030. La asociaci\u00f3n con AFKLMP contribuye a esto y es un buen ejemplo del uso exitoso de nuestro procedimiento &#8216;Book &amp; Claim&#8217;, que atribuye ahorros de CO<sub>2<\/sub> en el marco de las emisiones de alcance 3 a nuestros clientes. Es nuestra tarea conjunta acelerar la transici\u00f3n hacia un sector de transporte m\u00e1s amigable con el clima, y en \u00faltima instancia, clim\u00e1ticamente neutral. Solo tenemos este planeta\u00bb, dijo Tim Scharwath, CEO de DHL Global Forwarding, Freight.<\/p>\n<p>La colaboraci\u00f3n entre los dos expertos en log\u00edstica es otra prueba de su compromiso sostenible y muestra el papel crucial que desempe\u00f1a el SAF en la descarbonizaci\u00f3n de la industria del transporte a\u00e9reo. En el marco de la asociaci\u00f3n, DHL espera un ahorro de m\u00e1s de 80,000 toneladas de di\u00f3xido de carbono. En los vuelos de AFKLMP, se mezcla una proporci\u00f3n de combustibles sostenibles para aviones con el queroseno convencional. Cuanto mayor sea la proporci\u00f3n de SAF en la cantidad total de combustible, menores ser\u00e1n las emisiones de CO<sub>2<\/sub>. De esta manera, se puede ahorrar CO<sub>2<\/sub> donde realmente se emite. DHL transmite estas ventajas a los clientes y les ayuda as\u00ed a reducir su propia huella de carbono.<\/p>\n<p>\u00abLos equipos de Air France KLM Martinair Cargo est\u00e1n muy comprometidos y se sienten obligados a crear un futuro sostenible para nuestra industria. Esta cooperaci\u00f3n ofrece una gran oportunidad para acelerar nuestros esfuerzos conjuntos de sostenibilidad. El combustible sostenible para aviones (SAF) tiene un gran potencial para reducir las emisiones de CO<sub>2<\/sub>. Estamos emocionados de colaborar en los pr\u00f3ximos a\u00f1os con nuestro fuerte y duradero socio DHL Global Forwarding en el camino hacia una log\u00edstica y un sector de transporte m\u00e1s amigables con el clima. Cuando decimos que debemos actuar, es una subestimaci\u00f3n; debemos actuar r\u00e1pida y conjuntamente\u00bb, dijo Adriaan den Heijer, EVP Air France KLM Cargo y Director General de Martinair.<\/p>\n<h5>Sistema de reservas que rastrea reducciones de emisiones<\/h5>\n<p>La asociaci\u00f3n de DHL con AFKLMP se desarrollar\u00e1 de manera similar a colaboraciones anteriores; los clientes se beneficiar\u00e1n de la asociaci\u00f3n a trav\u00e9s del procedimiento &#8216;Book &amp; Claim&#8217;. Al reservar el servicio de transporte, pueden optar por una opci\u00f3n sostenible. Posteriormente, se les acreditar\u00e1 la correspondiente reducci\u00f3n de emisiones de alcance 3. Dado que es casi imposible rastrear f\u00edsicamente el combustible sostenible para aviones desde la producci\u00f3n hasta el avi\u00f3n, las ofertas &#8216;Book &amp; Claim&#8217; son una soluci\u00f3n a este problema log\u00edstico y t\u00e9cnico: el procedimiento es un sistema de contabilidad digital que rastrea las reducciones de emisiones gracias a los combustibles sostenibles a lo largo de las cadenas de valor y las asigna en consecuencia. Las empresas pueden poseer SAF a trav\u00e9s de compra y venta sin tener que demostrar f\u00edsicamente el combustible a lo largo de la cadena de suministro. Esto permite el acceso al mercado de SAF para empresas de todos los tama\u00f1os y en todas las ubicaciones.<\/p>\n<h5><strong>Compromiso de sostenibilidad<\/strong><\/h5>\n<p>Como parte de su plan de sostenibilidad y su misi\u00f3n 2050, el grupo Deutsche Post DHL Group ha decidido establecer objetivos basados en la ciencia y gastar\u00e1 hasta 2030 siete mil millones de euros en soluciones verdes y log\u00edstica ecol\u00f3gica. Como resultado, se espera que las emisiones del grupo se reduzcan a menos de 29 millones de toneladas. DHL quiere ser un pionero en la aviaci\u00f3n sostenible. Con este objetivo en mente, el grupo Deutsche Post DHL Group aumentar\u00e1 la proporci\u00f3n de combustibles sostenibles para aviones a m\u00e1s del 30 por ciento para 2030. El programa de evaluaci\u00f3n corporativa GoGreen para transportistas prefiere contratar a transportistas con un historial ecol\u00f3gico ejemplar. Air France KLM Martinair Cargo es uno de los transportistas m\u00e1s importantes de DHL Global Forwarding y, con calificaciones sobresalientes, se encuentra anualmente entre los tres mejores transportistas GoGreen.<\/p>\n<h5><strong>Compromiso de sostenibilidad de Air France KLM<\/strong><\/h5>\n<p>En octubre de 2021, el grupo Air France KLM se comprometi\u00f3 a que sus objetivos de reducci\u00f3n de emisiones de CO<sub>2<\/sub> sean evaluados por la organizaci\u00f3n de referencia independiente SBTi, para garantizar que est\u00e9n alineados con el Acuerdo de Par\u00eds sobre el clima. Air France KLM es uno de los primeros grupos de aviaci\u00f3n europeos en hacer evaluar su progreso en descarbonizaci\u00f3n por SBTi. Este nuevo paso importante en la estrategia de descarbonizaci\u00f3n complementa el objetivo del grupo de no generar emisiones netas para 2050.<\/p>\n<p>Entre los desarrollos de descarbonizaci\u00f3n del grupo Air France KLM se incluyen: un plan ambicioso para renovar su flota de aviones con una nueva generaci\u00f3n de aeronaves que emiten entre un 20 y un 25 por ciento menos de CO<sub>2<\/sub>. Entre 2019 y 2021, el grupo invirti\u00f3 2.5 mil millones de euros en la renovaci\u00f3n de su flota.<\/p>\n<p>Lograr ganancias de eficiencia operativa mediante la promoci\u00f3n de rutas directas adicionales y la aplicaci\u00f3n de procedimientos que limitan el consumo de combustible (aviones m\u00e1s ligeros, procedimientos de \u00abtaxi de un solo motor\u00bb, descenso constante). Air France y KLM se han propuesto ser neutrales en carbono en sus operaciones en tierra para 2030.<\/p>\n<p>Adem\u00e1s, Air France KLM se compromete en toda la industria y se involucra en el desarrollo de soluciones innovadoras en el dise\u00f1o y mantenimiento de aviones, motores y combustibles sint\u00e9ticos, que conducir\u00e1n gradualmente a una aviaci\u00f3n completamente libre de CO<sub>2<\/sub>.<\/p>\n<p>Foto: \u00a9 DHL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DHL Global Forwarding, el especialista en transporte a\u00e9reo y mar\u00edtimo del Deutsche Post DHL Group, ha firmado un acuerdo con Air France KLM Martinair Cargo (AFKLMP)<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1665,1557,1561],"tags":[],"class_list":["post-54463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHL compra 33 millones de litros de combustible sostenible para aviones - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHL compra 33 millones de litros de combustible sostenible para aviones - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"DHL Global Forwarding, el especialista en transporte a\u00e9reo y mar\u00edtimo del Deutsche Post DHL Group, ha firmado un acuerdo con Air France KLM Martinair Cargo (AFKLMP) [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-08T14:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_8.2.22_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1585\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DHL compra 33 millones de litros de combustible sostenible para aviones\",\"datePublished\":\"2022-02-08T14:55:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/\"},\"wordCount\":1129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_8.2.22_2.jpg\",\"articleSection\":[\"Air Freight\",\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/\",\"name\":\"DHL compra 33 millones de litros de combustible sostenible para aviones - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_8.2.22_2.jpg\",\"datePublished\":\"2022-02-08T14:55:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_8.2.22_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_8.2.22_2.jpg\",\"width\":1585,\"height\":887},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/02\\\/08\\\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHL compra 33 millones de litros de combustible sostenible para aviones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHL compra 33 millones de litros de combustible sostenible para aviones - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/","og_locale":"es_ES","og_type":"article","og_title":"DHL compra 33 millones de litros de combustible sostenible para aviones - Loginfo24","og_description":"DHL Global Forwarding, el especialista en transporte a\u00e9reo y mar\u00edtimo del Deutsche Post DHL Group, ha firmado un acuerdo con Air France KLM Martinair Cargo (AFKLMP) [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-02-08T14:55:57+00:00","og_image":[{"width":1585,"height":887,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_8.2.22_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/"},"author":{"name":"","@id":""},"headline":"DHL compra 33 millones de litros de combustible sostenible para aviones","datePublished":"2022-02-08T14:55:57+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/"},"wordCount":1129,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_8.2.22_2.jpg","articleSection":["Air Freight","Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/","url":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/","name":"DHL compra 33 millones de litros de combustible sostenible para aviones - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_8.2.22_2.jpg","datePublished":"2022-02-08T14:55:57+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_8.2.22_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_8.2.22_2.jpg","width":1585,"height":887},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/02\/08\/dhl-compra-33-millones-de-litros-de-combustible-sostenible-para-aviones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"DHL compra 33 millones de litros de combustible sostenible para aviones"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/54463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=54463"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/54463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/11054"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=54463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=54463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=54463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}