{"id":53888,"date":"2021-12-01T16:20:46","date_gmt":"2021-12-01T15:20:46","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/"},"modified":"2021-12-01T16:20:46","modified_gmt":"2021-12-01T15:20:46","slug":"la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/","title":{"rendered":"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente"},"content":{"rendered":"<h5><strong>En mayo de este a\u00f1o, la Asociaci\u00f3n de Empresas de Transporte Alemanas y doce de las aproximadamente 150 empresas de carga organizadas en el VDV fundaron la \u00abRed Futuro del Transporte de Carga por V\u00eda\u00bb. El objetivo de esta uni\u00f3n es fortalecer el transporte de carga individual en el transporte ferroviario de mercanc\u00edas, contribuyendo as\u00ed a aumentar la cuota de mercado de las empresas de carga en general. Hasta ahora, la alianza cuenta con 29 empresas de carga, y otras han expresado su inter\u00e9s. Los primeros transportes conjuntos se est\u00e1n llevando a cabo con \u00e9xito.<\/strong><\/h5>\n<p>(Berl\u00edn\/Mainz) \u00abSi queremos trasladar significativamente m\u00e1s mercanc\u00edas a la v\u00eda para alcanzar los objetivos de protecci\u00f3n clim\u00e1tica en el sector del transporte para 2030, solo podemos hacerlo juntos y en colaboraci\u00f3n con la mayor cantidad posible de actores\u00bb, explica Joachim Berends, vicepresidente del VDV y miembro de la junta de la Bentheimer Eisenbahn. \u00abPor eso, esta red llega en el momento adecuado y el gran inter\u00e9s de las empresas demuestra que hemos dado el impulso correcto a la industria con el pensamiento cooperativo.\u00bb<\/p>\n<p>Dr. Sigrid Nikutta, presidenta de DB Cargo: \u00ab\u00a1Llevamos la protecci\u00f3n clim\u00e1tica a la superficie! Si transportamos mercanc\u00edas a lo largo de toda su cadena de suministro completamente por ferrocarril, eso es la m\u00e1xima protecci\u00f3n clim\u00e1tica, y por eso es bueno que el transporte de carga individual est\u00e9 expl\u00edcitamente en el foco del contrato de coalici\u00f3n del nuevo gobierno federal. Si estamos trabajando juntos como industria, eso beneficia principalmente a nuestros clientes. Porque con nuestra alianza podemos satisfacer realmente cada necesidad del cliente en cualquier lugar de este pa\u00eds. Y podemos dejar claro juntos ante la pol\u00edtica y los municipios locales qu\u00e9 decisiones deben tomarse ahora para el importante transporte de carga individual. Las mercanc\u00edas deben ir por la v\u00eda. No por el paso del pueblo o el carril derecho de la autopista.\u00bb<\/p>\n<p>Berends, Nikutta y otros socios est\u00e1n especialmente complacidos con los primeros tres proyectos concretos que ya se han puesto en marcha en el marco de la Red Futuro del Transporte de Carga Individual:<\/p>\n<p>La Kreisbahn Siegen-Wittgenstein y DB Cargo est\u00e1n trabajando en estrecha colaboraci\u00f3n en el transporte intermodal de bebidas para Trinks GmbH. Trinks GmbH, uno de los principales distribuidores de bebidas de Alemania, transporta productos de Krombacher en tren desde Kreuztal a Berl\u00edn. Una vez a la semana, dos vagones con cuatro contenedores salen de la terminal de contenedores de S\u00fcdwestfalen de la Kreisbahn Siegen-Wittgenstein (KSW) con destino a Gro\u00dfbeeren, en el sur de la capital alemana. \u00abEste transporte de carga individual solo fue posible gracias a una intensa colaboraci\u00f3n entre la KSW, DB Cargo, el cliente Trinks y la cervecer\u00eda Krombacher\u00bb, dice Christian Betchen, director general de la Kreisbahn.<\/p>\n<h5>Abastecimiento de Grafschaft Bentheim<\/h5>\n<p>Otro ejemplo de \u00e9xito es el abastecimiento de la industria del acero en la regi\u00f3n de Grafschaft Bentheim, Emsland y Osnabr\u00fcck con productos de U.S. Steel a trav\u00e9s de DB Cargo y Bentheimer Eisenbahn. A trav\u00e9s del Railport en Nordhorn, los clientes de la regi\u00f3n son abastecidos \u00abjusto a tiempo\u00bb. En este caso, el almac\u00e9n de transbordo de los ferrocarriles sirve como almac\u00e9n de consignaci\u00f3n, una ventaja para el proveedor y los clientes.<\/p>\n<p>Una cooperaci\u00f3n de maniobras en la \u00ab\u00faltima milla\u00bb ha sido iniciada por la Regionalverkehr Ruhr-Lippe GmbH (RLG) y DB Cargo. La empresa Stahlform Schulte opera un almac\u00e9n de acero en Arnsberg a lo largo de la l\u00ednea de la RLG. En colaboraci\u00f3n con el Steel Logistic Center Hagen de DB Cargo AG, ciertas cantidades de acero se transportan al almac\u00e9n en Arnsberg, que est\u00e1 ubicado fuera del sitio de acero de Hagen. La colaboraci\u00f3n de los ferrocarriles involucrados, incluyendo un nivel de respaldo seguro, proporciona al cliente una mayor seguridad en la planificaci\u00f3n y el suministro. Las capacidades de maniobra ya son escasas en muchas regiones hoy en d\u00eda. Las optimizaciones a trav\u00e9s de cooperaciones de maniobras, especialmente en \u00e1reas cercanas, pueden aumentar las capacidades. Se requieren socios fuertes y flexibles en el lugar para acompa\u00f1ar con \u00e9xito la transformaci\u00f3n del transporte\u00bb, explica Detlef Berndt, jefe de la divisi\u00f3n ferroviaria en la RLG.<\/p>\n<h5>Colaboraci\u00f3n tambi\u00e9n en tres subgrupos de trabajo<\/h5>\n<p>Adem\u00e1s de los transportes conjuntos que ya se han implementado, los socios de la red tambi\u00e9n colaboran estrechamente en cuestiones institucionales y organizativas. En los tres subgrupos de trabajo \u00abOperaci\u00f3n\u00bb, \u00abVentas\u00bb y \u00abEstrategia\u00bb, los expertos de las empresas de carga representadas en la red intercambian regularmente y llevan a cabo proyectos conjuntos. Tambi\u00e9n aqu\u00ed hay resultados positivos iniciales que anunciar, de los cuales todos los socios de la red se benefician, como el desarrollo de un logotipo de producto com\u00fan para el transporte de carga individual, una soluci\u00f3n de respaldo com\u00fan en caso de interrupciones operativas o la digitalizaci\u00f3n de la colaboraci\u00f3n operativa.<\/p>\n<p>Foto: \u00a9 DB Cargo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mayo de este a\u00f1o, la Asociaci\u00f3n de Empresas de Transporte Alemanas y doce de las aproximadamente 150 empresas de carga organizadas en el VDV fundaron<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-53888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"En mayo de este a\u00f1o, la Asociaci\u00f3n de Empresas de Transporte Alemanas y doce de las aproximadamente 150 empresas de carga organizadas en el VDV fundaron [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T15:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Cargo_1.12.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1231\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente\",\"datePublished\":\"2021-12-01T15:20:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/\"},\"wordCount\":871,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Cargo_1.12.21.jpg\",\"articleSection\":[\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/\",\"name\":\"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Cargo_1.12.21.jpg\",\"datePublished\":\"2021-12-01T15:20:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Cargo_1.12.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Cargo_1.12.21.jpg\",\"width\":1231,\"height\":626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/12\\\/01\\\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/","og_locale":"es_ES","og_type":"article","og_title":"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente - Loginfo24","og_description":"En mayo de este a\u00f1o, la Asociaci\u00f3n de Empresas de Transporte Alemanas y doce de las aproximadamente 150 empresas de carga organizadas en el VDV fundaron [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-12-01T15:20:46+00:00","og_image":[{"width":1231,"height":626,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Cargo_1.12.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/"},"author":{"name":"","@id":""},"headline":"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente","datePublished":"2021-12-01T15:20:46+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/"},"wordCount":871,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Cargo_1.12.21.jpg","articleSection":["Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/","url":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/","name":"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Cargo_1.12.21.jpg","datePublished":"2021-12-01T15:20:46+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Cargo_1.12.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Cargo_1.12.21.jpg","width":1231,"height":626},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/12\/01\/la-red-futuro-del-transporte-de-carga-por-via-crece-constantemente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"La red Futuro del Transporte de Carga por V\u00eda Crece Constantemente"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/53888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=53888"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/53888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/11600"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=53888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=53888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=53888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}