{"id":53159,"date":"2021-11-02T16:54:13","date_gmt":"2021-11-02T15:54:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/"},"modified":"2021-11-02T16:54:13","modified_gmt":"2021-11-02T15:54:13","slug":"customs-support-adquiere-balimpex-en-suiza","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/","title":{"rendered":"Customs Support adquiere Balimpex en Suiza"},"content":{"rendered":"<h5><strong>Customs Support, el socio neutral para asuntos aduaneros en Europa, anuncia la adquisici\u00f3n de Balimpex. Esta adquisici\u00f3n permite una expansi\u00f3n en Suiza y es un paso m\u00e1s hacia convertirse en el principal socio de servicios aduaneros para clientes en toda Europa. Balimpex est\u00e1 presente en todos los principales puntos de cruce de fronteras suizos.<\/strong><\/h5>\n<p>(R\u00f3terdam\/Muttenz) Fundada en 1981, Balimpex tiene una amplia experiencia y una excelente reputaci\u00f3n en el sector de servicios aduaneros y servicios log\u00edsticos complementarios. Con aproximadamente 70 empleados en 10 ubicaciones, Balimpex atiende a sus clientes en todos los puntos estrat\u00e9gicos de cruce de fronteras entre Suiza y Alemania, desde Basilea hasta el Lago de Constanza, y en el cruce de frontera franc\u00e9s en Saint-Louis \/ Basilea. Un servicio r\u00e1pido, confiable y adaptado a las necesidades del cliente ha permitido a Balimpex construir relaciones s\u00f3lidas y duraderas con clientes y autoridades, convirtiendo a Balimpex en un excelente complemento para Customs Support.<\/p>\n<p>\u00abEstamos convencidos de que hemos encontrado en Customs Support un nuevo hogar \u00f3ptimo para nuestra empresa. Nuestras visiones se alinean y la incorporaci\u00f3n a la plataforma de Customs Support aumentar\u00e1 significativamente la capacidad de Balimpex y de los clientes de Customs Support. Estamos emocionados por la colaboraci\u00f3n,\u00bb dice Bertram Beck, director general de Balimpex.<\/p>\n<h5><strong>Expansi\u00f3n de la presencia geogr\u00e1fica en Europa<\/strong><\/h5>\n<p>\u00abDesde el principio hemos tenido una excelente impresi\u00f3n de Balimpex y ahora estamos felices de dar la bienvenida al equipo en la familia de Customs Support. Vemos esta adquisici\u00f3n como un paso importante en la expansi\u00f3n de nuestra presencia geogr\u00e1fica en Europa y creemos que ambas empresas y sus clientes se beneficiar\u00e1n enormemente de esta combinaci\u00f3n,\u00bb se alegra Frank Weermeijer, director general de Customs Support Group.<\/p>\n<h5><strong>Sobre Customs Support Group<\/strong><\/h5>\n<p>Customs Support Group, con sede en los Pa\u00edses Bajos, es el principal proveedor de servicios aduaneros digitales y neutrales en Europa, con m\u00e1s de 1,000 expertos en aduanas que atienden anualmente a m\u00e1s de 10,000 clientes. A trav\u00e9s de nuestra amplia gama de servicios y nuestra capacidad digital, apoyamos a nuestros clientes de manera consistente para garantizar el cumplimiento de la normativa, lograr eficiencias operativas, optimizar los aranceles de importaci\u00f3n, as\u00ed como en su planificaci\u00f3n aduanera y desarrollo en un paisaje aduanero en constante cambio.<\/p>\n<p>Adem\u00e1s de los servicios tradicionales de despacho y servicios digitales, Customs Support Group ofrece consultor\u00eda aduanera y servicios de medici\u00f3n de gases. La empresa actualmente opera en los Pa\u00edses Bajos, B\u00e9lgica, Alemania, Francia, Reino Unido, Polonia, Italia y Suiza.<\/p>\n<p>Foto: \u00a9 Customs Support<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Customs Support, el socio neutral para asuntos aduaneros en Europa, anuncia la adquisici\u00f3n de Balimpex. Esta adquisici\u00f3n permite una expansi\u00f3n en Suiza y es un paso<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-53159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Customs Support adquiere Balimpex en Suiza - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Customs Support adquiere Balimpex en Suiza - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Customs Support, el socio neutral para asuntos aduaneros en Europa, anuncia la adquisici\u00f3n de Balimpex. Esta adquisici\u00f3n permite una expansi\u00f3n en Suiza y es un paso [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T15:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Customs_Support_2.11.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1268\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Customs Support adquiere Balimpex en Suiza\",\"datePublished\":\"2021-11-02T15:54:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Customs_Support_2.11.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/\",\"name\":\"Customs Support adquiere Balimpex en Suiza - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Customs_Support_2.11.21.jpg\",\"datePublished\":\"2021-11-02T15:54:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Customs_Support_2.11.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Customs_Support_2.11.21.jpg\",\"width\":1268,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/11\\\/02\\\/customs-support-adquiere-balimpex-en-suiza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customs Support adquiere Balimpex en Suiza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Customs Support adquiere Balimpex en Suiza - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/","og_locale":"es_ES","og_type":"article","og_title":"Customs Support adquiere Balimpex en Suiza - Loginfo24","og_description":"Customs Support, el socio neutral para asuntos aduaneros en Europa, anuncia la adquisici\u00f3n de Balimpex. Esta adquisici\u00f3n permite una expansi\u00f3n en Suiza y es un paso [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-11-02T15:54:13+00:00","og_image":[{"width":1268,"height":711,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Customs_Support_2.11.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/"},"author":{"name":"","@id":""},"headline":"Customs Support adquiere Balimpex en Suiza","datePublished":"2021-11-02T15:54:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Customs_Support_2.11.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/","url":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/","name":"Customs Support adquiere Balimpex en Suiza - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Customs_Support_2.11.21.jpg","datePublished":"2021-11-02T15:54:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Customs_Support_2.11.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Customs_Support_2.11.21.jpg","width":1268,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/11\/02\/customs-support-adquiere-balimpex-en-suiza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Customs Support adquiere Balimpex en Suiza"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/53159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=53159"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/53159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/11906"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=53159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=53159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=53159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}