{"id":52602,"date":"2021-10-11T16:35:34","date_gmt":"2021-10-11T14:35:34","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/"},"modified":"2021-10-11T16:35:34","modified_gmt":"2021-10-11T14:35:34","slug":"inmuebles-industriales-y-logisticos-en-niveles-record","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/","title":{"rendered":"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord"},"content":{"rendered":"<h5><strong>Seg\u00fan el asesor inmobiliario Colliers, el volumen de inversi\u00f3n en inmuebles industriales y log\u00edsticos en los primeros nueve meses de 2021 muestra un resultado r\u00e9cord, con aproximadamente 5,9 mil millones de euros en volumen de inversi\u00f3n. La log\u00edstica contribuye con una participaci\u00f3n de mercado de dos d\u00edgitos (15 por ciento).<\/strong><strong> Debido a la alta demanda, el rendimiento bruto sigue cayendo al 3,4 por ciento.<\/strong><\/h5>\n<p>(Fr\u00e1ncfort\/Main) En los primeros nueve meses se invirti\u00f3 una suma r\u00e9cord de 5,9 mil millones de euros en inmuebles industriales y log\u00edsticos alemanes. Seg\u00fan Colliers, este es el segundo mejor resultado jam\u00e1s registrado al final de un tercer trimestre, despu\u00e9s de 2017. En comparaci\u00f3n con el a\u00f1o anterior, el resultado fue aproximadamente un 19 por ciento superior al valor de referencia y en el promedio de cuatro a\u00f1os se gener\u00f3 un aumento del 18 por ciento.<\/p>\n<p>Nicolas Roy, director de Industrial &amp; Logistics Germany en Colliers: \u00abEl desarrollo del mercado en los primeros nueve meses del a\u00f1o estuvo fuertemente influenciado por la demanda de empresas de comercio electr\u00f3nico. El cambio en el comportamiento de compra, provocado por la pandemia, permiti\u00f3 a muchos proveedores de alimentos en l\u00ednea y servicios de entrega de alimentos ingresar al mercado. Los nuevos participantes del mercado hacen que el mercado de inmuebles log\u00edsticos sea m\u00e1s atractivo para muchos inversores. Como resultado, la clase de activos log\u00edstica logr\u00f3 una notable participaci\u00f3n de mercado del 15 por ciento y actualmente se encuentra entre las clases de activos m\u00e1s interesantes.\u00bb<\/p>\n<h5><strong>Los inversores europeos muestran una actividad especialmente alta<\/strong><\/h5>\n<p>Debido a la pandemia en curso y las restricciones de viaje, alrededor del 56 por ciento del capital proviene de inversores nacionales. Esto corresponde al resultado de la primera mitad del a\u00f1o y muestra que el inter\u00e9s de los inversores nacionales sigue siendo muy alto. En el tercer trimestre, Patrizia se destac\u00f3 como especialmente activa y adquiri\u00f3 una cartera compuesta por cinco inmuebles de DHL. Adem\u00e1s, Catella pudo adquirir con \u00e9xito cuatro inmuebles log\u00edsticos para sus fondos especializados.<\/p>\n<p>Con aproximadamente el 44 por ciento del volumen total de transacciones, la participaci\u00f3n del capital internacional sigue siendo estable. En comparaci\u00f3n con el nivel anterior a la pandemia, el valor est\u00e1 aproximadamente 14 puntos porcentuales por debajo del resultado de 2019 (58 por ciento). Es notable que alrededor de dos tercios del capital internacional proviene de inversores europeos. Entre los inversores europeos, los inversores brit\u00e1nicos adquirieron un n\u00famero r\u00e9cord de casi 40 inmuebles log\u00edsticos en Alemania. Aproximadamente dos tercios de los fondos brit\u00e1nicos fluyeron hacia inmuebles log\u00edsticos fuera de los siete principales centros de inversi\u00f3n.<\/p>\n<h5><strong>La participaci\u00f3n de compras individuales alcanza niveles r\u00e9cord<\/strong><\/h5>\n<p>En comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior, la participaci\u00f3n de compras de cartera se mantuvo en un nivel estable de alrededor del 31 por ciento. En los meses de abril a junio, se llevaron a cabo la mayor\u00eda de las transacciones de cartera con siete ventas de paquetes. En el tercer trimestre, solo se negociaron tres grandes carteras. Entre otras cosas, Swiss Life Asset Managers compr\u00f3 diez inmuebles log\u00edsticos europeos, de los cuales seis est\u00e1n en Alemania, por un monto de seis cifras en millones. Los inmuebles formaban parte de la cartera de Coldplay de 2019. Adem\u00e1s, Europa Capital vendi\u00f3 ocho inmuebles log\u00edsticos, incluidos inmuebles que hab\u00edan comprado hace solo un a\u00f1o, a la empresa australiana Arrow Capital Partners. En comparaci\u00f3n a largo plazo, la participaci\u00f3n de las ventas de cartera con 7 puntos porcentuales se mantiene significativamente por debajo del nivel anterior a la pandemia de 2019.<\/p>\n<p>Entre las transacciones individuales m\u00e1s significativas en el tercer trimestre se encontraba la compra de un inmueble log\u00edstico en Gro\u00dfbeeren, cerca de Berl\u00edn. Fue el mayor acuerdo de activos individuales del a\u00f1o en el sector log\u00edstico en Berl\u00edn y tambi\u00e9n a nivel nacional. En total, aproximadamente dos tercios de todas las transacciones individuales en el tercer trimestre fueron realizadas por inversores nacionales, mientras que las carteras fueron mayormente vendidas a inversores extranjeros.<\/p>\n<h5><strong>La competencia de precios se intensifica<\/strong><\/h5>\n<p>Debido a la alta demanda y a la oferta restringida, la situaci\u00f3n en el mercado se est\u00e1 intensificando. El nivel de rendimiento para inmuebles log\u00edsticos core en las mejores ubicaciones con inquilinos de alta solvencia ha ca\u00eddo a\u00fan m\u00e1s al 3,4 por ciento en el tercer trimestre. Esto representa una disminuci\u00f3n de 50 puntos b\u00e1sicos en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior. \u00abParticularmente desde la segunda mitad de 2020, los rendimientos han estado en ca\u00edda libre. Desde el cuarto trimestre de 2020, hemos observado que, en promedio, los rendimientos disminuyen en aproximadamente 50 puntos b\u00e1sicos de un trimestre a otro. A mediados de a\u00f1o, se realizaron las primeras transacciones con un factor de precio de compra de aproximadamente 30 veces y esperamos m\u00e1s transacciones igualmente costosas en el \u00faltimo trimestre\u00bb, explica Roy.<\/p>\n<h5><strong>Perspectivas<\/strong><\/h5>\n<p>\u00abLa situaci\u00f3n actual del mercado promete algunas transacciones atractivas en el cuarto trimestre. Esperamos que el resultado anual supere el volumen de transacciones r\u00e9cord del a\u00f1o anterior. El aumento de los precios de construcci\u00f3n seguir\u00e1 elevando los precios de compra para desarrollos de proyectos. La situaci\u00f3n econ\u00f3mica general y las restricciones de viaje relacionadas con la pandemia se estabilizar\u00e1n cada vez m\u00e1s a medida que avance el a\u00f1o. Como resultado, esperamos m\u00e1s compradores internacionales que aumentar\u00e1n a\u00fan m\u00e1s la competencia de precios\u00bb, concluye Roy.<\/p>\n<p>Foto: \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el asesor inmobiliario Colliers, el volumen de inversi\u00f3n en inmuebles industriales y log\u00edsticos en los primeros nueve meses de 2021 muestra un resultado r\u00e9cord, con<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-52602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan el asesor inmobiliario Colliers, el volumen de inversi\u00f3n en inmuebles industriales y log\u00edsticos en los primeros nueve meses de 2021 muestra un resultado r\u00e9cord, con [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-11T14:35:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Colliers_11.10.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1345\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord\",\"datePublished\":\"2021-10-11T14:35:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/\"},\"wordCount\":957,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Colliers_11.10.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/\",\"name\":\"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Colliers_11.10.21.jpg\",\"datePublished\":\"2021-10-11T14:35:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Colliers_11.10.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Colliers_11.10.21.jpg\",\"width\":1345,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/10\\\/11\\\/inmuebles-industriales-y-logisticos-en-niveles-record\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/","og_locale":"es_ES","og_type":"article","og_title":"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord - Loginfo24","og_description":"Seg\u00fan el asesor inmobiliario Colliers, el volumen de inversi\u00f3n en inmuebles industriales y log\u00edsticos en los primeros nueve meses de 2021 muestra un resultado r\u00e9cord, con [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-11T14:35:34+00:00","og_image":[{"width":1345,"height":749,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Colliers_11.10.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/"},"author":{"name":"","@id":""},"headline":"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord","datePublished":"2021-10-11T14:35:34+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/"},"wordCount":957,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Colliers_11.10.21.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/","url":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/","name":"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Colliers_11.10.21.jpg","datePublished":"2021-10-11T14:35:34+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Colliers_11.10.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Colliers_11.10.21.jpg","width":1345,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/10\/11\/inmuebles-industriales-y-logisticos-en-niveles-record\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Inmuebles industriales y log\u00edsticos en niveles r\u00e9cord"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=52602"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/12139"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=52602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=52602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=52602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}