{"id":52156,"date":"2021-09-22T11:40:22","date_gmt":"2021-09-22T09:40:22","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/"},"modified":"2021-09-22T11:40:22","modified_gmt":"2021-09-22T09:40:22","slug":"modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/","title":{"rendered":"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl"},"content":{"rendered":"<h5><strong>La construcci\u00f3n de un nuevo edificio de producci\u00f3n y log\u00edstica ha sido oficialmente entregada a los responsables de B\u00fcrstner. Esto va acompa\u00f1ado de la implementaci\u00f3n de una nueva estructura organizativa, un concepto log\u00edstico de \u00faltima generaci\u00f3n y una mayor estandarizaci\u00f3n. El objetivo es una mayor productividad y un aumento simult\u00e1neo de las capacidades de producci\u00f3n.<\/strong><\/h5>\n<p>(Kehl) Una de las mayores inversiones individuales en tiempos recientes fue solemnemente entregada a la direcci\u00f3n de la planta en el puerto de Kehl. El n\u00facleo es el nuevo edificio de producci\u00f3n y log\u00edstica, donde se fabrican autocaravanas peque\u00f1as y medianas.<\/p>\n<p>La nueva l\u00ednea de montaje est\u00e1 ubicada en una combinaci\u00f3n de un nuevo edificio y edificios existentes renovados. En ellos se han consolidado dos l\u00edneas de producci\u00f3n. La prefabricaci\u00f3n ahora se realiza directamente antes de la entrada de la l\u00ednea. Esto significa caminos cortos en la producci\u00f3n. Adem\u00e1s, se ha implementado un nuevo concepto log\u00edstico: el suministro de las l\u00edneas se realiza Just-in-Sequence, es decir, seg\u00fan el tama\u00f1o del lote de una serie. Esto ahorra espacio, caminos y tiempo.<\/p>\n<h5><strong>Alta demanda hizo necesaria la expansi\u00f3n<\/strong><\/h5>\n<p>\u00abDesde el 30 de agosto, la curva de arranque de la l\u00ednea de montaje est\u00e1 en marcha. A los empleados se les explican paso a paso las nuevas tareas y contenidos de trabajo\u00bb, dice Iskender Coskun, director de la planta en B\u00fcrstner. La modernizaci\u00f3n y expansi\u00f3n de la producci\u00f3n era necesaria para poder atender la alta demanda de autocaravanas y campers de B\u00fcrstner tambi\u00e9n en el futuro.\u00bb<\/p>\n<p>Para ello, ya est\u00e1n programados los pr\u00f3ximos pasos: En enero de 2022, la propia costura de la empresa ser\u00e1 reestructurada y ubicada m\u00e1s cerca de la l\u00ednea de montaje. Hasta abril de 2022, se construir\u00e1 un nuevo taller de carpinter\u00eda en la ubicaci\u00f3n de Kehl y tambi\u00e9n se integrar\u00e1 en el flujo de producci\u00f3n. Esto garantizar\u00e1 una alta calidad de muebles y una producci\u00f3n flexible. Paralelamente, tambi\u00e9n se aumentar\u00e1n las capacidades para campers compactos en la planta de B\u00fcrstner en Wissembourg, Francia.<\/p>\n<p>Foto: \u00a9 B\u00fcrstner \/ <strong><em>Pie de foto:<\/em><\/strong> <em>(1. fila con tijeras de izquierda a derecha): Direcci\u00f3n: Alexander Kasteleiner, Olaf Sackers, Jens Kromer (portavoz),<\/em><em><br \/>\n(2. fila de izquierda a derecha): Iskender Coskun (director de operaciones) y el equipo del proyecto: Daniel Rosa, Tobias Stoffer, Christian Rest, Armin B\u00e4hr, Selina Schrempp<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La construcci\u00f3n de un nuevo edificio de producci\u00f3n y log\u00edstica ha sido oficialmente entregada a los responsables de B\u00fcrstner. Esto va acompa\u00f1ado de la implementaci\u00f3n de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-52156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La construcci\u00f3n de un nuevo edificio de producci\u00f3n y log\u00edstica ha sido oficialmente entregada a los responsables de B\u00fcrstner. Esto va acompa\u00f1ado de la implementaci\u00f3n de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T09:40:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Buerstner_22.9.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1221\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl\",\"datePublished\":\"2021-09-22T09:40:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/\"},\"wordCount\":437,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Buerstner_22.9.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/\",\"name\":\"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Buerstner_22.9.21.jpg\",\"datePublished\":\"2021-09-22T09:40:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Buerstner_22.9.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Buerstner_22.9.21.jpg\",\"width\":1221,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/22\\\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/","og_locale":"es_ES","og_type":"article","og_title":"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl - Loginfo24","og_description":"La construcci\u00f3n de un nuevo edificio de producci\u00f3n y log\u00edstica ha sido oficialmente entregada a los responsables de B\u00fcrstner. Esto va acompa\u00f1ado de la implementaci\u00f3n de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-22T09:40:22+00:00","og_image":[{"width":1221,"height":709,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Buerstner_22.9.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/"},"author":{"name":"","@id":""},"headline":"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl","datePublished":"2021-09-22T09:40:22+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/"},"wordCount":437,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Buerstner_22.9.21.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/","url":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/","name":"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Buerstner_22.9.21.jpg","datePublished":"2021-09-22T09:40:22+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Buerstner_22.9.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Buerstner_22.9.21.jpg","width":1221,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/22\/modernizacion-de-la-logistica-y-produccion-en-burstner-en-kehl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Modernizaci\u00f3n de la log\u00edstica y producci\u00f3n en B\u00fcrstner en Kehl"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=52156"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/12312"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=52156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=52156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=52156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}